{"id":187376,"date":"2026-05-29T15:18:30","date_gmt":"2026-05-29T15:18:30","guid":{"rendered":"https:\/\/sinch.com\/voice\/features\/encaminhamento-de-chamadas\/"},"modified":"2026-06-30T13:04:42","modified_gmt":"2026-06-30T13:04:42","slug":"encaminhamento-de-chamadas","status":"publish","type":"voice_features","link":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/","title":{"rendered":"Encaminhamento de chamadas"},"content":{"rendered":"\r\n    <section data-content-type=\"component\" class=\"header-block section-py bg-sand\" data-theme=\"light\">\r\n        <div class=\"container header-block-container\">\r\n\r\n            \r\n            <div class=\"row align-items-center\">\r\n                <div class=\"col-12 order-2 col-md-6 col-lg-5 order-md-1\">\r\n                    <div class=\"d-flex flex-column gap-3 gap-md-4\">\r\n                        <div>\r\n                                                            <p class=\"text-uppercase section-caption text-body-color\">ENCAMINHAR CHAMADAS GLOBALMENTE\u00a0<\/p>\r\n                            \r\n                            \r\n                            <h1 class=\"text-accent m-0 p-0 h1\">\r\n                                Encaminhamento de chamadas simples e escal\u00e1vel\u00a0                            <\/h1>\r\n                        <\/div>\r\n\r\n                                                    <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Com a Sinch, voc\u00ea pode redirecionar automaticamente as chamadas para o n\u00famero ou dispositivo certo em qualquer lugar do mundo. A configura\u00e7\u00e3o leva alguns minutos com as nossas ferramentas f\u00e1ceis de autoatendimento ou a <a href=\"https:\/\/sinch.com\/pt\/voz\/voz-programavel\/voice-api\/\">Voice API da Sinch<\/a>, para que a sua empresa continue funcionando sem quedas nas chamadas.\u00a0 <\/p><\/div>\r\n                        \r\n                        \r\n                        \r\n                                                    <div class=\"btn-group g-3 mt-0 row\">\r\n                                \r\n        <div class=\"col-auto\">\r\n        <a href=\"#form\"  class=\"btn btn-secondary btn-lg btn-animated scrollme\" >Fale com um especialista<\/a>\r\n        <\/div>\r\n                                    <\/div>\r\n\r\n                                                                        <\/div>\r\n                <\/div>\r\n\r\n                                    <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 order-md-2 ps-md-7 ps-lg-10 text-md-end\">\r\n\r\n                        \r\n                            <img decoding=\"async\" width=\"648\" height=\"445\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Diagram-Call-Flow.png\" class=\"skip-lazy img-fluid\" alt=\"Image for Encaminhamento de chamadas simples e escal\u00e1vel\u00a0\" fetchpriority=\"high\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Diagram-Call-Flow.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Diagram-Call-Flow-300x206.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Diagram-Call-Flow-1024x704.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Diagram-Call-Flow-768x528.png 768w\" \/>\r\n                        \r\n                        \r\n                    <\/div>\r\n                \r\n            <\/div>\r\n        <\/div>\r\n\r\n                    <div class=\"block-clients pt-6 pt-md-7 pt-lg-9\">\r\n                \n\r\n        <div class=\"clients clients-default\">\r\n                            <div class=\"clients-title container text-accent fs-sm\">\r\n                                            <div class=\"text-center mb-4\">\r\n                            Junte-se a mais de 150.000 empresas, incluindo 8 das 10 maiores empresas de tecnologia do mundo                        <\/div>\r\n                                    <\/div>\r\n                <div class=\"clients-logos container p-0 d-flex overflow-hidden flex-wrap\">\r\n                                                    <div>\r\n                                    <svg width=\"92\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/google.svg\" role=\"img\"\r\n                                        alt=\"Google\">\r\n                                                                                    <title>\r\n                                                Google                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"58\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/uber.svg\" role=\"img\"\r\n                                        alt=\"Uber\">\r\n                                                                                    <title>\r\n                                                Uber                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"132\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/paypal.svg\" role=\"img\"\r\n                                        alt=\"PayPal\">\r\n                                                                                    <title>\r\n                                                PayPal                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"62\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/visa.svg\" role=\"img\"\r\n                                        alt=\"Visa\">\r\n                                                                                    <title>\r\n                                                Visa                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"160\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/albertsons.svg\" role=\"img\"\r\n                                        alt=\"Albertsons\">\r\n                                                                                    <title>\r\n                                                Albertsons                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"86\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/tinder.svg\" role=\"img\"\r\n                                        alt=\"Tinder\">\r\n                                                                                    <title>\r\n                                                Tinder                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"96\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/firstbank.svg\" role=\"img\"\r\n                                        alt=\"First Bank\">\r\n                                                                                    <title>\r\n                                                First Bank                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                        <\/div>\r\n                    <\/div>\r\n\r\n\n\r\n            <\/div>\r\n        \r\n        \r\n        \r\n    <\/section>\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-3f5f757736eed422d55d449db86cc018\" class=\"section section-altblo section-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 col-md-9\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n                            <p class=\"text-uppercase section-caption text-body-color\">O QUE NOS TORNA DIFERENTES\u00a0<\/p>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Encaminhamento de chamadas flex\u00edvel para todas as empresas\u00a0<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Seja voc\u00ea uma startup em crescimento ou uma empresa global, a Sinch facilita o encaminhamento de chamadas. Use nossas ferramentas no-code ou APIs amig\u00e1veis para desenvolvedores para manter as pessoas que ligam conectadas e satisfeitas.\u00a0 <\/p><\/div>\r\n                            \r\n                            \r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 d-none\">\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n\r\n                            <div class=\" mt-6 mt-md-7 mt-lg-9\">\r\n                    \n\r\n    \r\n        <div class=\"row cards gy-6 gy-md-7 gy-lg-9 gx-lg-5 \">\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/phone-sound-badge-check.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Melhor experi\u00eancia para quem liga                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Envie automaticamente as pessoas que ligam para o agente ou departamento certo, reduzindo os tempos de espera e criando uma experi\u00eancia tranquila.\u00a0\u2028                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/rocket.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Aumente a agilidade da empresa\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Encaminhe chamadas para n\u00fameros m\u00f3veis ou de backup instantaneamente para que voc\u00ea sempre consiga contatar sua equipe durante o trabalho remoto, interrup\u00e7\u00f5es ou eventos inesperados.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/curve-chart-up.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Rastrear o desempenho de marketing                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Atribua n\u00fameros exclusivos para cada campanha e encaminhe chamadas de forma centralizada para rastrear quais an\u00fancios geram resultados e maximizar o ROI.\u00a0\u2028                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                    <\/div>\r\n\n\r\n                <\/div>\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-bfc34ee3cf0d7e95329b5dbdd89d8c58\" class=\"section section-altblo section-py bg-light\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n                            <p class=\"text-uppercase section-caption text-body-color\">ATENDIMENTO AO CLIENTE\u00a0<\/p>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Envie cada cliente para o lugar certo\u00a0<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">O encaminhamento de chamadas reconhece o n\u00famero discado e redireciona as chamadas diretamente para a equipe ou agente certo, resultando em um servi\u00e7o mais r\u00e1pido, menos transfer\u00eancias e clientes mais felizes.\u00a0 <\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p class=\"mb-0\">Reduza os tempos de espera\u00a0 <\/p><\/li><li><p class=\"mb-0\">Direcione as chamadas para equipes especializadas\u00a0<\/p><\/li><li><p class=\"mb-0\">Aumente a satisfa\u00e7\u00e3o e a fidelidade\u00a0<br><\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 pe-md-7 pe-lg-10\">\r\n\r\n                    <img decoding=\"async\" width=\"648\" height=\"406\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Diagram-Photo-Voice-Call-Recording.png\" class=\"img-fluid\" alt=\"Imagem para Envie cada cliente para o lugar certo\u00a0\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Diagram-Photo-Voice-Call-Recording.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Diagram-Photo-Voice-Call-Recording-300x188.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Diagram-Photo-Voice-Call-Recording-1024x642.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Diagram-Photo-Voice-Call-Recording-768x482.png 768w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-a120f209e58cfe1043105a67f6c12dac\" class=\"section section-altblo section-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5 order-md-1\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n                            <p class=\"text-uppercase section-caption text-body-color\">CONTINUIDADE DOS NEG\u00d3CIOS\u00a0<\/p>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Mantenha suas equipes conectadas em qualquer lugar\u00a0<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">N\u00e3o deixe que eventos inesperados atrapalhem a sua empresa. Encaminhe n\u00fameros do escrit\u00f3rio para dispositivos m\u00f3veis ou linhas de backup para dar suporte ao trabalho remoto e manter tudo funcionando durante os per\u00edodos de inatividade.\u00a0<\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p class=\"mb-0\">D\u00ea suporte ao trabalho remoto ou h\u00edbrido\u00a0 <\/p><\/li><li><p class=\"mb-0\">Mantenha os servi\u00e7os funcionando durante interrup\u00e7\u00f5es\u00a0 <\/p><\/li><li><p class=\"mb-0\">Proteja a receita com o redirecionamento r\u00e1pido\u00a0 <br><\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 order-md-2 ps-md-7 ps-lg-10 text-md-end\">\r\n\r\n                    <img decoding=\"async\" width=\"648\" height=\"425\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Call-Routing-FinServ.png\" class=\"img-fluid\" alt=\"Imagem para Mantenha suas equipes conectadas em qualquer lugar\u00a0\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Call-Routing-FinServ.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Call-Routing-FinServ-300x197.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Call-Routing-FinServ-1024x672.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Call-Routing-FinServ-768x504.png 768w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-0fde94938f1dd4ad8f19ba26e874d935\" class=\"section section-altblo section-py bg-light\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n                            <p class=\"text-uppercase section-caption text-body-color\">ROI DE MARKETING\u00a0<\/p>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Veja quais an\u00fancios geram chamadas reais\u00a0<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Atribua um n\u00famero exclusivo a cada campanha de an\u00fancios e encaminhe todos eles para uma \u00fanica linha. Rastreie instantaneamente quais campanhas geram chamadas para que voc\u00ea possa investir com sabedoria.\u00a0  <\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p class=\"mb-0\">Atribua chamadas a an\u00fancios de campanhas espec\u00edficas\u00a0 <\/p><\/li><li><p class=\"mb-0\">Me\u00e7a o desempenho da campanha offline\u00a0 <br><\/p><\/li><li><p>Tome decis\u00f5es de or\u00e7amento baseadas em dados\u00a0<\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 pe-md-7 pe-lg-10\">\r\n\r\n                    <img decoding=\"async\" width=\"648\" height=\"423\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Answering-Machine-03.png\" class=\"img-fluid\" alt=\"Imagem para Veja quais an\u00fancios geram chamadas reais\u00a0\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Answering-Machine-03.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Answering-Machine-03-300x196.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Answering-Machine-03-1024x668.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Voice-Answering-Machine-03-768x501.png 768w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-d8bbf445b5249e16ad632c293e6b43f8\" class=\"section section-altblo section-py bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 col-md-9\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n                            <p class=\"text-uppercase section-caption text-body-color\">ENCAMINHAMENTO DE CHAMADAS EM A\u00c7\u00c3O\u00a0<\/p>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Onde o encaminhamento de chamadas entrega valor\u00a0<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                            \r\n                            \r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 d-none\">\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n                            <div class=\" mt-6 mt-md-7 mt-lg-9\">\r\n                    \n\r\n    \r\n        <div class=\"row cards g-3 \">\r\n                            <div class=\"col-12 col-md-6 col-lg-3\">\r\n                                        <div class=\"card h-100 card-bg-solid rounded-lg shadow-sm bg-body d-flex flex-column\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/curve-chart-up.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Rastreamento da campanha de marketing\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Atribua n\u00fameros exclusivos a an\u00fancios e encaminhe chamadas de forma centralizada para ver quais canais geram conversas reais e ajustar seus gastos.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                            <div class=\"col-12 col-md-6 col-lg-3\">\r\n                                        <div class=\"card h-100 card-bg-solid rounded-lg shadow-sm bg-body d-flex flex-column\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/home.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Suporte ao trabalho remoto\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Encaminhe as chamadas do escrit\u00f3rio para telefones m\u00f3veis, para que as equipes permane\u00e7am acess\u00edveis e produtivas, n\u00e3o importando onde estejam.\u00a0\u2028                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                            <div class=\"col-12 col-md-6 col-lg-3\">\r\n                                        <div class=\"card h-100 card-bg-solid rounded-lg shadow-sm bg-body d-flex flex-column\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/phone-arrows-forward.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Continuidade dos neg\u00f3cios\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Redirecione chamadas para backups durante interrup\u00e7\u00f5es ou fechamentos para evitar a perda de oportunidades e manter os servi\u00e7os funcionando.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                            <div class=\"col-12 col-md-6 col-lg-3\">\r\n                                        <div class=\"card h-100 card-bg-solid rounded-lg shadow-sm bg-body d-flex flex-column\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/headset.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Atendimento ao cliente aprimorado\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Conecte cada pessoa que liga diretamente ao departamento certo. Diga adeus \u00e0s transfer\u00eancias intermin\u00e1veis e ol\u00e1 aos clientes felizes.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                    <\/div>\r\n\n\r\n                <\/div>\r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-65864c2d1dce69d09a0c2eb0dcab7081\" class=\"section section-altblo section-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 col-md-9\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n                            <p class=\"text-uppercase section-caption text-body-color\">RECURSOS QUE SIMPLESMENTE FUNCIONAM\u00a0<\/p>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Encaminhamento de chamadas completo e f\u00e1cil\u00a0<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                            \r\n                            \r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 d-none\">\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n\r\n                            <div class=\" mt-6 mt-md-7 mt-lg-9\">\r\n                    \n\r\n    \r\n        <div class=\"row cards gy-6 gy-md-7 gy-lg-9 gx-lg-5 \">\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/wrench.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Configura\u00e7\u00e3o de autoatendimento\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Ative o encaminhamento de chamadas em minutos com o painel da Sinch.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/window.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Op\u00e7\u00e3o no-code\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Usu\u00e1rios sem conhecimento t\u00e9cnico podem definir regras de encaminhamento por meio de uma interface intuitiva.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/api.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                API amig\u00e1vel para desenvolvedores\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Tenha controle total com a Voice API program\u00e1vel e a l\u00f3gica personalizada.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/earth-grid.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Alcance global\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    D\u00ea suporte a clientes e equipes em qualquer lugar com o encaminhamento de chamadas ao redor do mundo.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/badge-money.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Pre\u00e7os claros\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Inclu\u00eddo nas tarifas padr\u00e3o por minuto \u2014 sem taxas ocultas ou cobran\u00e7as extras.\u00a0\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/thumbs-up.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Confiabilidade em Scale\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Criado em uma rede de n\u00edvel corporativo para um encaminhamento de chamadas consistente e de alta qualidade.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/shield-lock.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Seguran\u00e7a de n\u00edvel empresarial\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Em conformidade com a ISO 27001, o GDPR e o STIR\/SHAKEN com criptografia TLS e SRTP.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/eye.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Configura\u00e7\u00e3o em tempo real\u00a0                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Altere as regras de encaminhamento instantaneamente por meio do painel ou da API.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                    <\/div>\r\n\n\r\n                <\/div>\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n        <section data-content-type=\"component\" id=\"faq_1\" class=\"section section-py bg-light bg-light\" data-theme=\"light\">\r\n            <div class=\"container\">\r\n                                    <div class=\"row\">\r\n                        <div class=\"col-12 col-lg-9 offset-lg-1\">\r\n                            <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                        <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Perguntas frequentes sobre o encaminhamento de chamadas\u00a0<\/h2>\r\n                    <\/div>\r\n\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"row justify-content-lg-center mt-6 mt-md-7 mt-lg-9\">\r\n                    <div class=\"col-12 col-lg-10\">\r\n                        <div class=\"accordion accordion-faq faq d-flex flex-column gap-3\">\r\n\r\n                            \r\n                                <div class=\"accordion-item rounded-lg\">\r\n                                    <div\r\n                                        id=\"title-block-25e80e20e995930455aa2372ab3c5c65-1\"\r\n                                        class=\"accordion-header\">\r\n\r\n                                        <button\r\n                                            class=\"accordion-button p-4 p-md-5\"\r\n                                            type=\"button\"\r\n                                            data-bs-toggle=\"collapse\"\r\n                                            data-bs-target=\"#faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-1\"\r\n                                            aria-expanded=\"true\"\r\n                                            aria-controls=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-1\">\r\n                                            O que \u00e9 o encaminhamento de chamadas e como ele funciona?                                        <\/button>\r\n\r\n                                    <\/div>\r\n                                    <div\r\n                                        id=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-1\"\r\n                                        class=\"accordion-collapse collapse show\"\r\n                                        aria-labelledby=\"title-block-25e80e20e995930455aa2372ab3c5c65-1\">\r\n                                        <div class=\"accordion-body content-body px-4 px-md-5 pb-5 pb-md-6 pt-3\">\r\n                                            <p class=\"mb-0\">O encaminhamento de chamadas redireciona automaticamente as chamadas recebidas de um n\u00famero de telefone para outro. Com a Sinch, voc\u00ea define as regras de encaminhamento no painel ou via Voice API, e as chamadas recebidas no seu n\u00famero da Sinch ir\u00e3o diretamente para o destino escolhido.<\/p>                                                                                    <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                            \r\n                                <div class=\"accordion-item rounded-lg\">\r\n                                    <div\r\n                                        id=\"title-block-25e80e20e995930455aa2372ab3c5c65-2\"\r\n                                        class=\"accordion-header\">\r\n\r\n                                        <button\r\n                                            class=\"accordion-button p-4 p-md-5 collapsed\"\r\n                                            type=\"button\"\r\n                                            data-bs-toggle=\"collapse\"\r\n                                            data-bs-target=\"#faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-2\"\r\n                                            aria-expanded=\"false\"\r\n                                            aria-controls=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-2\">\r\n                                            O encaminhamento de n\u00famero est\u00e1 inclu\u00eddo nos pre\u00e7os padr\u00e3o?                                        <\/button>\r\n\r\n                                    <\/div>\r\n                                    <div\r\n                                        id=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-2\"\r\n                                        class=\"accordion-collapse collapse\"\r\n                                        aria-labelledby=\"title-block-25e80e20e995930455aa2372ab3c5c65-2\">\r\n                                        <div class=\"accordion-body content-body px-4 px-md-5 pb-5 pb-md-6 pt-3\">\r\n                                            <p class=\"mb-0\">Sim, o encaminhamento de chamadas est\u00e1 inclu\u00eddo na taxa <a href=\"https:\/\/sinch.com\/pt\/precos\/\">padr\u00e3o por minuto<\/a> para o <a href=\"https:\/\/sinch.com\/pt\/voz\/voz-programavel\/voice-api\/\">Programmable Voice<\/a>. N\u00e3o h\u00e1 cobran\u00e7as adicionais de configura\u00e7\u00e3o ou uso.<\/p>                                                                                    <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                            \r\n                                <div class=\"accordion-item rounded-lg\">\r\n                                    <div\r\n                                        id=\"title-block-25e80e20e995930455aa2372ab3c5c65-3\"\r\n                                        class=\"accordion-header\">\r\n\r\n                                        <button\r\n                                            class=\"accordion-button p-4 p-md-5 collapsed\"\r\n                                            type=\"button\"\r\n                                            data-bs-toggle=\"collapse\"\r\n                                            data-bs-target=\"#faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-3\"\r\n                                            aria-expanded=\"false\"\r\n                                            aria-controls=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-3\">\r\n                                            Preciso de skills t\u00e9cnicas para fazer a configura\u00e7\u00e3o?                                        <\/button>\r\n\r\n                                    <\/div>\r\n                                    <div\r\n                                        id=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-3\"\r\n                                        class=\"accordion-collapse collapse\"\r\n                                        aria-labelledby=\"title-block-25e80e20e995930455aa2372ab3c5c65-3\">\r\n                                        <div class=\"accordion-body content-body px-4 px-md-5 pb-5 pb-md-6 pt-3\">\r\n                                            <p class=\"mb-0\">De forma alguma. O nosso <a href=\"https:\/\/sinch.com\/pt\/sign-up\/\">painel da Sinch<\/a> no-code permite que qualquer pessoa configure e gerencie regras de encaminhamento de chamadas em apenas alguns cliques.<\/p>                                                                                    <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                            \r\n                                <div class=\"accordion-item rounded-lg\">\r\n                                    <div\r\n                                        id=\"title-block-25e80e20e995930455aa2372ab3c5c65-4\"\r\n                                        class=\"accordion-header\">\r\n\r\n                                        <button\r\n                                            class=\"accordion-button p-4 p-md-5 collapsed\"\r\n                                            type=\"button\"\r\n                                            data-bs-toggle=\"collapse\"\r\n                                            data-bs-target=\"#faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-4\"\r\n                                            aria-expanded=\"false\"\r\n                                            aria-controls=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-4\">\r\n                                            Posso encaminhar chamadas internacionalmente?                                        <\/button>\r\n\r\n                                    <\/div>\r\n                                    <div\r\n                                        id=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-4\"\r\n                                        class=\"accordion-collapse collapse\"\r\n                                        aria-labelledby=\"title-block-25e80e20e995930455aa2372ab3c5c65-4\">\r\n                                        <div class=\"accordion-body content-body px-4 px-md-5 pb-5 pb-md-6 pt-3\">\r\n                                            <p class=\"mb-0\">Com certeza. Voc\u00ea pode encaminhar chamadas para n\u00fameros em mais de 70 pa\u00edses e mais de 16.000 cidades com o <a href=\"https:\/\/sinch.com\/pt\/voz\/recursos\/servicos-globais\/\">alcance global da Sinch<\/a>.<\/p>                                                                                    <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                            \r\n                                <div class=\"accordion-item rounded-lg\">\r\n                                    <div\r\n                                        id=\"title-block-25e80e20e995930455aa2372ab3c5c65-5\"\r\n                                        class=\"accordion-header\">\r\n\r\n                                        <button\r\n                                            class=\"accordion-button p-4 p-md-5 collapsed\"\r\n                                            type=\"button\"\r\n                                            data-bs-toggle=\"collapse\"\r\n                                            data-bs-target=\"#faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-5\"\r\n                                            aria-expanded=\"false\"\r\n                                            aria-controls=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-5\">\r\n                                            E quanto \u00e0 seguran\u00e7a e ao compliance?                                        <\/button>\r\n\r\n                                    <\/div>\r\n                                    <div\r\n                                        id=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-5\"\r\n                                        class=\"accordion-collapse collapse\"\r\n                                        aria-labelledby=\"title-block-25e80e20e995930455aa2372ab3c5c65-5\">\r\n                                        <div class=\"accordion-body content-body px-4 px-md-5 pb-5 pb-md-6 pt-3\">\r\n                                            <p class=\"mb-0\">O encaminhamento de chamadas da Sinch \u00e9 certificado pela ISO 27001, compat\u00edvel com o GDPR, compat\u00edvel com <a href=\"https:\/\/sinch.com\/pt\/voz\/seguranca\/stirshaken\/\">STIR\/SHAKEN<\/a> nos EUA\/CA e usa criptografia TLS e SRTP para os dados das chamadas.<\/p>                                                                                    <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                            \r\n                                <div class=\"accordion-item rounded-lg\">\r\n                                    <div\r\n                                        id=\"title-block-25e80e20e995930455aa2372ab3c5c65-6\"\r\n                                        class=\"accordion-header\">\r\n\r\n                                        <button\r\n                                            class=\"accordion-button p-4 p-md-5 collapsed\"\r\n                                            type=\"button\"\r\n                                            data-bs-toggle=\"collapse\"\r\n                                            data-bs-target=\"#faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-6\"\r\n                                            aria-expanded=\"false\"\r\n                                            aria-controls=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-6\">\r\n                                            Como fa\u00e7o para come\u00e7ar a usar o encaminhamento de chamadas?                                        <\/button>\r\n\r\n                                    <\/div>\r\n                                    <div\r\n                                        id=\"faq-collapse-block-25e80e20e995930455aa2372ab3c5c65-6\"\r\n                                        class=\"accordion-collapse collapse\"\r\n                                        aria-labelledby=\"title-block-25e80e20e995930455aa2372ab3c5c65-6\">\r\n                                        <div class=\"accordion-body content-body px-4 px-md-5 pb-5 pb-md-6 pt-3\">\r\n                                            <p>Basta entrar no painel da Sinch, alugar um n\u00famero e definir suas regras de encaminhamento para come\u00e7ar \u2014 \u00e9 muito f\u00e1cil.<\/p>                                                                                    <\/div>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                                    <\/div>\r\n                        <script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"FAQPage\",\"@id\":\"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"O que \u00e9 o encaminhamento de chamadas e como ele funciona?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p class=&quot;mb-0&quot;&gt;O encaminhamento de chamadas redireciona automaticamente as chamadas recebidas de um n\u00famero de telefone para outro. Com a Sinch, voc\u00ea define as regras de encaminhamento no painel ou via Voice API, e as chamadas recebidas no seu n\u00famero da Sinch ir\u00e3o diretamente para o destino escolhido.&lt;\/p&gt;\"}},{\"@type\":\"Question\",\"name\":\"O encaminhamento de n\u00famero est\u00e1 inclu\u00eddo nos pre\u00e7os padr\u00e3o?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p class=&quot;mb-0&quot;&gt;Sim, o encaminhamento de chamadas est\u00e1 inclu\u00eddo na taxa &lt;a href=&quot;https:\/\/sinch.com\/pt\/precos\/&quot;&gt;padr\u00e3o por minuto&lt;\/a&gt; para o &lt;a href=&quot;https:\/\/sinch.com\/pt\/voz\/voz-programavel\/voice-api\/&quot;&gt;Programmable Voice&lt;\/a&gt;. N\u00e3o h\u00e1 cobran\u00e7as adicionais de configura\u00e7\u00e3o ou uso.&lt;\/p&gt;\"}},{\"@type\":\"Question\",\"name\":\"Preciso de skills t\u00e9cnicas para fazer a configura\u00e7\u00e3o?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p class=&quot;mb-0&quot;&gt;De forma alguma. O nosso &lt;a href=&quot;https:\/\/sinch.com\/pt\/sign-up\/&quot;&gt;painel da Sinch&lt;\/a&gt; no-code permite que qualquer pessoa configure e gerencie regras de encaminhamento de chamadas em apenas alguns cliques.&lt;\/p&gt;\"}},{\"@type\":\"Question\",\"name\":\"Posso encaminhar chamadas internacionalmente?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p class=&quot;mb-0&quot;&gt;Com certeza. Voc\u00ea pode encaminhar chamadas para n\u00fameros em mais de 70 pa\u00edses e mais de 16.000 cidades com o &lt;a href=&quot;https:\/\/sinch.com\/pt\/voz\/recursos\/servicos-globais\/&quot;&gt;alcance global da Sinch&lt;\/a&gt;.&lt;\/p&gt;\"}},{\"@type\":\"Question\",\"name\":\"E quanto \u00e0 seguran\u00e7a e ao compliance?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p class=&quot;mb-0&quot;&gt;O encaminhamento de chamadas da Sinch \u00e9 certificado pela ISO 27001, compat\u00edvel com o GDPR, compat\u00edvel com &lt;a href=&quot;https:\/\/sinch.com\/pt\/voz\/seguranca\/stirshaken\/&quot;&gt;STIR\/SHAKEN&lt;\/a&gt; nos EUA\/CA e usa criptografia TLS e SRTP para os dados das chamadas.&lt;\/p&gt;\"}},{\"@type\":\"Question\",\"name\":\"Como fa\u00e7o para come\u00e7ar a usar o encaminhamento de chamadas?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"&lt;p&gt;Basta entrar no painel da Sinch, alugar um n\u00famero e definir suas regras de encaminhamento para come\u00e7ar \u2014 \u00e9 muito f\u00e1cil.&lt;\/p&gt;\"}}]}<\/script>                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/section>\r\n    \n\n\r\n    <section data-content-type=\"component\"  id=\"form\" class=\"section section-py form-block bg-primary\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row justify-content-center\">\r\n                <div class=\"col-12 col-lg-8 justify-content-center\">\r\n\r\n                    <div class=\"\">\r\n\r\n\r\n                        <div class=\"form-block-container shadow-lg bg-body px-5 py-7 p-md-9\" data-theme=\"light\">\r\n\r\n                            \r\n\r\n                                <!-- MARKETING CLOUD Form Container -- Start -->\r\n                                <div class=\"marketing-cloud-form-container\">\r\n                                                                            <div class=\"form-content mb-3\">\r\n                                                                                            <h2 class=\"h5 mb-3\">Fale com um especialista sobre o encaminhamento de chamadas flex\u00edvel\u00a0<\/h2>\r\n                                                                                                                                        <p class=\"content-body text-body-color mb-0\"><p class=\"mb-0\">  Veja como a Sinch ajuda voc\u00ea a encaminhar chamadas para qualquer lugar do mundo, direcionar os clientes para a equipe certa e manter a sua empresa funcionando \u2014 n\u00e3o importa onde seus colaboradores estejam.\u00a0 <\/p><\/p>\r\n                                                                                    <\/div>\r\n\r\n                                    \r\n\r\n                                    \r\n                                    <iframe\r\n                                        id=\"marketing-cloud-form\"\r\n                                        class=\"marketing-cloud-iframe\"\r\n                                        data-iframe-params=\"utm_source,utm_medium,utm_campaign,utm_term,utm_content,transid,gclid,intcmp,msclkid\"\r\n                                        src=\"https:\/\/cloud.m.sinch.com\/sinchform1_0?referrer=https%3A%2F%2Fsinch.com%2Fpt%2Fwp-json%2Fwp%2Fv2%2Fvoice_features%2F187376&#038;lang=pt&#038;theme=sinch.com\"\r\n                                        title=\"Fale com um especialista sobre o encaminhamento de chamadas flex\u00edvel\u00a0\"\r\n                                        style=\"width: 100%;\">\r\n                                    <\/iframe>\r\n                                <\/div>\r\n                                <!-- MARKETING CLOUD Container -- Start -->\r\n\r\n\r\n                                                    <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n","protected":false},"featured_media":169487,"template":"","meta":{"_acf_changed":true},"class_list":["post-187376","voice_features","type-voice_features","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encaminhamento de chamadas | Encaminhamento de n\u00famero flex\u00edvel e econ\u00f4mico<\/title>\n<meta name=\"description\" content=\"Fa\u00e7a cada chamada valer a pena com o encaminhamento de chamadas da Sinch. Redirecione facilmente as chamadas ao redor do mundo, rastreie campanhas e mantenha a sua empresa operando perfeitamente. Comece a encaminhar chamadas hoje mesmo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encaminhamento de chamadas | Encaminhamento de n\u00famero flex\u00edvel e econ\u00f4mico\" \/>\n<meta property=\"og:description\" content=\"Fa\u00e7a cada chamada valer a pena com o encaminhamento de chamadas da Sinch. Redirecione facilmente as chamadas ao redor do mundo, rastreie campanhas e mantenha a sua empresa operando perfeitamente. Comece a encaminhar chamadas hoje mesmo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wearesinch\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T13:04:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Link-Preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WeAreSinch\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/voz\\\/recursos\\\/encaminhamento-de-chamadas\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/pt\\\/voz\\\/recursos\\\/encaminhamento-de-chamadas\\\/\",\"name\":\"Encaminhamento de chamadas | Encaminhamento de n\u00famero flex\u00edvel e econ\u00f4mico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/voz\\\/recursos\\\/encaminhamento-de-chamadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/voz\\\/recursos\\\/encaminhamento-de-chamadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI-Call-Forwarding-Link-Preview.png\",\"datePublished\":\"2026-05-29T15:18:30+00:00\",\"dateModified\":\"2026-06-30T13:04:42+00:00\",\"description\":\"Fa\u00e7a cada chamada valer a pena com o encaminhamento de chamadas da Sinch. Redirecione facilmente as chamadas ao redor do mundo, rastreie campanhas e mantenha a sua empresa operando perfeitamente. Comece a encaminhar chamadas hoje mesmo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/voz\\\/recursos\\\/encaminhamento-de-chamadas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinch.com\\\/pt\\\/voz\\\/recursos\\\/encaminhamento-de-chamadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/voz\\\/recursos\\\/encaminhamento-de-chamadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI-Call-Forwarding-Link-Preview.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI-Call-Forwarding-Link-Preview.png\",\"width\":1200,\"height\":668},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/voz\\\/recursos\\\/encaminhamento-de-chamadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinch.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encaminhamento de chamadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/sinch.com\\\/pt\\\/\",\"name\":\"Sinch\",\"description\":\"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinch.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#organization\",\"name\":\"Sinch\",\"url\":\"https:\\\/\\\/sinch.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"width\":800,\"height\":496,\"caption\":\"Sinch\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wearesinch\\\/\",\"https:\\\/\\\/x.com\\\/WeAreSinch\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sinch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZZ2u_B2afTxA0v-xcgfsaw\",\"https:\\\/\\\/www.instagram.com\\\/wearesinch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encaminhamento de chamadas | Encaminhamento de n\u00famero flex\u00edvel e econ\u00f4mico","description":"Fa\u00e7a cada chamada valer a pena com o encaminhamento de chamadas da Sinch. Redirecione facilmente as chamadas ao redor do mundo, rastreie campanhas e mantenha a sua empresa operando perfeitamente. Comece a encaminhar chamadas hoje mesmo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/","og_locale":"pt_BR","og_type":"article","og_title":"Encaminhamento de chamadas | Encaminhamento de n\u00famero flex\u00edvel e econ\u00f4mico","og_description":"Fa\u00e7a cada chamada valer a pena com o encaminhamento de chamadas da Sinch. Redirecione facilmente as chamadas ao redor do mundo, rastreie campanhas e mantenha a sua empresa operando perfeitamente. Comece a encaminhar chamadas hoje mesmo.","og_url":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/","og_site_name":"Sinch","article_publisher":"https:\/\/www.facebook.com\/wearesinch\/","article_modified_time":"2026-06-30T13:04:42+00:00","og_image":[{"width":1200,"height":668,"url":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Link-Preview.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@WeAreSinch","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/","url":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/","name":"Encaminhamento de chamadas | Encaminhamento de n\u00famero flex\u00edvel e econ\u00f4mico","isPartOf":{"@id":"https:\/\/sinch.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/#primaryimage"},"image":{"@id":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/#primaryimage"},"thumbnailUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Link-Preview.png","datePublished":"2026-05-29T15:18:30+00:00","dateModified":"2026-06-30T13:04:42+00:00","description":"Fa\u00e7a cada chamada valer a pena com o encaminhamento de chamadas da Sinch. Redirecione facilmente as chamadas ao redor do mundo, rastreie campanhas e mantenha a sua empresa operando perfeitamente. Comece a encaminhar chamadas hoje mesmo.","breadcrumb":{"@id":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/#primaryimage","url":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Link-Preview.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Call-Forwarding-Link-Preview.png","width":1200,"height":668},{"@type":"BreadcrumbList","@id":"https:\/\/sinch.com\/pt\/voz\/recursos\/encaminhamento-de-chamadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinch.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Encaminhamento de chamadas"}]},{"@type":"WebSite","@id":"https:\/\/sinch.com\/pt\/#website","url":"https:\/\/sinch.com\/pt\/","name":"Sinch","description":"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch","publisher":{"@id":"https:\/\/sinch.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinch.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sinch.com\/pt\/#organization","name":"Sinch","url":"https:\/\/sinch.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sinch.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","width":800,"height":496,"caption":"Sinch"},"image":{"@id":"https:\/\/sinch.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wearesinch\/","https:\/\/x.com\/WeAreSinch","https:\/\/www.linkedin.com\/company\/sinch","https:\/\/www.youtube.com\/channel\/UCZZ2u_B2afTxA0v-xcgfsaw","https:\/\/www.instagram.com\/wearesinch\/"]}]}},"_links":{"self":[{"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/voice_features\/187376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/voice_features"}],"about":[{"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/types\/voice_features"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/media\/169487"}],"wp:attachment":[{"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/media?parent=187376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}