{"id":36419,"date":"2021-09-20T07:09:00","date_gmt":"2021-09-20T07:09:00","guid":{"rendered":"https:\/\/sinchcomdev.local\/legal\/termos-e-condicoes-suplementares-dos-servicos-de-consultoria\/"},"modified":"2025-10-02T08:35:42","modified_gmt":"2025-10-02T08:35:42","slug":"messaging-supplemental-terms-and-conditions-old","status":"publish","type":"legal","link":"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/","title":{"rendered":"TERMOS E CONDI\u00c7\u00d5ES SUPLEMENTARES DE MENSAGERIA"},"content":{"rendered":"\n<p>Estes termos e condi\u00e7\u00f5es suplementares (&#8220;<strong>Suplemento<\/strong>&#8220;) s\u00e3o parte de um contrato para determinados servi\u00e7os SINCH (&#8220;<strong>Contrato<\/strong>&#8220;) firmado entre SINCH e o Cliente e se aplicam exclusivamente aos servi\u00e7os SINCH que fazem refer\u00eancia a este Suplemento, incluindo servi\u00e7os de Short Message Service (SMS), Rich Communication Services (RCS) e\/ou Multi-media Messaging Service (MMS) (&#8220;<strong>Servi\u00e7o<\/strong>&#8220;) e n\u00e3o a qualquer outro produto ou servi\u00e7o SINCH.&nbsp;<\/p>\n\n\n\n<p>Os termos em mai\u00fasculas s\u00e3o definidos no Gloss\u00e1rio a seguir. Os termos em mai\u00fasculas n\u00e3o definidos neste Suplemento ter\u00e3o os significados que lhes s\u00e3o atribu\u00eddos nos Termos e Condi\u00e7\u00f5es Gerais dos Servi\u00e7os SINCH (&#8220;<strong>GTC<\/strong>&#8220;).&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Parte A \u2013 Termos Legais&nbsp;<\/strong>&nbsp;<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A1. Servi\u00e7os<\/strong>&nbsp;<\/h3>\n\n\n\n<p><strong>A1.1<\/strong>. <strong>Condi\u00e7\u00f5es do Provedor de Servi\u00e7os, leis e regulamentos.<\/strong> N\u00e3o obstante a Se\u00e7\u00e3o 4.1 do GTC, o Cliente dever\u00e1 cumprir todas as Condi\u00e7\u00f5es do Provedor de Servi\u00e7os, requisitos e condi\u00e7\u00f5es legais e regulamentares aplic\u00e1veis e todas as diretrizes aplic\u00e1veis da ind\u00fastria relacionadas aos Dados do Cliente, Servi\u00e7os do Cliente, Mensagens ou seu uso do Servi\u00e7o. Se um Provedor de Servi\u00e7o alterar as Condi\u00e7\u00f5es do Provedor de Servi\u00e7o e\/ou os padr\u00f5es t\u00e9cnicos para a entrega do Servi\u00e7o, a SINCH poder\u00e1 modificar os termos e condi\u00e7\u00f5es que regem esse Servi\u00e7o mediante notifica\u00e7\u00e3o por escrito ao Cliente.&nbsp;<\/p>\n\n\n\n<p><strong>A1.2. Requisitos de participa\u00e7\u00e3o\/n\u00e3o-participa\u00e7\u00e3o do Usu\u00e1rio Final.<\/strong> O Cliente dever\u00e1 enviar Mensagens apenas para Usu\u00e1rios Finais que consentiram, e continuarem a consentir conscientemente ou optar por receb\u00ea-las (\u201c<em>opt-in<\/em>\u201d) e que foram informados de seus direitos, conjuntamente com um processo gratuito e prontamente acess\u00edvel para cancelar o recebimento de Mensagens futuras, como por exemplo, atrav\u00e9s de respostas de texto do Usu\u00e1rio Final PARAR, SAIR, CANCELAR, RECUSAR e\/ou CANCELAR ASSINATURA. O Cliente dever\u00e1 interromper imediatamente o envio de Mensagens para um Usu\u00e1rio Final que optou por n\u00e3o receber tais Mensagens (\u201c<em>opt-out<\/em>\u201d).&nbsp; A pedido da SINCH, o Cliente dever\u00e1 fornecer a prova de todo e qualquer pedido de <em>opt-in(s) <\/em>e\/ou<em> opt-out(s), <\/em>bem como o tempo de resposta para interromper a transmiss\u00e3o de Mensagens ap\u00f3s um pedido de <em>opt-out<\/em>, para a satisfa\u00e7\u00e3o razo\u00e1vel da SINCH.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>A1.3. Fornecimento dos Servi\u00e7os do Cliente<\/strong>. O Cliente dever\u00e1 informar aos Usu\u00e1rios Finais que \u00e9 a fonte e o fornecedor das Mensagens e fornecer os detalhes de contato adequados aos Usu\u00e1rios Finais. O Cliente ser\u00e1 o \u00fanico respons\u00e1vel pelos atos, omiss\u00f5es ou viola\u00e7\u00f5es dos Usu\u00e1rios Finais com rela\u00e7\u00e3o ao uso do Servi\u00e7o e das Mensagens, incluindo, sem limita\u00e7\u00e3o, os Dados do Cliente. O Cliente dever\u00e1 informar imediatamente a SINCH se tomar conhecimento de qualquer viola\u00e7\u00e3o dos termos deste par\u00e1grafo.&nbsp;<\/p>\n\n\n\n<p><strong>A1.4. Restri\u00e7\u00f5es<\/strong>. O Cliente n\u00e3o dever\u00e1 usar o Servi\u00e7o ou permitir que o Servi\u00e7o seja usado:&nbsp;<\/p>\n\n\n\n<p>a)      de uma maneira que viole qualquer lei aplic\u00e1vel, regulamento, diretrizes da ind\u00fastria ou c\u00f3digo de pr\u00e1tica, ou que viole, infrinja ou se aproprie indevidamente dos direitos de terceiros;\u00a0<\/p>\n\n\n\n<p>b)      para transmitir qualquer Mensagem ou qualquer material eletr\u00f4nico (incluindo v\u00edrus ou outras rotinas de programa\u00e7\u00e3o de computador destrutivas semelhantes) que cause, ou provavelmente possa causar, detrimento ou dano \u00e0 Rede SINCH ou qualquer sistema de computador ou equipamento de telecomunica\u00e7\u00f5es ou telefones m\u00f3veis de propriedade da SINCH ou qualquer outra pessoa, ou para facilitar a transmiss\u00e3o ou uso de qualquer c\u00f3digo que permita a terceiros interferir ou acessar quaisquer Dados do Cliente;\u00a0<\/p>\n\n\n\n<p>c)      para enviar <em>spam<\/em>, &#8220;lixo eletr\u00f4nico&#8221; ou publicidade n\u00e3o solicitada ou Mensagens ou material promocional, ou para enviar ou receber ou usar intencionalmente qualquer Mensagem ou material que seja obsceno, abusivo, ofensivo, enganoso, fraudulento, violento, anti\u00e9tico, indecente, difamat\u00f3rio, discriminat\u00f3rio, amea\u00e7ador, calunioso, ilegal ou amea\u00e7ador ou promova o abuso de \u00e1lcool ou o uso de drogas ilegais; ou\u00a0<\/p>\n\n\n\n<p>d)      para enviar quaisquer Mensagens que contenham informa\u00e7\u00f5es m\u00e9dicas e\/ou de emerg\u00eancia com risco de vida se tal Mensagem for o \u00fanico canal de transmiss\u00e3o para o Usu\u00e1rio Final com rela\u00e7\u00e3o a tal emerg\u00eancia.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A2. Conformidade<\/strong>&nbsp;<\/h3>\n\n\n\n<p><strong>A2.1.<\/strong> <strong>Requisitos.<\/strong> As disposi\u00e7\u00f5es das Se\u00e7\u00f5es 2.5 e 4.1(c) do GTC se aplicam igualmente as solicita\u00e7\u00f5es, instru\u00e7\u00f5es e\/ou aos pedidos feitos ou emitidos por qualquer Provedor de Servi\u00e7os.&nbsp;<\/p>\n\n\n\n<p><strong>A2.2. Responsabilidade<\/strong>. A SINCH poder\u00e1, a seu exclusivo crit\u00e9rio, exigir que o Cliente assuma a responsabilidade prim\u00e1ria por qualquer solicita\u00e7\u00e3o ou consulta feita na Se\u00e7\u00e3o A2.1 acima em rela\u00e7\u00e3o a quaisquer Servi\u00e7os do Cliente, Mensagens ou Dados do Cliente ou decorrentes do uso do Cliente do Servi\u00e7o ou de uma viola\u00e7\u00e3o potencial ou real do Contrato pelo Cliente.&nbsp;<\/p>\n\n\n\n<p>O Cliente concorda, \u00e0s suas pr\u00f3prias custas, em aceitar total responsabilidade por qualquer solicita\u00e7\u00e3o ou consulta, incluindo por quaisquer despesas, penalidades, multas, san\u00e7\u00f5es ou outros custos an\u00e1logos que possam surgir, e em rela\u00e7\u00e3o a tal solicita\u00e7\u00e3o ou consulta, fornecer todas as informa\u00e7\u00f5es solicitadas a tal regulador ou Provedor de Servi\u00e7os (com c\u00f3pias para SINCH) em tempo h\u00e1bil.&nbsp;<\/p>\n\n\n\n<p><strong>A2.3. Efeito da Rescis\u00e3o<\/strong>. As Se\u00e7\u00f5es A1.2 (&#8220;<strong>Requisitos de participa\u00e7\u00e3o\/n\u00e3o participa\u00e7\u00e3o do Usu\u00e1rio Final<\/strong>&#8220;) e A1.3 (&#8220;<strong>Fornecimento de Servi\u00e7os ao Cliente<\/strong>&#8220;) acima dever\u00e3o sobreviver a rescis\u00e3o do Contrato.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>A2.4. Indeniza\u00e7\u00e3o<\/strong>. O Cliente indenizar\u00e1 e, por op\u00e7\u00e3o da SINCH, defender\u00e1 a SINCH, suas Afiliadas e subcontratadas contra:&nbsp;&nbsp;<\/p>\n\n\n\n<p>(a)     quaisquer reivindica\u00e7\u00f5es (incluindo, sem limita\u00e7\u00e3o, quaisquer reivindica\u00e7\u00f5es, multas, penalidades ou perdas) ou outras responsabilidades movidas contra a SINCH, suas Afiliadas e subcontratadas por qualquer terceiro (incluindo, sem limita\u00e7\u00e3o, qualquer outro cliente da SINCH, Provedor de Servi\u00e7os ou autoridade governamental ou reguladora) relacionada aos Dados do Cliente, Servi\u00e7os do Cliente, Mensagens ou uso do Servi\u00e7o pelo Cliente (incluindo, sem limita\u00e7\u00e3o, qualquer reclama\u00e7\u00e3o relacionada \u00e0 viola\u00e7\u00e3o ou apropria\u00e7\u00e3o indevida de quaisquer direitos de propriedade intelectual de terceiros ou qualquer viola\u00e7\u00e3o de leis ou regulamentos); e\u00a0\u00a0<\/p>\n\n\n\n<p>(b)     todo pagamento de indeniza\u00e7\u00e3o deferido e transitado em julgado contra a SINCH, suas Afiliadas e subcontratadas com rela\u00e7\u00e3o a essas reivindica\u00e7\u00f5es.\u00a0\u00a0<\/p>\n\n\n\n<p><strong>A2.5. Isen\u00e7\u00e3o de responsabilidade<\/strong>. O Cliente concorda que, no que diz respeito ao fornecimento do Servi\u00e7o, nem a SINCH nem qualquer fornecedor da SINCH ser\u00e1 respons\u00e1vel, seja por obriga\u00e7\u00e3o contratual, legal ou direta perante o Cliente ou qualquer Usu\u00e1rio Final ou qualquer outro cliente do Cliente por (i) quaisquer Mensagens exclu\u00eddas ou n\u00e3o entregues, independentemente do motivo da exclus\u00e3o ou n\u00e3o entrega, incluindo, sem limita\u00e7\u00e3o, erros de processamento de mensagens, erros de transmiss\u00e3o ou rede de mensagens e\/ou falhas de servi\u00e7o; ou (ii) a precis\u00e3o das informa\u00e7\u00f5es fornecidas por meio do Servi\u00e7o.&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Parte B \u2013 Termos Comerciais&nbsp;<\/strong>&nbsp;<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>B1. Responsabilidades do Cliente<\/strong><\/h3>\n\n\n\n<p><strong>B1.1.<\/strong> <strong>Acesso e Conectividade<\/strong>\u00a0<\/p>\n\n\n\n<p>a)      <strong>Conex\u00e3o de Rede SINCH.<\/strong> O Cliente \u00e9 o \u00fanico respons\u00e1vel, as pr\u00f3prias custas, pelo estabelecimento e manuten\u00e7\u00e3o de seus equipamentos, software, instala\u00e7\u00f5es e sua conex\u00e3o \u00e0 Rede SINCH.\u00a0\u00a0<\/p>\n\n\n\n<p>b)      <strong>SINCH Dashboard<\/strong>. A SINCH poder\u00e1, a seu exclusivo crit\u00e9rio, fornecer ao Cliente acesso \u00e0 interface da extranet da world wide web (&#8220;<strong>SINCH Dashboard<\/strong>&#8220;) cujo acesso permitir\u00e1 ao Cliente obter relat\u00f3rios estat\u00edsticos detalhando a atividade do Servi\u00e7o. O acesso ao SINCH Dashboard \u00e9 fornecido ao Cliente apenas para fins informativos, e os dados e informa\u00e7\u00f5es exibidos s\u00e3o fornecidos sem garantias de qualquer tipo quanto a integridade ou precis\u00e3o dos mesmos. O Cliente concorda em n\u00e3o basear-se ou confiar em tais dados e informa\u00e7\u00f5es na contabiliza\u00e7\u00e3o de valores devidos entre as Partes ou para fins de cobran\u00e7a.\u00a0\u00a0<\/p>\n\n\n\n<p>c)      <strong>N\u00fameros de Acesso<\/strong>. O Cliente reconhece que os N\u00fameros de Acesso usados para fornecer os Servi\u00e7os ao Cliente ser\u00e3o, em todo momento, propriedade e estar\u00e3o sujeitos aos termos e condi\u00e7\u00f5es aplic\u00e1veis impostos pela entidade autorizada a administrar tais N\u00fameros de Acesso. Os N\u00fameros de Acesso a serem usados para fornecer o Servi\u00e7o para um Servi\u00e7o do Cliente poder\u00e3o, a crit\u00e9rio exclusivo da SINCH, ser obtidos pela SINCH para o Cliente, se solicitado pelo Cliente mediante a Ordem de Servi\u00e7o aplic\u00e1vel e sujeito \u00e0 disponibilidade.\u00a0 O Cliente n\u00e3o poder\u00e1 utilizar os N\u00fameros de Acesso, exceto em rela\u00e7\u00e3o \u00e0 presta\u00e7\u00e3o do Servi\u00e7o realizada pela SINCH.\u00a0<\/p>\n\n\n\n<p>d)      <strong>Previs\u00f5es de Tr\u00e1fego<\/strong>. O Cliente dever\u00e1 fornecer \u00e0 SINCH previs\u00f5es peri\u00f3dicas e precisas dos volumes m\u00e1ximos de mensagens propostos, incluindo hor\u00e1rios de pico, volumes mensais e trimestrais. Quando o tr\u00e1fego real de Mensagens exceder cento e vinte por cento (120%) do volume previsto (&#8220;<strong>Estouro<\/strong>&#8220;), a SINCH poder\u00e1, sem qualquer responsabilidade para o Cliente, suspender imediatamente o Servi\u00e7o. Sempre que o Cliente n\u00e3o enviar tais previs\u00f5es, a SINCH poder\u00e1, a seu exclusivo crit\u00e9rio, determinar o volume de Mensagens que constitui um Estouro.\u00a0\u00a0<\/p>\n\n\n\n<p><strong>B1.2.<\/strong> <strong>Mensagens Comerciais<\/strong>. O Cliente reconhece que o Servi\u00e7o se destina exclusivamente a Mensagens Comerciais e n\u00e3o dever\u00e1 ser usado para fins de mensagens entre usu\u00e1rios de dispositivos m\u00f3veis. Para os fins desta Se\u00e7\u00e3o, &#8220;Mensagens Comerciais&#8221; significa Mensagens com o intuito a promover ou facilitar, direta ou indiretamente, os bens, servi\u00e7os ou imagem de qualquer pessoa ou entidade que exer\u00e7a uma atividade comercial.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>B2. Termos Comerciais<\/strong>&nbsp;<\/h3>\n\n\n\n<p><strong>B2.1. Aumentos de Pre\u00e7o<\/strong>.&nbsp; Salvo acordo em contr\u00e1rio firmado em uma Ordem de Servi\u00e7o, a SINCH poder\u00e1 modificar quaisquer taxas a seu exclusivo crit\u00e9rio mediante notifica\u00e7\u00e3o por escrito.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Gloss\u00e1rio<\/strong><\/h3>\n\n\n\n<p>1.1 &#8220;<strong>N\u00famero de Acesso<\/strong>&#8221; significa um conjunto de d\u00edgitos usados para permitir que o Cliente envie e\/ou receba Mensagens como parte de um Servi\u00e7o do Cliente. Os N\u00fameros de Acesso dever\u00e3o incluir &#8216;c\u00f3digos curtos&#8217; e &#8216;c\u00f3digos longos&#8217;, conforme aplic\u00e1vel.\u00a0\u00a0<\/p>\n\n\n\n<p>1.2 &#8220;<strong>Servi\u00e7o(s) do Cliente<\/strong>&#8221; significa um programa ou iniciativa de marketing, publicidade, promocional ou informativa ou outro projeto conduzido pelo Cliente utilizando o Servi\u00e7o.\u00a0\u00a0<\/p>\n\n\n\n<p>1.3 &#8220;<strong>Usu\u00e1rio Final<\/strong>&#8221; significa uma pessoa ou entidade que \u00e9 um usu\u00e1rio e\/ou destinat\u00e1rio de um Servi\u00e7o do Cliente.\u00a0\u00a0<\/p>\n\n\n\n<p>1.4 &#8220;<strong>Mensagem<\/strong>&#8221; significa uma mensagem digital que cont\u00e9m Dados do Cliente a ser entregue por tecnologia <em>Short Message Service <\/em>(SMS), Rich Communication Services (RCS), Multi-Media Messaging Service (MMS), Internet Protocol (IP) ou outra tecnologia, protocolos ou padr\u00f5es usados para transmitir conte\u00fado digital ou informa\u00e7\u00f5es por dispositivos m\u00f3veis.\u00a0\u00a0<\/p>\n\n\n\n<p>1.5 &#8220;<strong>Provedor de Servi\u00e7os<\/strong>&#8221; significa qualquer entidade, incluindo, sem limita\u00e7\u00e3o, operadoras de rede m\u00f3vel e agregadores de mensagens m\u00f3veis, que \u00e9 usada em rela\u00e7\u00e3o ao fornecimento do Servi\u00e7o.\u00a0<\/p>\n\n\n\n<p>1.6 &#8220;<strong>Condi\u00e7\u00f5es do Provedor de Servi\u00e7os<\/strong>&#8221; significa as taxas, termos e condi\u00e7\u00f5es e &#8220;c\u00f3digos de conduta&#8221; ou regra de conte\u00fado das mensagens e restri\u00e7\u00f5es impostas pelos Provedores de Servi\u00e7o envolvidos na presta\u00e7\u00e3o do Servi\u00e7o e realiza\u00e7\u00e3o dos Servi\u00e7os ao Cliente como condi\u00e7\u00e3o para permitir que a SINCH forne\u00e7a o Servi\u00e7o e que o Cliente realize os Servi\u00e7os ao Cliente, incorporando tais Condi\u00e7\u00f5es do Provedor de Servi\u00e7o aos termos deste Contrato ou conforme indicado pela SINCH ao Cliente por escrito ou por e-mail periodicamente.\u00a0\u00a0<\/p>\n\n\n\n<p><\/p>\n","protected":false},"author":2,"parent":0,"menu_order":130,"template":"","meta":{"_acf_changed":false,"footnotes":""},"legal_category":[],"class_list":["post-36419","legal","type-legal","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Termos e Condi\u00e7\u00f5es Suplementares de Mensageria - Sinch<\/title>\n<meta name=\"description\" content=\"Explore os Termos e Condi\u00e7\u00f5es Suplementares para Servi\u00e7os de Consultoria e garanta entendimento claro das obriga\u00e7\u00f5es contratuais. Saiba mais!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termos e Condi\u00e7\u00f5es Suplementares de Mensageria - Sinch\" \/>\n<meta property=\"og:description\" content=\"Explore os Termos e Condi\u00e7\u00f5es Suplementares para Servi\u00e7os de Consultoria e garanta entendimento claro das obriga\u00e7\u00f5es contratuais. Saiba mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wearesinch\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-02T08:35:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinch.com\/wp-content\/uploads\/2026\/02\/SI-Powering-Trusted-Comms.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WeAreSinch\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/legal\\\/messaging-supplemental-terms-and-conditions-old\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/pt\\\/legal\\\/messaging-supplemental-terms-and-conditions-old\\\/\",\"name\":\"Termos e Condi\u00e7\u00f5es Suplementares de Mensageria - Sinch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#website\"},\"datePublished\":\"2021-09-20T07:09:00+00:00\",\"dateModified\":\"2025-10-02T08:35:42+00:00\",\"description\":\"Explore os Termos e Condi\u00e7\u00f5es Suplementares para Servi\u00e7os de Consultoria e garanta entendimento claro das obriga\u00e7\u00f5es contratuais. Saiba mais!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/legal\\\/messaging-supplemental-terms-and-conditions-old\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinch.com\\\/pt\\\/legal\\\/messaging-supplemental-terms-and-conditions-old\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/legal\\\/messaging-supplemental-terms-and-conditions-old\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinch.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legal\",\"item\":\"https:\\\/\\\/sinch.com\\\/pt\\\/legal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TERMOS E CONDI\u00c7\u00d5ES SUPLEMENTARES DE MENSAGERIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/sinch.com\\\/pt\\\/\",\"name\":\"Sinch\",\"description\":\"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinch.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#organization\",\"name\":\"Sinch\",\"url\":\"https:\\\/\\\/sinch.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"width\":800,\"height\":496,\"caption\":\"Sinch\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wearesinch\\\/\",\"https:\\\/\\\/x.com\\\/WeAreSinch\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sinch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZZ2u_B2afTxA0v-xcgfsaw\",\"https:\\\/\\\/www.instagram.com\\\/wearesinch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termos e Condi\u00e7\u00f5es Suplementares de Mensageria - Sinch","description":"Explore os Termos e Condi\u00e7\u00f5es Suplementares para Servi\u00e7os de Consultoria e garanta entendimento claro das obriga\u00e7\u00f5es contratuais. Saiba mais!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/","og_locale":"pt_BR","og_type":"article","og_title":"Termos e Condi\u00e7\u00f5es Suplementares de Mensageria - Sinch","og_description":"Explore os Termos e Condi\u00e7\u00f5es Suplementares para Servi\u00e7os de Consultoria e garanta entendimento claro das obriga\u00e7\u00f5es contratuais. Saiba mais!","og_url":"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/","og_site_name":"Sinch","article_publisher":"https:\/\/www.facebook.com\/wearesinch\/","article_modified_time":"2025-10-02T08:35:42+00:00","og_image":[{"width":1200,"height":668,"url":"https:\/\/sinch.com\/wp-content\/uploads\/2026\/02\/SI-Powering-Trusted-Comms.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@WeAreSinch","twitter_misc":{"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/","url":"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/","name":"Termos e Condi\u00e7\u00f5es Suplementares de Mensageria - Sinch","isPartOf":{"@id":"https:\/\/sinch.com\/pt\/#website"},"datePublished":"2021-09-20T07:09:00+00:00","dateModified":"2025-10-02T08:35:42+00:00","description":"Explore os Termos e Condi\u00e7\u00f5es Suplementares para Servi\u00e7os de Consultoria e garanta entendimento claro das obriga\u00e7\u00f5es contratuais. Saiba mais!","breadcrumb":{"@id":"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sinch.com\/pt\/legal\/messaging-supplemental-terms-and-conditions-old\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinch.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Legal","item":"https:\/\/sinch.com\/pt\/legal\/"},{"@type":"ListItem","position":3,"name":"TERMOS E CONDI\u00c7\u00d5ES SUPLEMENTARES DE MENSAGERIA"}]},{"@type":"WebSite","@id":"https:\/\/sinch.com\/pt\/#website","url":"https:\/\/sinch.com\/pt\/","name":"Sinch","description":"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch","publisher":{"@id":"https:\/\/sinch.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinch.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sinch.com\/pt\/#organization","name":"Sinch","url":"https:\/\/sinch.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sinch.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","width":800,"height":496,"caption":"Sinch"},"image":{"@id":"https:\/\/sinch.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wearesinch\/","https:\/\/x.com\/WeAreSinch","https:\/\/www.linkedin.com\/company\/sinch","https:\/\/www.youtube.com\/channel\/UCZZ2u_B2afTxA0v-xcgfsaw","https:\/\/www.instagram.com\/wearesinch\/"]}]}},"_links":{"self":[{"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/legal\/36419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/legal"}],"about":[{"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/types\/legal"}],"author":[{"embeddable":true,"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/legal\/36419\/revisions"}],"wp:attachment":[{"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/media?parent=36419"}],"wp:term":[{"taxonomy":"legal_category","embeddable":true,"href":"https:\/\/sinch.com\/pt\/wp-json\/wp\/v2\/legal_category?post=36419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}