{"id":43245,"date":"2024-03-26T11:22:00","date_gmt":"2024-03-26T11:22:00","guid":{"rendered":"https:\/\/sinchcomdev.local\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/"},"modified":"2025-12-18T16:01:42","modified_gmt":"2025-12-18T16:01:42","slug":"nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel","status":"publish","type":"blog","link":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/","title":{"rendered":"Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>CONTEXTE<\/strong><\/h2>\n\n\n\n<p>Le RCS est partie int\u00e9grante du plan de communication de Nespresso. Il est aussi bien utilis\u00e9 pour les nouvelles collections de caf\u00e9s, que pour la collecte d\u2019opt-in pour les campagnes relationnelles. Cette ann\u00e9e, la marque souhaitait profiter des f\u00eates de no\u00ebl pour faire (re) d\u00e9couvrir ses produits et mettre en avant ses collections accessoires encore peu connues de leurs clients, se pr\u00eatant pourtant parfaitement \u00e0 de beaux cadeaux de No\u00ebl.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>SOLUTION<\/strong><\/h2>\n\n\n\n<p>Nespresso a fait appel \u00e0 Sinch pour les aider dans la cr\u00e9ation de leur sc\u00e9nario (wording, arborescence), dans un premier temps souhait\u00e9 en 2 \u00e9tapes.<\/p>\n\n\n\n<p>En respectant ce d\u00e9tail Sinch a propos\u00e9 que les 2 \u00e9tapes permettent de se renseigner sur 2 th\u00e9matiques : la personnalit\u00e9 du client et ses habitudes de consommation, en employant un ton chaleureux et de proximit\u00e9.<\/p>\n\n\n\n<p>Afin de bien comprendre les go\u00fbts et envies des clients Sinch recommande g\u00e9n\u00e9ralement de cr\u00e9er un bot de 3 \u00e0 5 \u00e9tapes (questions). Ceci n\u2019\u00e9tant pas r\u00e9alisable pour ce use case Sinch a recommand\u00e9 \u00e0 Nespresso d\u2019ajouter une conclusion permettant de le rejouer le sc\u00e9nario ou de permettre au client de d\u00e9couvrir d\u2019autre caf\u00e9s sur le site, au cas o\u00f9 il n\u2019aurait pas trouv\u00e9 son bonheur du premier coup. L\u2019ajout de cette conclusion a permis de g\u00e9n\u00e9rer <strong>25% d\u2019intentions d\u2019achat additionnelles. <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-10827\" width=\"1400\" height=\"361\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/chiffres_nespresso.png\" alt=\"Chiffres montrant de meilleurs taux de clics sur le RCS vs SMS\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/chiffres_nespresso.png 1400w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/chiffres_nespresso-300x77.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/chiffres_nespresso-768x198.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/chiffres_nespresso-1024x264.png 1024w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/figure>\n\n\n\n<p>Bien que Nespresso utilise le RCS depuis plus de 3 ans, la marque continue de comparer les performances du canal et a donc r\u00e9alis\u00e9 un ABC test (SMS &amp; Rich conversationnel) qui s\u2019est une fois de plus av\u00e9r\u00e9 concluant.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Chaque ann\u00e9e nous avons un nouvel univers tr\u00e8s cr\u00e9atif pour la p\u00e9riode des f\u00eates, moment cl\u00e9 de l&rsquo;ann\u00e9e chez Nespresso, o\u00f9 nous cherchons \u00e0 enchanter nos clients.<\/em><\/p>\n\n\n\n<p><em>Dans ce contexte-l\u00e0, nous avons l&rsquo;habitude d&rsquo;envoyer des communications innovantes pour aider nos clients \u00e0 d\u00e9nicher les meilleures id\u00e9es cadeaux, pour eux ou pour leurs proches, parmi notre large s\u00e9lection de produits : caf\u00e9s, accessoires, machines\u2026 <\/em><\/p>\n\n\n\n<p><em>Nous avons opt\u00e9 cette ann\u00e9e pour une campagne RCS afin de mettre en avant tous ces produits de la mani\u00e8re la plus personnalis\u00e9e possible, et guider le client au mieux dans son choix. A la mani\u00e8re d&rsquo;un test de personnalit\u00e9, le client pouvait interagir avec Nespresso pour exprimer ses pr\u00e9f\u00e9rences, ou celle de la personne \u00e0 g\u00e2ter, et enfin trouver LA p\u00e9pite.<\/em><\/p>\n\n\n\n<p><em>Pour r\u00e9aliser ce RCS, nous avons pu compter sur le soutien de Sinch qui a construit cette multiplicit\u00e9 de sc\u00e9nario pour nous permettre de proposer \u00e0 nos clients plus de 30 produits diff\u00e9rents ! Le client avait \u00e9galement la possibilit\u00e9 de recommencer le sc\u00e9nario autant de fois qu&rsquo;il le souhaitait, sans jamais aboutir aux m\u00eames recommandations.<\/em><\/p>\n\n\n\n<p><em>Nous sommes fiers de ce projet qui a permis un contact privil\u00e9gi\u00e9 avec nos clients pendant cette p\u00e9riode festive.<\/em><\/p>\n\n\n\n<p>Maya Verdier &#8211; Chef de Projets Gestion de Campagnes B2C<\/p>\n<\/blockquote>\n","protected":false},"author":39,"featured_media":43247,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"blog_category":[],"class_list":["post-43245","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nespresso: RCS pour Inspirer vos Clients \u00e0 No\u00ebl | Sinch<\/title>\n<meta name=\"description\" content=\"Comment Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nespresso: RCS pour Inspirer vos Clients \u00e0 No\u00ebl | Sinch\" \/>\n<meta property=\"og:description\" content=\"Comment Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wearesinch\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T16:01:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/nespresso_featured_RCSNoel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1401\" \/>\n\t<meta property=\"og:image:height\" content=\"830\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WeAreSinch\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\\\/\",\"name\":\"Nespresso: RCS pour Inspirer vos Clients \u00e0 No\u00ebl | Sinch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/nespresso_featured_RCSNoel.jpg\",\"datePublished\":\"2024-03-26T11:22:00+00:00\",\"dateModified\":\"2025-12-18T16:01:42+00:00\",\"description\":\"Comment Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/nespresso_featured_RCSNoel.jpg\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/nespresso_featured_RCSNoel.jpg\",\"width\":1401,\"height\":830},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinch.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/sinch.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/sinch.com\\\/fr\\\/\",\"name\":\"Sinch\",\"description\":\"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinch.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/#organization\",\"name\":\"Sinch\",\"url\":\"https:\\\/\\\/sinch.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"width\":800,\"height\":496,\"caption\":\"Sinch\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wearesinch\\\/\",\"https:\\\/\\\/x.com\\\/WeAreSinch\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sinch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZZ2u_B2afTxA0v-xcgfsaw\",\"https:\\\/\\\/www.instagram.com\\\/wearesinch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nespresso: RCS pour Inspirer vos Clients \u00e0 No\u00ebl | Sinch","description":"Comment Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/","og_locale":"fr_FR","og_type":"article","og_title":"Nespresso: RCS pour Inspirer vos Clients \u00e0 No\u00ebl | Sinch","og_description":"Comment Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl","og_url":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/","og_site_name":"Sinch","article_publisher":"https:\/\/www.facebook.com\/wearesinch\/","article_modified_time":"2025-12-18T16:01:42+00:00","og_image":[{"width":1401,"height":830,"url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/nespresso_featured_RCSNoel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@WeAreSinch","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/","url":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/","name":"Nespresso: RCS pour Inspirer vos Clients \u00e0 No\u00ebl | Sinch","isPartOf":{"@id":"https:\/\/sinch.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/#primaryimage"},"image":{"@id":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/nespresso_featured_RCSNoel.jpg","datePublished":"2024-03-26T11:22:00+00:00","dateModified":"2025-12-18T16:01:42+00:00","description":"Comment Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl","breadcrumb":{"@id":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/#primaryimage","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/nespresso_featured_RCSNoel.jpg","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/nespresso_featured_RCSNoel.jpg","width":1401,"height":830},{"@type":"BreadcrumbList","@id":"https:\/\/sinch.com\/fr\/blog\/nespresso-utilise-le-rcs-pour-inspirer-ses-clients-noel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinch.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/sinch.com\/fr\/blog\/"},{"@type":"ListItem","position":3,"name":"Nespresso utilise le RCS pour inspirer ses clients \u00e0 No\u00ebl"}]},{"@type":"WebSite","@id":"https:\/\/sinch.com\/fr\/#website","url":"https:\/\/sinch.com\/fr\/","name":"Sinch","description":"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch","publisher":{"@id":"https:\/\/sinch.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinch.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sinch.com\/fr\/#organization","name":"Sinch","url":"https:\/\/sinch.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sinch.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","width":800,"height":496,"caption":"Sinch"},"image":{"@id":"https:\/\/sinch.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wearesinch\/","https:\/\/x.com\/WeAreSinch","https:\/\/www.linkedin.com\/company\/sinch","https:\/\/www.youtube.com\/channel\/UCZZ2u_B2afTxA0v-xcgfsaw","https:\/\/www.instagram.com\/wearesinch\/"]}]}},"_links":{"self":[{"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/blog\/43245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/users\/39"}],"version-history":[{"count":0,"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/blog\/43245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/media\/43247"}],"wp:attachment":[{"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/media?parent=43245"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/tags?post=43245"},{"taxonomy":"blog_category","embeddable":true,"href":"https:\/\/sinch.com\/fr\/wp-json\/wp\/v2\/blog_category?post=43245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}