{"id":170365,"date":"2025-11-06T21:57:33","date_gmt":"2025-11-06T21:57:33","guid":{"rendered":"https:\/\/sinch.com\/?post_type=use-cases&#038;p=170365"},"modified":"2026-01-30T14:14:06","modified_gmt":"2026-01-30T14:14:06","slug":"atencion-cliente","status":"publish","type":"use-cases","link":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/","title":{"rendered":"Contentos"},"content":{"rendered":"\r\n    <section data-content-type=\"component\" class=\"header-block section-py bg-sand\" data-theme=\"light\">\r\n        <div class=\"container header-block-container\">\r\n\r\n            \r\n            <div class=\"row align-items-center\">\r\n                <div class=\"col-12 order-2 col-md-6 col-lg-5 order-md-1\">\r\n                    <div class=\"d-flex flex-column gap-3 gap-md-4\">\r\n                        <div>\r\n                                                            <p class=\"text-uppercase section-caption text-body-color\">Atenci\u00f3n al cliente<\/p>\r\n                            \r\n                            <h1 class=\"text-accent m-0 p-0 h2\">\r\n                                Los clientes satisfechos son clientes fieles                              <\/h1>\r\n                        <\/div>\r\n\r\n                                                    <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Con los chatbots de IA y una moderna soluci\u00f3n de centro de contacto, Sinch te ayuda a ofrecer una asistencia personalizada que hace que los clientes vuelvan.<\/p><\/div>\r\n                        \r\n                        \r\n                        \r\n                                                    <div class=\"btn-group g-3 mt-0 row\">\r\n                                \r\n        <div class=\"col-auto\">\r\n        <a href=\"#form\"  class=\"btn btn-secondary btn-lg btn-animated scrollme\" >Habla con un experto<\/a>\r\n        <\/div>\r\n                                    <\/div>\r\n\r\n                                                                        <\/div>\r\n                <\/div>\r\n\r\n                                    <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 order-md-2 ps-md-7 ps-lg-10 text-md-end\">\r\n\r\n                        \r\n                            <img decoding=\"async\" width=\"648\" height=\"506\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy.png\" class=\"skip-lazy img-fluid\" alt=\"Image for Los clientes satisfechos son clientes fieles\" fetchpriority=\"high\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-300x234.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-1024x800.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-768x600.png 768w\" \/>\r\n                        \r\n                        \r\n                    <\/div>\r\n                \r\n            <\/div>\r\n        <\/div>\r\n\r\n                    <div class=\"block-clients pt-6 pt-md-7 pt-lg-9\">\r\n                \n\r\n        <div class=\"clients clients-default\">\r\n                            <div class=\"clients-title container text-accent fs-sm\">\r\n                                            <div class=\"text-center mb-4\">\r\n                            M\u00e1s de 900&nbsp;000 millones de interacciones enviadas cada a\u00f1o, para empresas que necesitan poder contar con resultados fiables                        <\/div>\r\n                                    <\/div>\r\n                <div class=\"clients-logos container p-0 d-flex overflow-hidden flex-wrap\">\r\n                                                    <div>\r\n                                    <svg width=\"92\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/google.svg\" role=\"img\"\r\n                                        alt=\"Google\">\r\n                                                                                    <title>\r\n                                                Google                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"58\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/uber.svg\" role=\"img\"\r\n                                        alt=\"Uber\">\r\n                                                                                    <title>\r\n                                                Uber                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"132\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/paypal.svg\" role=\"img\"\r\n                                        alt=\"PayPal\">\r\n                                                                                    <title>\r\n                                                PayPal                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"62\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/visa.svg\" role=\"img\"\r\n                                        alt=\"Visa\">\r\n                                                                                    <title>\r\n                                                Visa                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"160\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/albertsons.svg\" role=\"img\"\r\n                                        alt=\"Albertsons\">\r\n                                                                                    <title>\r\n                                                Albertsons                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"86\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/tinder.svg\" role=\"img\"\r\n                                        alt=\"Tinder\">\r\n                                                                                    <title>\r\n                                                Tinder                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"96\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/firstbank.svg\" role=\"img\"\r\n                                        alt=\"First Bank\">\r\n                                                                                    <title>\r\n                                                First Bank                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                        <\/div>\r\n                    <\/div>\r\n\r\n\n\r\n            <\/div>\r\n        \r\n        \r\n        \r\n    <\/section>\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-3f9c6e4e397c1100395404e44e83b413\" class=\"section section-altblo section-py bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 col-md-9\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h4\">Las expectativas de los clientes aumentan. Los presupuestos no. Tu equipo lo siente cada d\u00eda.  <\/h2>\r\n                    <\/div>\r\n\r\n\r\n                            \r\n                            \r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 d-none\">\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n                            <div class=\" mt-6 mt-md-7 mt-lg-9\">\r\n                    \n\r\n    \r\n        <div class=\"row cards g-3 \">\r\n                            <div class=\"col-12 col-md-6 col-lg-4\">\r\n                                        <div class=\"card h-100 card-bg-solid rounded-lg shadow-sm bg-body d-flex flex-column\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/hourglass.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Demasiadas incidencias, poco tiempo                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    A medida que aumenta el volumen, crecen los tiempos de espera y las cuestiones urgentes quedan enterradas, con lo que los clientes corren el riesgo de marcharse.\u2028\u2028                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                            <div class=\"col-12 col-md-6 col-lg-4\">\r\n                                        <div class=\"card h-100 card-bg-solid rounded-lg shadow-sm bg-body d-flex flex-column\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/wrench.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                El servicio gen\u00e9rico est\u00e1 perjudicando tus ANS                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Las respuestas de talla \u00fanica y los bots que no pueden manejar la complejidad, provocan m\u00e1s escaladas y tiempos de resoluci\u00f3n m\u00e1s largos.\u2028\u2028                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                            <div class=\"col-12 col-md-6 col-lg-4\">\r\n                                        <div class=\"card h-100 card-bg-solid rounded-lg shadow-sm bg-body d-flex flex-column\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/connection.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Los canales desconectados frustran a los clientes                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Cuando las conversaciones no se trasladan al chat, al email o al tel\u00e9fono, los clientes se repiten y la satisfacci\u00f3n disminuye.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                    <\/div>\r\n\n\r\n                <\/div>\r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\"  class=\"section section-py bg-light\" data-theme=\"light\">\r\n        <div class=\"position-relative overflow-hidden resources-cards-wrap\">\r\n            <div class=\"position-relative resources-cards\">\r\n                                    <div class=\"container\">\r\n                        <div class=\"d-flex flex-column flex-md-row align-items-start justify-content-between gap-6 gap-md-7 gap-lg-9\">\r\n                            <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                        <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">As\u00ed puede ayudarte Sinch<\/h2>\r\n                    <\/div>\r\n\r\n                                                            <\/div>\r\n                                                            <div class=\"\">\r\n                                        <div class=\"d-flex gap-4\">\r\n        <button data-carousel-role=\"prev\" data-carousel-nav=\"block-396941ce6745c6414911f7b38032915b\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Diapositiva anterior\">\r\n            <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-left.svg\"><\/svg>\r\n        <\/button>\r\n        <button data-carousel-role=\"next\" data-carousel-nav=\"block-396941ce6745c6414911f7b38032915b\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Siguiente diapositiva\">\r\n            <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n        <\/button>\r\n    <\/div>\r\n                                    <\/div>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                                <div class=\"w-100 mt-6 mt-md-7 mt-lg-9\">\r\n                    <div class=\"carousel\" data-carousel=\"block-396941ce6745c6414911f7b38032915b\" data-carousel-active-index=\"0\" data-carousel-dragable=\"false\">\r\n                        <div class=\"container\">\r\n                            <div class=\"carousel__track carouselTrack\" data-transition=\"true\">\r\n                                <div class=\"row position-relative flex-nowrap\">\r\n                                    \r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-3\" data-carousel-slide=\"0\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"800\" height=\"496\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-10.png\" class=\"rounded-0\" alt=\"Imagen para Asistencia\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-10.png 800w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-10-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-10-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-10-784x486.png 784w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Asistencia                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Ofrece a cada cliente una experiencia coherente, independientemente del canal. Gestiona conversaciones de voz, email, SMS, chat y aplicaciones, todo desde un solo lugar.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-3\" data-carousel-slide=\"1\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"800\" height=\"496\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-9.png\" class=\"rounded-0\" alt=\"Imagen para Automatizar\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-9.png 800w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-9-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-9-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-9-784x486.png 784w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Automatizar                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Los chatbots de IA aprovechan tu base de conocimientos para gestionar problemas comunes a trav\u00e9s de cualquier canal, mientras que el IVR garantiza que los llamantes lleguen al recurso adecuado sin rodeos.                                  <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-3\" data-carousel-slide=\"2\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"800\" height=\"496\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-8.png\" class=\"rounded-0\" alt=\"Imagen para Entregar\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-8.png 800w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-8-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-8-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-8-784x486.png 784w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Entregar                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Mant\u00e9n las incidencias activas. Si una notificaci\u00f3n por mensaje de texto, email o aplicaci\u00f3n no llega, la l\u00f3gica de alternativas cambia autom\u00e1ticamente la ruta para que los clientes sigan recibiendo la ayuda que necesitan.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-3\" data-carousel-slide=\"3\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"800\" height=\"496\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-7.png\" class=\"rounded-0\" alt=\"Imagen para Crecer\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-7.png 800w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-7-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-7-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-7-784x486.png 784w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Crecer                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    De miles a cientos de millones de interacciones, Sinch crece contigo. Nuestra infraestructura de nivel empresarial mantiene los costes predecibles y el rendimiento fiable.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-3\" data-carousel-slide=\"4\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"800\" height=\"496\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-6.png\" class=\"rounded-0\" alt=\"Imagen para Redirigir\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-6.png 800w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-6-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-6-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-6-784x486.png 784w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Redirigir                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    El enrutamiento basado en habilidades conecta a cada cliente con el agente mejor cualificado a la primera, reduciendo las transferencias, ahorrando tiempo y aumentando la satisfacci\u00f3n.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-3\" data-carousel-slide=\"5\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"800\" height=\"496\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-5.png\" class=\"rounded-0\" alt=\"Imagen para Conexi\u00f3n intuitiva\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-5.png 800w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-5-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-5-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-5-784x486.png 784w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Conexi\u00f3n intuitiva                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Re\u00fane todas tus herramientas. Sinch se integra perfectamente con CRM, ticketing y bases de conocimiento para que los agentes tengan el contexto al alcance de la mano.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                    \r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n    \r\n\n\n        \r\n        <section data-content-type=\"component\"  class=\"section overflow-hidden section-py bg-body\" data-theme=\"light\">\r\n            <div class=\"d-flex flex-column gap-6 gap-md-7 gap-lg-9\">\r\n                                <div class=\"carousel \" data-carousel=\"block-1c17bfdfab0eaaeb4baeb89e25ba1b41\" data-carousel-active-index=\"0\" data-carousel-dragable=\"true\" data-cursor-helper=\"Drag\">\r\n                    <div class=\"container testimonials\">\r\n                        <div class=\"carousel__track carouselTrack\" data-transition=\"true\">\r\n                            <div class=\"row position-relative flex-nowrap\">\r\n                                                                    <div class=\"col-12 active\" data-carousel-slide=\"0\">\r\n                                        <div class=\"quote carousel-item bg-primary  px-5 py-7 p-md-9 rounded-xl shadow-lg d-flex flex-column m-0 h-100\" data-theme=\"light\">\r\n\r\n                                            <div class=\"row g-5 g-md-6 g-lg-7\">\r\n                                                <div class=\"col-12 col-lg-6 gap-4 gap-md-5 d-flex flex-column\">\r\n                                                                                                            <div class=\"quote-logo\">\r\n                                                                                                                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/moet-ik-naar-de-dokter.svg\" alt=\"Logotipo del testimonio de \">\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                                                                            <div>\r\n                                                            \r\n                                                                                                                            <blockquote class=\"m-0 quote-content text-body-color\" id=\"quote-block-1c17bfdfab0eaaeb4baeb89e25ba1b41-0\">\r\n                                                                    \u00abNecesitaba crear un bot de voz para el enrutamiento de urgencias con el fin de reducir los tiempos de espera de los pacientes. Ha sido una gran experiencia trabajar con Sinch porque la informaci\u00f3n fluye en ambos sentidos. Dedican todos sus recursos al problema que intentamos resolver\u00bb.                                                                <\/blockquote>\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                    \r\n                                                    \r\n                                                    \r\n\r\n                                                                                                            <div class=\"quote-link\">\r\n                                                            <a href=\"https:\/\/sinch.com\/customer-stories\/how-mindd-built-ai-enabled-voice-chatbot-safely-triage-patients\/\"  class=\"btn-arrow fs-sm \" >Lee el testimonio<\/a>\r\n                                                        <\/div>\r\n                                                    \r\n                                                <\/div>\r\n\r\n                                                \r\n                                                    <div class=\"col-12 col-lg-6 text-end\">\r\n\r\n                                                        \r\n                                                                            <a href=\"https:\/\/www.youtube.com\/watch?v=KfgsXLfUvI4\" class=\"d-block border-0 p-0 rounded-lg overflow-hidden bg-transparent position-relative lazy-video-link\" data-modal-video=\"KfgsXLfUvI4\" target=\"_blank\" rel=\"nofollow\" role=\"button\" data-source=\"youtube\" data-language=\"es\" type=\"button\" data-cursor-helper=\"Play\" data-cursor-helper-icon=\"play\">\r\n                                    <div class=\"lazy-video-preview position-relative\">\r\n                        <div data-lazy-video=\"1123888336\" data-lazy-video-trigger=\"initial\" data-lazy-video-preview data-source=\"vimeo\">\r\n                        <\/div>\r\n                        <img decoding=\"async\" class=\"img-fluid w-100\" src=\"https:\/\/i.vimeocdn.com\/video\/2065606873-50da5dc9635eb69213d9801407a1d61d082b121aecb973b786bd6a73bed7ce75-d_1280?region=us\" alt=\"Reducing patient wait times with an AI voice bot\">\r\n                    <\/div>\r\n                \r\n                <div class=\"btn btn-light btn-light-social btn-play btn-play-square\">\r\n                    <svg width=\"32\" height=\"32\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/play.svg\"><\/svg>\r\n                <\/div>\r\n            <\/a>\r\n                        <script type=\"application\/ld+json\">\r\n            {\n    \"@context\": \"http:\/\/schema.org\",\n    \"@type\": \"VideoObject\",\n    \"@id\": \"https:\/\/www.youtube.com\/watch?v=KfgsXLfUvI4#VideoObject\",\n    \"thumbnailUrl\": \"https:\/\/img.youtube.com\/vi\/KfgsXLfUvI4\/maxresdefault.jpg\",\n    \"embedUrl\": \"https:\/\/www.youtube.com\/embed\/KfgsXLfUvI4\",\n    \"contentUrl\": \"https:\/\/www.youtube.com\/watch?v=KfgsXLfUvI4\",\n    \"name\": \"Reducing patient wait times with an AI voice bot\",\n    \"description\": \"Discover how Moet Ik Naar De Dokter (MINDD), a Dutch medical technology company, is improving patient experiences with conversational AI. \\n\\nTogether with Sinch, they developed an advanced voice chatbot that effectively triages patient calls, ensuring urgent cases receive immediate attention. \\n\\nThe voice bot then poses a series of questions, created by medical professionals, to triage callers based on symptom severity. The NLP model is trained to recognize over 70 different medical issues, and the system will prioritize calls accordingly. \\n\\nAll this information is securely relayed directly to the doctor\\u2019s office, equipping human agents with the necessary data to assist effectively. \\n\\nThe NLP model is also trained to recognize signs of distress. Should a patient urgently need help and request it, the AI voice assistant immediately shifts them from the standard triage process to an accelerated lane for assistance. \\n\\n\\nRead the full story: https:\/\/www.sinch.com\/insights\/customer-stories\/how-mindd-built-ai-enabled-voice-chatbot-safely-triage-patients\/\\n\\n\\n#VoiceAI #VoiceBot #AI\",\n    \"uploadDate\": \"2024-06-12T12:40:03+00:00\",\n    \"duration\": \"PT3M38S\"\n}        <\/script>\r\n        \r\n                                                        \r\n                                                    <\/div>\r\n\r\n                                                                                            <\/div>\r\n\r\n                                        <\/div>\r\n\r\n                                    <\/div>\r\n                                                                    <div class=\"col-12\" data-carousel-slide=\"1\">\r\n                                        <div class=\"quote carousel-item bg-primary  px-5 py-7 p-md-9 rounded-xl shadow-lg d-flex flex-column m-0 h-100\" data-theme=\"light\">\r\n\r\n                                            <div class=\"row g-5 g-md-6 g-lg-7\">\r\n                                                <div class=\"col-12 col-lg-6 gap-4 gap-md-5 d-flex flex-column\">\r\n                                                                                                            <div class=\"quote-logo\">\r\n                                                                                                                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/aquanet.svg\" alt=\"Logotipo del testimonio de Katarzyna Szram\">\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                                                                            <div>\r\n                                                            \r\n                                                                                                                            <blockquote class=\"m-0 quote-content text-body-color\" id=\"quote-block-1c17bfdfab0eaaeb4baeb89e25ba1b41-1\">\r\n                                                                    \u00abEl hecho de que el cliente pueda cerrar el caso en el primer contacto hablando con una sola persona, en lugar de tener que ponerse \u00e9l mismo en contacto con distintos departamentos en distintos n\u00fameros de tel\u00e9fono, hablar con varias personas y repetir cada vez el problema comunicado, es extremadamente importante\u00bb.\u2028                                                                <\/blockquote>\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                    \r\n                                                    \r\n                                                                                                            <div class=\"mt-auto\">\r\n                                                            <div class=\"d-flex gap-3\">\r\n                                                                \r\n                                                                                                                                    <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                                                                        <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-1c17bfdfab0eaaeb4baeb89e25ba1b41-1\">\r\n                                                                            Katarzyna Szram                                                                        <\/cite>\r\n\r\n                                                                                                                                                    <span class=\"mb-0 text-body-color\">Directora comercial, Aquanet SA<\/span>\r\n                                                                                                                                            <\/div>\r\n                                                                                                                            <\/div>\r\n                                                        <\/div>\r\n\r\n                                                    \r\n\r\n                                                                                                            <div class=\"quote-link\">\r\n                                                            <a href=\"https:\/\/sinch.com\/customer-stories\/streamlining-customer-service-communication-aquanet\/\"  class=\"btn-arrow fs-sm \" >Lee el testimonio<\/a>\r\n                                                        <\/div>\r\n                                                    \r\n                                                <\/div>\r\n\r\n                                                \r\n                                                    <div class=\"col-12 col-lg-6 text-end\">\r\n\r\n                                                        \r\n                                                            <img decoding=\"async\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/Customer-Katarzyna-Szram.svg\" class=\"img-fluid rounded w-100\" alt=\"Image for Testimonial\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 528px, (min-resolution: 2dppx) and (min-width: 1200px) 528px, (min-width: 1200px) 1056px, 100vw\" \/>\r\n                                                        \r\n                                                        \r\n                                                    <\/div>\r\n\r\n                                                                                            <\/div>\r\n\r\n                                        <\/div>\r\n\r\n                                    <\/div>\r\n                                                                    <div class=\"col-12\" data-carousel-slide=\"2\">\r\n                                        <div class=\"quote carousel-item bg-primary  px-5 py-7 p-md-9 rounded-xl shadow-lg d-flex flex-column m-0 h-100\" data-theme=\"light\">\r\n\r\n                                            <div class=\"row g-5 g-md-6 g-lg-7\">\r\n                                                <div class=\"col-12 col-lg-6 gap-4 gap-md-5 d-flex flex-column\">\r\n                                                                                                            <div class=\"quote-logo\">\r\n                                                                                                                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/vanmoof.svg\" alt=\"Logotipo del testimonio de Fenne de Beer\">\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                                                                            <div>\r\n                                                            \r\n                                                                                                                            <blockquote class=\"m-0 quote-content text-body-color\" id=\"quote-block-1c17bfdfab0eaaeb4baeb89e25ba1b41-2\">\r\n                                                                    \u00abCon el chatbot de Sinch, podemos gestionar muchas m\u00e1s preguntas en distintos idiomas que antes, sin tener que aumentar el n\u00famero de agentes\u00bb.<br \/>\r\n                                                                <\/blockquote>\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                    \r\n                                                    \r\n                                                                                                            <div class=\"mt-auto\">\r\n                                                            <div class=\"d-flex gap-3\">\r\n                                                                \r\n                                                                                                                                    <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                                                                        <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-1c17bfdfab0eaaeb4baeb89e25ba1b41-2\">\r\n                                                                            Fenne de Beer                                                                        <\/cite>\r\n\r\n                                                                                                                                                    <span class=\"mb-0 text-body-color\">Gestora de proyectos, VanMoof<\/span>\r\n                                                                                                                                            <\/div>\r\n                                                                                                                            <\/div>\r\n                                                        <\/div>\r\n\r\n                                                    \r\n\r\n                                                                                                            <div class=\"quote-link\">\r\n                                                            <a href=\"https:\/\/sinch.com\/customer-stories\/how-vanmoof-used-ai-chatbot-scale-customer-service\/\"  class=\"btn-arrow fs-sm \" >Lee el testimonio<\/a>\r\n                                                        <\/div>\r\n                                                    \r\n                                                <\/div>\r\n\r\n                                                \r\n                                                    <div class=\"col-12 col-lg-6 text-end\">\r\n\r\n                                                        \r\n                                                            <img decoding=\"async\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/Customer-Fenne-de-Beer.svg\" class=\"img-fluid rounded w-100\" alt=\"Image for Testimonial\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 528px, (min-resolution: 2dppx) and (min-width: 1200px) 528px, (min-width: 1200px) 1056px, 100vw\" \/>\r\n                                                        \r\n                                                        \r\n                                                    <\/div>\r\n\r\n                                                                                            <\/div>\r\n\r\n                                        <\/div>\r\n\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                                    <div class=\"\">\r\n                        <div class=\"container d-flex justify-content-center\">\r\n                                    <div class=\"d-flex gap-4\">\r\n            <button data-carousel-role=\"prev\" data-carousel-nav=\"block-1c17bfdfab0eaaeb4baeb89e25ba1b41\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Diapositiva anterior\">\r\n                <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-left.svg\"><\/svg>\r\n            <\/button>\r\n            <button data-carousel-role=\"next\" data-carousel-nav=\"block-1c17bfdfab0eaaeb4baeb89e25ba1b41\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Siguiente diapositiva\">\r\n                <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n            <\/button>\r\n        <\/div>\r\n                                <\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n        <\/section>\r\n    \n\n\r\n    <section data-content-type=\"component\" id=\"block-deabba4bf37eb0ffc9ee2706b9344cf5\" class=\"section section-altblo section-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Compatibilidad multicanal creado para un servicio al cliente de primera clase  <\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Fideliza a tus clientes con un servicio constante y conectado. Sinch proporciona a los agentes el contexto y las herramientas que necesitan para resolver los problemas m\u00e1s r\u00e1pidamente y reducir la frustraci\u00f3n.<\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p>Transfiere el contexto a trav\u00e9s de los canales para que los clientes no tengan que repetirse<\/p><\/li><li><p class=\"mb-0\">Organiza conversaciones fluidas con nuestro creador de chatbots con IA y nuestro centro de contacto integrado<\/p><\/li><li><p class=\"mb-0\">Int\u00e9gralo todo sin esfuerzo con tus CRM, sistemas de tickets y bases de conocimiento para resoluciones m\u00e1s r\u00e1pidas<\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 pe-md-7 pe-lg-10\">\r\n\r\n                    <img decoding=\"async\" width=\"648\" height=\"464\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-2.png\" class=\"img-fluid\" alt=\"Imagen para Compatibilidad multicanal creado para un servicio al cliente de primera clase\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-2.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-2-300x215.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-2-1024x734.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-2-768x551.png 768w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-796c8eddeeac28e6c01a5652ece68839\" class=\"section section-altblo section-py bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5 order-md-1\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Aumenta el CSAT, reduciendo tus costes  <\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Resuelve los problemas r\u00e1pidamente mientras mantienes a los agentes centrados en la felicidad del cliente. Sinch te permite combinar la automatizaci\u00f3n basada en IA con la experiencia humana para ofrecer una atenci\u00f3n al cliente brillante.<\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p class=\"mb-0\">Gestiona las consultas rutinarias al instante con chatbots de IA y un IVR moderno<\/p><\/li><li><p class=\"mb-0\">Asigna autom\u00e1ticamente la consulta de un cliente al agente m\u00e1s cualificado en funci\u00f3n de sus habilidades, experiencia o idioma<\/p><\/li><li><p class=\"mb-0\">Ofrece un servicio proactivo con mensajes salientes automatizados y devoluciones de llamada<\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 order-md-2 ps-md-7 ps-lg-10 text-md-end\">\r\n\r\n                    <img decoding=\"async\" width=\"648\" height=\"493\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-3.png\" class=\"img-fluid\" alt=\"Imagen para Aumenta el CSAT, reduciendo tus costes\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-3.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-3-300x228.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-3-1024x780.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-3-768x585.png 768w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-d52fe27d0a328a0c10d87d51fd46e326\" class=\"section section-altblo section-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Alcance global con SLA garantizados  <\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Resuelve los problemas de los clientes en su canal preferido. La infraestructura de nivel empresarial de Sinch, la amplia cobertura de canales y la l\u00f3gica de retroceso incorporada son las claves para aumentar el compromiso y mejorar el ROI.<\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p>Llega a cualquier persona, en cualquier lugar, a trav\u00e9s de llamadas, chatbots, email y mucho m\u00e1s&nbsp;<\/p><\/li><li><p class=\"mb-0\">Acuerdos de nivel de servicio con un tiempo de actividad del 99,95&nbsp;% y mecanismos de conmutaci\u00f3n por error para mejorar la entrega<\/p><\/li><li><p class=\"mb-0\">Opciones alternativas fiables cuando los mensajes no llegan&nbsp;<\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 pe-md-7 pe-lg-10\">\r\n\r\n                    <img decoding=\"async\" width=\"648\" height=\"451\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-4.png\" class=\"img-fluid\" alt=\"Imagen para Alcance global con SLA garantizados\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-4.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-4-300x209.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-4-1024x713.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-4-768x535.png 768w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-fe9b0d50fe889bce82b074ca7297f7bf\" class=\"section section-altblo section-py bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 col-md-6 col-lg-5\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Conecta a los clientes con la ayuda desde cualquier lugar<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Gu\u00eda a cada cliente hacia el mejor servicio de asistencia, sea cual sea el canal, y ofrece experiencias coherentes desde que lo solicita hasta que lo resuelves.<\/p><\/div>\r\n                            \r\n                            \r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 col-md-6 col-lg-7 mt-5 mt-md-0 ps-md-7 ps-lg-10\">\r\n\r\n                                            \n            <div class=\"loop px-lg-4 marquee marquee-down marquee-gradient-bilateral\">\r\n            <div class=\"marquee-track\">\r\n                                    \r\n                                                    <a href=\"https:\/\/sinch.com\/voice\/programmable-voice\/voice-api\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/soundwaves.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Voz<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/sinch-chat\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-user.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Chat en directo<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/products\/mailgun-send\/?utm_source=sinch\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/email.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Email<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/sms\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-text.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">SMS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/mms\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-stack-audio-video.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">MMS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/rcs\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-stack-video-ellipsis.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">RCS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/whatsapp\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/whatsapp.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">WhatsApp<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/facebook-messenger\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/facebook.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Facebook Messenger<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/instagram\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/instagram.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Instagram<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/viber\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/viber.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Viber<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/telegram\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/telegram.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Telegram<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/kakaotalk\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/kakaotalk.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">KakaoTalk<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/messaging\/conversation-api\/line\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/line.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">LINE<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/wechat\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/wechat.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">WeChat<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                                                        \r\n                                                    <a href=\"https:\/\/sinch.com\/voice\/programmable-voice\/voice-api\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/soundwaves.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Voz<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/sinch-chat\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-user.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Chat en directo<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/products\/mailgun-send\/?utm_source=sinch\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/email.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Email<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/sms\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-text.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">SMS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/mms\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-stack-audio-video.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">MMS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/rcs\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-stack-video-ellipsis.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">RCS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/whatsapp\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/whatsapp.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">WhatsApp<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/facebook-messenger\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/facebook.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Facebook Messenger<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/instagram\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/instagram.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Instagram<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/viber\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/viber.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Viber<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/telegram\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/telegram.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Telegram<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/kakaotalk\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/kakaotalk.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">KakaoTalk<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/messaging\/conversation-api\/line\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/line.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">LINE<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/wechat\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/wechat.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">WeChat<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                                                <\/div>\r\n        <\/div>\r\n\r\n\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\"  id=\"form\" class=\"section section-py form-block bg-primary\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row justify-content-center\">\r\n                <div class=\"col-12 col-lg-8 justify-content-center\">\r\n\r\n                    <div class=\"\">\r\n\r\n\r\n                        <div class=\"form-block-container shadow-lg bg-body px-5 py-7 p-md-9\" data-theme=\"light\">\r\n\r\n                            \r\n\r\n                                <!-- MARKETING CLOUD Form Container -- Start -->\r\n                                <div class=\"marketing-cloud-form-container\">\r\n                                                                            <div class=\"form-content mb-3\">\r\n                                                                                            <h2 class=\"h5 mb-3\">\u00bfTodo listo para obtener clientes m\u00e1s fieles gracias a un gran servicio?<\/h2>\r\n                                                                                                                                <\/div>\r\n\r\n                                    \r\n\r\n                                    \r\n                                    <iframe\r\n                                        id=\"marketing-cloud-form\"\r\n                                        class=\"marketing-cloud-iframe\"\r\n                                        data-iframe-params=\"utm_source,utm_medium,utm_campaign,utm_term,utm_content,transid,gclid,intcmp,msclkid\"\r\n                                        src=\"https:\/\/cloud.m.sinch.com\/sinchform1_0?referrer=https%3A%2F%2Fsinch.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fuse-cases%2F170365&#038;lang=es&#038;theme=sinch.com\"\r\n                                        title=\"\u00bfTodo listo para obtener clientes m\u00e1s fieles gracias a un gran servicio?\"\r\n                                        style=\"width: 100%;\">\r\n                                    <\/iframe>\r\n                                <\/div>\r\n                                <!-- MARKETING CLOUD Container -- Start -->\r\n\r\n\r\n                                                    <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n","protected":false},"author":19,"featured_media":169162,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-170365","use-cases","type-use-cases","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soluciones de atenci\u00f3n a clientes con SMS, email y m\u00e1s | Sinch<\/title>\n<meta name=\"description\" content=\"Fideliza y reduce costes con SMS, WhatsApp, email y RCS. Mant\u00e9n contentos a los clientes y aumenta las conversiones con Sinch.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soluciones de atenci\u00f3n a clientes con SMS, email y m\u00e1s | Sinch\" \/>\n<meta property=\"og:description\" content=\"Fideliza y reduce costes con SMS, WhatsApp, email y RCS. Mant\u00e9n contentos a los clientes y aumenta las conversiones con Sinch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wearesinch\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T14:14:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-Link-Preview-1024x570.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WeAreSinch\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/atencion-cliente\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/atencion-cliente\\\/\",\"name\":\"Soluciones de atenci\u00f3n a clientes con SMS, email y m\u00e1s | Sinch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/atencion-cliente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/atencion-cliente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI-Use-Case-Happy-Link-Preview.png\",\"datePublished\":\"2025-11-06T21:57:33+00:00\",\"dateModified\":\"2026-01-30T14:14:06+00:00\",\"description\":\"Fideliza y reduce costes con SMS, WhatsApp, email y RCS. Mant\u00e9n contentos a los clientes y aumenta las conversiones con Sinch.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/atencion-cliente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/atencion-cliente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/atencion-cliente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI-Use-Case-Happy-Link-Preview.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI-Use-Case-Happy-Link-Preview.png\",\"width\":1200,\"height\":668},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/atencion-cliente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinch.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Use Cases\",\"item\":\"https:\\\/\\\/sinch.com\\\/es\\\/use-cases\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Contentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/\",\"name\":\"Sinch\",\"description\":\"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinch.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#organization\",\"name\":\"Sinch\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"width\":800,\"height\":496,\"caption\":\"Sinch\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wearesinch\\\/\",\"https:\\\/\\\/x.com\\\/WeAreSinch\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sinch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZZ2u_B2afTxA0v-xcgfsaw\",\"https:\\\/\\\/www.instagram.com\\\/wearesinch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soluciones de atenci\u00f3n a clientes con SMS, email y m\u00e1s | Sinch","description":"Fideliza y reduce costes con SMS, WhatsApp, email y RCS. Mant\u00e9n contentos a los clientes y aumenta las conversiones con Sinch.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/","og_locale":"es_ES","og_type":"article","og_title":"Soluciones de atenci\u00f3n a clientes con SMS, email y m\u00e1s | Sinch","og_description":"Fideliza y reduce costes con SMS, WhatsApp, email y RCS. Mant\u00e9n contentos a los clientes y aumenta las conversiones con Sinch.","og_url":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/","og_site_name":"Sinch","article_publisher":"https:\/\/www.facebook.com\/wearesinch\/","article_modified_time":"2026-01-30T14:14:06+00:00","og_image":[{"url":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-Link-Preview-1024x570.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@WeAreSinch","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/","url":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/","name":"Soluciones de atenci\u00f3n a clientes con SMS, email y m\u00e1s | Sinch","isPartOf":{"@id":"https:\/\/sinch.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/#primaryimage"},"image":{"@id":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-Link-Preview.png","datePublished":"2025-11-06T21:57:33+00:00","dateModified":"2026-01-30T14:14:06+00:00","description":"Fideliza y reduce costes con SMS, WhatsApp, email y RCS. Mant\u00e9n contentos a los clientes y aumenta las conversiones con Sinch.","breadcrumb":{"@id":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/#primaryimage","url":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-Link-Preview.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/10\/SI-Use-Case-Happy-Link-Preview.png","width":1200,"height":668},{"@type":"BreadcrumbList","@id":"https:\/\/sinch.com\/es\/use-cases\/atencion-cliente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinch.com\/es\/"},{"@type":"ListItem","position":2,"name":"Use Cases","item":"https:\/\/sinch.com\/es\/use-cases\/"},{"@type":"ListItem","position":3,"name":"Contentos"}]},{"@type":"WebSite","@id":"https:\/\/sinch.com\/es\/#website","url":"https:\/\/sinch.com\/es\/","name":"Sinch","description":"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch","publisher":{"@id":"https:\/\/sinch.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinch.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sinch.com\/es\/#organization","name":"Sinch","url":"https:\/\/sinch.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sinch.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","width":800,"height":496,"caption":"Sinch"},"image":{"@id":"https:\/\/sinch.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wearesinch\/","https:\/\/x.com\/WeAreSinch","https:\/\/www.linkedin.com\/company\/sinch","https:\/\/www.youtube.com\/channel\/UCZZ2u_B2afTxA0v-xcgfsaw","https:\/\/www.instagram.com\/wearesinch\/"]}]}},"_links":{"self":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/use-cases\/170365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/use-cases"}],"about":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/types\/use-cases"}],"author":[{"embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/users\/19"}],"version-history":[{"count":0,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/use-cases\/170365\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/media\/169162"}],"wp:attachment":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/media?parent=170365"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/tags?post=170365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}