{"id":174274,"date":"2025-12-12T21:43:23","date_gmt":"2025-12-12T21:43:23","guid":{"rendered":"https:\/\/sinch.com\/industries\/servicios-financieros\/"},"modified":"2026-07-08T02:43:56","modified_gmt":"2026-07-08T02:43:56","slug":"servicios-financieros","status":"publish","type":"industries","link":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/","title":{"rendered":"servicios financieros"},"content":{"rendered":"\r\n    <section data-content-type=\"component\" class=\"header-block section-py scrollme glow glow-start glow-top bg-sand\" data-theme=\"light\">\r\n        <div class=\"container header-block-container\">\r\n\r\n            \r\n            <div class=\"row align-items-center\">\r\n                <div class=\"col-12 order-2 col-md-6 col-lg-5 order-md-1\">\r\n                    <div class=\"d-flex flex-column gap-3 gap-md-4\">\r\n                        <div>\r\n                                                            <p class=\"text-uppercase section-caption text-body-color\">servicios financieros<\/p>\r\n                            \r\n                            \r\n                            <h1 class=\"text-accent m-0 p-0 h2\">\r\n                                Una infraestructura de comunicaciones con la que puedes <b class=\"text-highlight\">contar<\/b>                            <\/h1>\r\n                        <\/div>\r\n\r\n                                                    <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Crea experiencias del cliente fiables, escalables y en cumplimiento con la normativa en una plataforma dise\u00f1ada para los servicios financieros modernos.   <\/p><\/div>\r\n                        \r\n                        \r\n                        \r\n                                                    <div class=\"btn-group g-3 mt-0 row\">\r\n                                \r\n        <div class=\"col-auto\">\r\n        <a href=\"#form\"  class=\"btn btn-secondary btn-lg btn-animated scrollme\" >Habla con un experto<\/a>\r\n        <\/div>\r\n                                    <\/div>\r\n\r\n                                                                        <\/div>\r\n                <\/div>\r\n\r\n                                    <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 order-md-2 ps-md-7 ps-lg-10 text-md-end\">\r\n\r\n                        \r\n                            <img decoding=\"async\" width=\"920\" height=\"628\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-hero.png\" class=\"skip-lazy img-fluid\" alt=\"Image for Una infraestructura de comunicaciones con la que puedes contar\" fetchpriority=\"high\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-hero.png 1840w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-hero-300x205.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-hero-1024x699.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-hero-768x524.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-hero-1536x1048.png 1536w\" \/>\r\n                        \r\n                        \r\n                    <\/div>\r\n                \r\n            <\/div>\r\n        <\/div>\r\n\r\n                    <div class=\"block-clients pt-6 pt-md-7 pt-lg-9\">\r\n                \n\r\n        <div class=\"clients clients-default\">\r\n                            <div class=\"clients-title container text-accent fs-sm\">\r\n                                            <div class=\"text-center mb-4\">\r\n                            \u00danete a las miles de empresas de servicios financieros que conf\u00edan en la infraestructura de comunicaciones de Sinch                        <\/div>\r\n                                    <\/div>\r\n                <div class=\"clients-logos container p-0 d-flex overflow-hidden flex-wrap\">\r\n                                                    <div>\r\n                                    <svg width=\"168\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/hsbc.svg\" role=\"img\"\r\n                                        alt=\"hsbc\">\r\n                                                                                    <title>\r\n                                                hsbc                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"62\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/visa.svg\" role=\"img\"\r\n                                        alt=\"visa\">\r\n                                                                                    <title>\r\n                                                visa                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"132\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/paypal.svg\" role=\"img\"\r\n                                        alt=\"paypal\">\r\n                                                                                    <title>\r\n                                                paypal                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"91\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/nordea.svg\" role=\"img\"\r\n                                        alt=\"nordea\">\r\n                                                                                    <title>\r\n                                                nordea                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"116\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/allianz.svg\" role=\"img\"\r\n                                        alt=\"allianz\">\r\n                                                                                    <title>\r\n                                                allianz                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"173\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/nationwide.svg\" role=\"img\"\r\n                                        alt=\"nationwide\">\r\n                                                                                    <title>\r\n                                                nationwide                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                                        <div>\r\n                                    <svg width=\"138\" height=\"48\" class=\"clients-logo\" data-svg-load=\"eager\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/logos\/oxperta-capital.svg\" role=\"img\"\r\n                                        alt=\"oxperta-capital\">\r\n                                                                                    <title>\r\n                                                oxperta-capital                                            <\/title>\r\n                                                                                <\/svg>\r\n                                <\/div>\r\n                                        <\/div>\r\n                    <\/div>\r\n\r\n\n\r\n            <\/div>\r\n        \r\n        \r\n        \r\n    <\/section>\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-3668876b6f05d203aa66dc8ca0ce0c71\" class=\"section section-altblo section-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 col-md-9\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h4\">El sector avanza r\u00e1pido y las expectativas nunca han sido tan altas. \u00bfPuedes seguir el ritmo?<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                            \r\n                            \r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 d-none\">\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n\r\n                            <div class=\" mt-6 mt-md-7 mt-lg-9\">\r\n                    \n\r\n    \r\n        <div class=\"row cards gy-6 gy-md-7 gy-lg-9 gx-lg-5 \">\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/calendar.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Tus comunicaciones parecen anticuadas                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Los emails tradicionales y las llamadas est\u00e1ndar parecen un poco retro en comparaci\u00f3n con la mensajer\u00eda RCS moderna, los emails de precisi\u00f3n y las llamadas en la aplicaci\u00f3n branded.\u00a0\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/privacy.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Los defraudadores trabajan horas extras                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    La AI est\u00e1 haciendo que los ataques sean m\u00e1s r\u00e1pidos y sofisticados. El espacio entre t\u00fa y tus clientes nunca ha estado tan saturado ni ha sido tan peligroso.\u00a0\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/window-stack.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Los recursos fragmentados te est\u00e1n frenando                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Est\u00e1s dedicando demasiado tiempo a desenredar la dispersi\u00f3n tecnol\u00f3gica en lugar de crear nuevas funciones innovadoras.\u00a0\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                    <\/div>\r\n\n\r\n                <\/div>\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\"  class=\"section section-py bg-light\" data-theme=\"light\">\r\n        <div class=\"position-relative overflow-hidden resources-cards-wrap\">\r\n            <div class=\"position-relative resources-cards\">\r\n                                    <div class=\"container\">\r\n                        <div class=\"d-flex flex-column flex-md-row align-items-start justify-content-between gap-6 gap-md-7 gap-lg-9\">\r\n                            <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                        <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">As\u00ed puede ayudarte Sinch<\/h2>\r\n                    <\/div>\r\n\r\n                                                            <\/div>\r\n                                                            <div class=\"\">\r\n                                        <div class=\"d-flex gap-4\">\r\n        <button data-carousel-role=\"prev\" data-carousel-nav=\"block-12a3243b037c77e0c72eecd3ccdcdc8f\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Diapositiva anterior\">\r\n            <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-left.svg\"><\/svg>\r\n        <\/button>\r\n        <button data-carousel-role=\"next\" data-carousel-nav=\"block-12a3243b037c77e0c72eecd3ccdcdc8f\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Siguiente diapositiva\">\r\n            <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n        <\/button>\r\n    <\/div>\r\n                                    <\/div>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                                <div class=\"w-100 mt-6 mt-md-7 mt-lg-9\">\r\n                    <div class=\"carousel\" data-carousel=\"block-12a3243b037c77e0c72eecd3ccdcdc8f\" data-carousel-active-index=\"0\" data-carousel-dragable=\"false\">\r\n                        <div class=\"container\">\r\n                            <div class=\"carousel__track carouselTrack\" data-transition=\"true\">\r\n                                <div class=\"row position-relative flex-nowrap\">\r\n                                    \r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-4\" data-carousel-slide=\"0\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"1600\" height=\"992\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-Be-the-most-reputable-sender-card-v1.png\" class=\"rounded-0\" alt=\"Imagen para Comunicaciones en las que tus clientes pueden confiar\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-Be-the-most-reputable-sender-card-v1.png 1600w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-Be-the-most-reputable-sender-card-v1-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-Be-the-most-reputable-sender-card-v1-1024x635.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-Be-the-most-reputable-sender-card-v1-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-Be-the-most-reputable-sender-card-v1-1208x748.png 1208w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-Be-the-most-reputable-sender-card-v1-784x486.png 784w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-Be-the-most-reputable-sender-card-v1-1536x952.png 1536w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Comunicaciones en las que tus clientes pueden confiar                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Te ofrecemos las herramientas y la orientaci\u00f3n necesarias para garantizar que tengas la mejor reputaci\u00f3n posible en los canales que elijas.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-4\" data-carousel-slide=\"1\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"1600\" height=\"992\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Untangle-your-infrastructure-card.png\" class=\"rounded-0\" alt=\"Imagen para Desenreda tu infraestructura\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Untangle-your-infrastructure-card.png 1600w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Untangle-your-infrastructure-card-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Untangle-your-infrastructure-card-1024x635.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Untangle-your-infrastructure-card-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Untangle-your-infrastructure-card-1208x748.png 1208w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Untangle-your-infrastructure-card-784x486.png 784w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Untangle-your-infrastructure-card-1536x952.png 1536w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Desenreda tu infraestructura                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Consolida tu l\u00edo de API en un \u00fanico panel de control unificado con un socio con el que puedas contar.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-4\" data-carousel-slide=\"2\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"1600\" height=\"992\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Stay-ahead-of-the-regulators-card.png\" class=\"rounded-0\" alt=\"Imagen para Antic\u00edpate a los reguladores\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Stay-ahead-of-the-regulators-card.png 1600w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Stay-ahead-of-the-regulators-card-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Stay-ahead-of-the-regulators-card-1024x635.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Stay-ahead-of-the-regulators-card-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Stay-ahead-of-the-regulators-card-1208x748.png 1208w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Stay-ahead-of-the-regulators-card-784x486.png 784w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Stay-ahead-of-the-regulators-card-1536x952.png 1536w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Antic\u00edpate a los reguladores                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Desde estrictas normas de canal hasta el complejo cumplimiento del sector, nuestros productos se crean con las best practices integradas.\u00a0\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                                                                <div class=\"resoureces-cards__slide col-12 col-md-6 col-lg-4\" data-carousel-slide=\"3\">\r\n                                                                    <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg card-image-zoom-large\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"1600\" height=\"992\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Give-your-AI-a-solid-foundation-card.png\" class=\"rounded-0\" alt=\"Imagen para Dale a tu AI una base s\u00f3lida\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Give-your-AI-a-solid-foundation-card.png 1600w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Give-your-AI-a-solid-foundation-card-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Give-your-AI-a-solid-foundation-card-1024x635.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Give-your-AI-a-solid-foundation-card-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Give-your-AI-a-solid-foundation-card-1208x748.png 1208w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Give-your-AI-a-solid-foundation-card-784x486.png 784w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Give-your-AI-a-solid-foundation-card-1536x952.png 1536w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 justify-content-between\">\r\n                        <div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Dale a tu AI una base s\u00f3lida                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Mant\u00e9n a tus agentes de AI funcionando sin problemas con una infraestructura de red de baja latencia que es la mejor de su clase.\u00a0                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                    <\/div>\r\n                                    \r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n    \r\n\n\n        \r\n        <section data-content-type=\"component\"  id=\"Read\" class=\"section overflow-hidden section-py bg-body\" data-theme=\"light\">\r\n            <div class=\"d-flex flex-column gap-6 gap-md-7 gap-lg-9\">\r\n                                <div class=\"carousel \" data-carousel=\"block-a0450983d89c0857234643c81f33bd04\" data-carousel-active-index=\"0\" data-carousel-dragable=\"true\" data-cursor-helper=\"Drag\">\r\n                    <div class=\"container testimonials\">\r\n                        <div class=\"carousel__track carouselTrack\" data-transition=\"true\">\r\n                            <div class=\"row position-relative flex-nowrap\">\r\n                                                                    <div class=\"col-12 active\" data-carousel-slide=\"0\">\r\n                                        <div class=\"quote carousel-item bg-sand  px-5 py-7 p-md-9 rounded-xl shadow-lg d-flex flex-column m-0 h-100\" data-theme=\"light\">\r\n\r\n                                            <div class=\"row g-5 g-md-6 g-lg-7\">\r\n                                                <div class=\"col-12 col-lg-6 gap-4 gap-md-5 d-flex flex-column\">\r\n                                                                                                            <div class=\"quote-logo\">\r\n                                                                                                                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/hsbc.svg\" alt=\"Logotipo del testimonio de \">\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                                                                            <div>\r\n                                                                                                                                                                                                <h2 class=\"fw-bold h5\">Banca de confianza entregada a trav\u00e9s de miles de millones de mensajes<\/h2>\r\n                                                                                                                            \r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                    \r\n                                                                                                            <div class=\"overflow-hidden\">\r\n                                                            <div class=\"row g-3\">\r\n                                                                \r\n                                                                    <div class=\"col-12 col-md-6\">\r\n                                                                                            <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                            \r\n                                                        <div class=\"card-title text-accent mb-0 h3\"\r\n                                                                >\r\n                                +100 M                            <\/div>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    mensajes enviados al mes                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                                            <\/div>\r\n\r\n                                                                \r\n                                                                    <div class=\"col-12 col-md-6\">\r\n                                                                                            <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                            \r\n                                                        <div class=\"card-title text-accent mb-0 h3\"\r\n                                                                >\r\n                                +10                            <\/div>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    a\u00f1os de asociaci\u00f3n con Sinch                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                                                                            <\/div>\r\n\r\n                                                                                                                            <\/div>\r\n                                                        <\/div>\r\n                                                    \r\n                                                    \r\n\r\n                                                                                                            <div class=\"quote-link\">\r\n                                                            <a href=\"https:\/\/sinch.com\/customer-stories\/hsbc\/\"  class=\"btn-arrow fs-sm \" >Lee el testimonio del cliente<\/a>\r\n                                                        <\/div>\r\n                                                    \r\n                                                <\/div>\r\n\r\n                                                \r\n                                                    <div class=\"col-12 col-lg-6 text-end\">\r\n\r\n                                                        \r\n                                                            <img decoding=\"async\" width=\"1056\" height=\"720\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Photo-HSBC-Customer-Story-Cover.png\" class=\"img-fluid rounded w-100\" alt=\"Imagen para Banca de confianza entregada a trav\u00e9s de miles de millones de mensajes\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 528px, (min-resolution: 2dppx) and (min-width: 1200px) 528px, (min-width: 1200px) 1056px, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Photo-HSBC-Customer-Story-Cover.png 1056w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Photo-HSBC-Customer-Story-Cover-300x205.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Photo-HSBC-Customer-Story-Cover-1024x698.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Photo-HSBC-Customer-Story-Cover-768x524.png 768w\" \/>\r\n                                                        \r\n                                                        \r\n                                                    <\/div>\r\n\r\n                                                                                            <\/div>\r\n\r\n                                        <\/div>\r\n\r\n                                    <\/div>\r\n                                                                    <div class=\"col-12\" data-carousel-slide=\"1\">\r\n                                        <div class=\"quote carousel-item bg-sand  px-5 py-7 p-md-9 rounded-xl shadow-lg d-flex flex-column m-0 h-100\" data-theme=\"light\">\r\n\r\n                                            <div class=\"row g-5 g-md-6 g-lg-7\">\r\n                                                <div class=\"col-12 col-lg-6 gap-4 gap-md-5 d-flex flex-column\">\r\n                                                                                                            <div class=\"quote-logo\">\r\n                                                                                                                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/08\/nationwide.svg\" alt=\"Logotipo del testimonio de Simon Dixon\">\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                                                                            <div>\r\n                                                            \r\n                                                                                                                            <blockquote class=\"m-0 quote-content text-body-color\" id=\"quote-block-a0450983d89c0857234643c81f33bd04-1\">\r\n                                                                    \u201cSinch entendi\u00f3 r\u00e1pidamente nuestros valores y la filosof\u00eda de Nationwide. Tenemos una relaci\u00f3n abierta, honesta y de confianza sobre la cual construir.\u201c                                                                <\/blockquote>\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                    \r\n                                                    \r\n                                                                                                            <div class=\"mt-auto\">\r\n                                                            <div class=\"d-flex gap-3\">\r\n                                                                \r\n                                                                                                                                    <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                                                                        <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-a0450983d89c0857234643c81f33bd04-1\">\r\n                                                                            Simon Dixon                                                                        <\/cite>\r\n\r\n                                                                                                                                                    <span class=\"mb-0 text-body-color\">Gestor de la demanda en comunicaci\u00f3n, entrega y log\u00edstica de Nationwide<\/span>\r\n                                                                                                                                            <\/div>\r\n                                                                                                                            <\/div>\r\n                                                        <\/div>\r\n\r\n                                                    \r\n\r\n                                                                                                            <div class=\"quote-link\">\r\n                                                            <a href=\"https:\/\/sinch.com\/messaging\/customer-stories\/nationwide-building-society\/\"  class=\"btn-arrow fs-sm \" >Lee el testimonio del cliente<\/a>\r\n                                                        <\/div>\r\n                                                    \r\n                                                <\/div>\r\n\r\n                                                \r\n                                                    <div class=\"col-12 col-lg-6 text-end\">\r\n\r\n                                                        \r\n                                                            <img decoding=\"async\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Nationwide-customer-story-cover.svg\" class=\"img-fluid rounded w-100\" alt=\"Image for Testimonial\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 528px, (min-resolution: 2dppx) and (min-width: 1200px) 528px, (min-width: 1200px) 1056px, 100vw\" \/>\r\n                                                        \r\n                                                        \r\n                                                    <\/div>\r\n\r\n                                                                                            <\/div>\r\n\r\n                                        <\/div>\r\n\r\n                                    <\/div>\r\n                                                                    <div class=\"col-12\" data-carousel-slide=\"2\">\r\n                                        <div class=\"quote carousel-item bg-sand  px-5 py-7 p-md-9 rounded-xl shadow-lg d-flex flex-column m-0 h-100\" data-theme=\"light\">\r\n\r\n                                            <div class=\"row g-5 g-md-6 g-lg-7\">\r\n                                                <div class=\"col-12 col-lg-6 gap-4 gap-md-5 d-flex flex-column\">\r\n                                                                                                            <div class=\"quote-logo\">\r\n                                                                                                                            <img decoding=\"async\" class=\"quote-logo\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/Avtal.png\" alt=\"Logotipo del testimonio de Khaled Bittar\">\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                                                                            <div>\r\n                                                                                                                                                                                                <h2 class=\"fw-bold h5\">C\u00f3mo Avtal aument\u00f3 las tasas de recuperaci\u00f3n en m\u00e1s de un 50 % con SMS y email<\/h2>\r\n                                                                                                                            \r\n                                                                                                                            <blockquote class=\"m-0 quote-content text-body-color\" id=\"quote-block-a0450983d89c0857234643c81f33bd04-2\">\r\n                                                                    \u00abLa tecnolog\u00eda de Sinch est\u00e1 muy bien desarrollada, y hay un mont\u00f3n de documentaci\u00f3n que hace que resulte f\u00e1cil para nuestro equipo de ingenieros.  Y en cuanto a la asistencia, recibimos respuestas incre\u00edblemente r\u00e1pidas\u00bb.                                                                <\/blockquote>\r\n                                                                                                                    <\/div>\r\n                                                    \r\n                                                    \r\n                                                    \r\n                                                                                                            <div class=\"mt-auto\">\r\n                                                            <div class=\"d-flex gap-3\">\r\n                                                                \r\n                                                                                                                                    <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                                                                        <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-a0450983d89c0857234643c81f33bd04-2\">\r\n                                                                            Khaled Bittar                                                                        <\/cite>\r\n\r\n                                                                                                                                                    <span class=\"mb-0 text-body-color\">Director ejecutivo (CEO) de Avtal<\/span>\r\n                                                                                                                                            <\/div>\r\n                                                                                                                            <\/div>\r\n                                                        <\/div>\r\n\r\n                                                    \r\n\r\n                                                                                                            <div class=\"quote-link\">\r\n                                                            <a href=\"https:\/\/sinch.com\/messaging\/customer-stories\/avtal\/\"  class=\"btn-arrow fs-sm \" >Lee el testimonio del cliente<\/a>\r\n                                                        <\/div>\r\n                                                    \r\n                                                <\/div>\r\n\r\n                                                \r\n                                                    <div class=\"col-12 col-lg-6 text-end\">\r\n\r\n                                                        \r\n                                                                            <a href=\"https:\/\/www.youtube.com\/watch?v=cgsUlfAlDgE\" class=\"d-block border-0 p-0 rounded-lg overflow-hidden bg-transparent position-relative lazy-video-link\" data-modal-video=\"cgsUlfAlDgE\" target=\"_blank\" rel=\"nofollow\" role=\"button\" data-source=\"youtube\" data-language=\"es\" type=\"button\" data-cursor-helper=\"Play\" data-cursor-helper-icon=\"play\">\r\n                                    <img decoding=\"async\" class=\"img-fluid w-100\" src=\"https:\/\/img.youtube.com\/vi\/cgsUlfAlDgE\/maxresdefault.jpg\" alt=\"How Avtal increased recovery rates by 50% with SMS and email\">\r\n                \r\n                <div class=\"btn btn-light btn-light-social btn-play btn-play-square\">\r\n                    <svg width=\"32\" height=\"32\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/play.svg\"><\/svg>\r\n                <\/div>\r\n            <\/a>\r\n                        <script type=\"application\/ld+json\">\r\n            {\n    \"@context\": \"http:\/\/schema.org\",\n    \"@type\": \"VideoObject\",\n    \"@id\": \"https:\/\/www.youtube.com\/watch?v=cgsUlfAlDgE#VideoObject\",\n    \"thumbnailUrl\": \"https:\/\/img.youtube.com\/vi\/cgsUlfAlDgE\/maxresdefault.jpg\",\n    \"embedUrl\": \"https:\/\/www.youtube.com\/embed\/cgsUlfAlDgE\",\n    \"contentUrl\": \"https:\/\/www.youtube.com\/watch?v=cgsUlfAlDgE\",\n    \"name\": \"How Avtal increased recovery rates by 50% with SMS and email\",\n    \"description\": \"See how Avtal, a platform for collecting on delinquent accounts, partnered with Sinch to increase recovery rates by up to 70%. By replacing traditional phone calls and mail with a consumer-friendly messaging strategy, Avtal is transforming the collections experience for both creditors and their customers.\\n\\nThis story shows how CEO Khaled Bittar and his team used Sinch\\u2019s compliant, direct-to-carrier messaging platform to empower consumers. By providing a simple payment portal accessible via SMS, Avtal gives customers a private, easy-to-use way to resolve their accounts on their own terms.\\n\\nKey Takeaways:\\n- How Avtal increased account recovery rates by 50-70% by giving consumers a simple, digital way to pay.\\n- Why personalized strategy and support from a dedicated Sinch Customer Success Manager makes all the difference.\\n- How a text-based, self-service portal provides a better customer experience and outperforms traditional collection methods.\\n- How Sinch\\u2019s compliance expertise and direct-to-carrier platform provide the trust and reliability needed in financial services.\\n\\nAbout Avtal: \\nAvtal provides a modern platform for agencies and creditors to manage and collect on delinquent accounts. By focusing on consumer-preferred digital channels like email and text, Avtal facilitates a simpler, more effective, and user-friendly account resolution process.\",\n    \"uploadDate\": \"2025-11-07T14:15:56+00:00\",\n    \"duration\": \"PT3M29S\"\n}        <\/script>\r\n        \r\n                                                        \r\n                                                    <\/div>\r\n\r\n                                                                                            <\/div>\r\n\r\n                                        <\/div>\r\n\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                                    <div class=\"\">\r\n                        <div class=\"container d-flex justify-content-center\">\r\n                                    <div class=\"d-flex gap-4\">\r\n            <button data-carousel-role=\"prev\" data-carousel-nav=\"block-a0450983d89c0857234643c81f33bd04\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Diapositiva anterior\">\r\n                <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-left.svg\"><\/svg>\r\n            <\/button>\r\n            <button data-carousel-role=\"next\" data-carousel-nav=\"block-a0450983d89c0857234643c81f33bd04\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Siguiente diapositiva\">\r\n                <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n            <\/button>\r\n        <\/div>\r\n                                <\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n        <\/section>\r\n    \n\n\r\n    <section data-content-type=\"component\" id=\"block-fa92482d4e27f1b97fbbf465f5e07219\" class=\"section section-altblo section-py bg-body\" data-theme=\"dark\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Opera comunicaciones en las que tus clientes <b class=\"text-highlight\">confiar\u00e1n<\/b><\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Mant\u00e9n tu reputaci\u00f3n impecable en cada canal principal. Combinamos herramientas de inteligencia con expertos que saben exactamente c\u00f3mo optimizar tu configuraci\u00f3n, independientemente del canal que utilices.<\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p class=\"mb-0\">Haz upgrade a la mensajer\u00eda moderna como RCS y WhatsApp, con el respaldo de la conmutaci\u00f3n por error autom\u00e1tica a SMS para que nunca pierdas el ritmo.\u00a0\u00a0<\/p><\/li><li><p class=\"mb-0\">Supervisa la salud de tu email con una puntuaci\u00f3n de precisi\u00f3n y la asistencia proactiva de tus gestores t\u00e9cnicos de cuenta dedicados.\u00a0<\/p><\/li><li><p class=\"mb-0\">Elimina los riesgos de suplantaci\u00f3n de identidad con llamadas de voz en la aplicaci\u00f3n verificadas y branded.\u00a0\u00a0<\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 pe-md-7 pe-lg-10\">\r\n\r\n                    <img decoding=\"async\" width=\"920\" height=\"561\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-1.png\" class=\"img-fluid\" alt=\"Imagen para Opera comunicaciones en las que tus clientes confiar\u00e1n\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-1.png 1840w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-1-300x183.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-1-1024x624.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-1-768x468.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-1-1536x937.png 1536w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-f739076c60b1abdd804a1390392b01cf\" class=\"section section-altblo section-py bg-body\" data-theme=\"dark\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5 order-md-1\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Deja de luchar con tu tecnolog\u00eda. <b class=\"text-highlight\">Empieza a acelerar.  <\/b><\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Cambia tus sistemas fragmentados y parcheados por una plataforma optimizada que permita a tu equipo moverse r\u00e1pido y liderar la carga digital.  <\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p class=\"mb-0\">Gestiona todo en un solo lugar: controla todos tus canales, anal\u00edticas y configuraciones desde un \u00fanico panel de control unificado. <\/p><\/li><li><p class=\"mb-0\">Simplifica tus operaciones: gestiona el acceso de tu equipo, verifica el estado del sistema y obt\u00e9n asistencia de expertos desde un centro \u00fanico.  <\/p><\/li><li><p class=\"mb-0\">Agiliza tus auditor\u00edas: as\u00f3ciate con un \u00fanico proveedor que cotiza en bolsa y que ha sido rentable desde el primer d\u00eda.  <\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 order-md-2 ps-md-7 ps-lg-10 text-md-end\">\r\n\r\n                    <img decoding=\"async\" width=\"920\" height=\"568\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-2.png\" class=\"img-fluid\" alt=\"Imagen para Deja de luchar con tu tecnolog\u00eda. Empieza a acelerar.\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-2.png 1840w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-2-300x185.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-2-1024x632.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-2-768x474.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-2-1536x948.png 1536w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-ec3661907f1638405fba04bd05211fbe\" class=\"section section-altblo section-py bg-body\" data-theme=\"dark\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Incorpora se\u00f1ales sofisticadas para <b class=\"text-highlight\">identificar a los defraudadores<\/b><\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Con la inteligencia de n\u00fameros en tiempo real, te ayudamos a detener a los malos en un segundo plano. Protege a tus clientes y tus resultados del intercambio de SIM, el inflado de tr\u00e1fico y las cuentas falsas.  <\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p class=\"mb-0\">Detecta los intercambios de SIM y las cuentas comprometidas antes de que los defraudadores puedan iniciar sesi\u00f3n.<\/p><\/li><li><p class=\"mb-0\">Bloquea la Inflaci\u00f3n Artificial de Tr\u00e1fico (IAT) y otras estafas costosas.<\/p><\/li><li><p class=\"mb-0\">Verifica a los usuarios silenciosamente en segundo plano, manteni\u00e9ndolos seguros sin arruinar su experiencia.<\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 pe-md-7 pe-lg-10\">\r\n\r\n                    <img decoding=\"async\" width=\"920\" height=\"640\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-3.png\" class=\"img-fluid\" alt=\"Imagen para Incorpora se\u00f1ales sofisticadas para identificar a los defraudadores\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-3.png 1840w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-3-300x209.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-3-1024x712.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-3-768x534.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-3-1536x1069.png 1536w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-5e23290fb32b632cdfd1b9465a5d4275\" class=\"section section-altblo section-py bg-body\" data-theme=\"dark\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 order-2 col-md-6 col-lg-5 order-md-1\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Un alcance global con el que puedes <b class=\"text-highlight\">contar\u00a0<\/b><\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Infraestructura de nivel empresarial, cobertura masiva de canales y herramientas avanzadas. Te brindamos la escala que necesitas para crecer en cualquier lugar.    <\/p><\/div>\r\n                            \r\n                            <ul class=\"list-styled-check m-0 text-body-color\"><li><p class=\"mb-0\">Llega a cualquier persona, en cualquier lugar, a trav\u00e9s de voz, mensajer\u00eda, email y mucho m\u00e1s.  <\/p><\/li><li><p class=\"mb-0\">Conf\u00eda en SLA con un tiempo de actividad del 99,95 % y mecanismos inteligentes de conmutaci\u00f3n por error que garantizan la entrega.    <\/p><\/li><li><p class=\"mb-0\">As\u00f3ciate con un l\u00edder reconocido por Gartner, IDC y Omdia.   <\/p><\/li><\/ul>\r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 order-1 col-md-6 col-lg-7 mb-5 mb-md-0 order-md-2 ps-md-7 ps-lg-10 text-md-end\">\r\n\r\n                    <img decoding=\"async\" width=\"920\" height=\"860\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-4.png\" class=\"img-fluid\" alt=\"Imagen para Un alcance global con el que puedes contar\u00a0\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-4.png 1840w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-4-300x280.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-4-1024x957.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-4-768x718.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-financial-services-Value-prop-image-4-1536x1436.png 1536w\" \/>\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\" id=\"block-8629c1095c55e0ef98f132d283180827\" class=\"section section-altblo section-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center \">\r\n                                    <div class=\"col-12 col-md-6 col-lg-5\">\r\n                        <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                    <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Todos los canales que necesitas, en un solo lugar<\/h2>\r\n                    <\/div>\r\n\r\n\r\n                                                            <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Simplifica tus recursos, unifica a tu equipo y ofrece una experiencia fluida en todo el recorrido del cliente. <\/p><\/div>\r\n                            \r\n                            \r\n                            \r\n                            \r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-12 col-md-6 col-lg-7 mt-5 mt-md-0 ps-md-7 ps-lg-10\">\r\n\r\n                                            \n            <div class=\"loop px-lg-4 marquee marquee-down marquee-gradient-bilateral\">\r\n            <div class=\"marquee-track\">\r\n                                    \r\n                                                    <a href=\"https:\/\/sinch.com\/products\/mailgun-send\/?utm_source=sinch\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/email.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Email<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/sms\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-text.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">SMS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/rcs\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-stack-audio-video.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">RCS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/whatsapp\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/whatsapp.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">WhatsApp<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/voice\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/phone-call.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Voz de red<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/voice\/programmable-voice\/in-app-calling\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/phone-badge-call.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Voz en la aplicaci\u00f3n<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/messaging\/conversation-api\/mobile-push-notifications\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/phone-bell.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Push en la aplicaci\u00f3n<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/sinch-chat\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/laptop-chat.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Chat en directo<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                                                        \r\n                                                    <a href=\"https:\/\/sinch.com\/products\/mailgun-send\/?utm_source=sinch\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/email.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Email<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/sms\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-text.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">SMS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/rcs\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/chat-stack-audio-video.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">RCS<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/whatsapp\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/whatsapp.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">WhatsApp<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/voice\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/phone-call.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Voz de red<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/voice\/programmable-voice\/in-app-calling\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/phone-badge-call.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Voz en la aplicaci\u00f3n<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/messaging\/conversation-api\/mobile-push-notifications\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/phone-bell.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Push en la aplicaci\u00f3n<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                    \r\n                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/sinch-chat\/\" target=\"_blank\" class=\"marquee-item border border-light rounded d-block btn btn-light text-start mb-3 px-4 px-md-5 py-3 py-md-4 \" >\r\n                                                        <span class=\"d-flex align-items-center gap-3 gap-md-4\">\r\n                            <svg width=\"48\" height=\"48\" class=\"loop-icon\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/laptop-chat.svg\"><\/svg>\r\n                            <span class=\"h5 m-0 text-accent fw-bold\">Chat en directo<\/span>\r\n                        <\/span>\r\n\r\n                                                    <\/a>\r\n                        \r\n                                                <\/div>\r\n        <\/div>\r\n\r\n\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \r\n            \r\n                    <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\"  id=\"form\" class=\"section section-py form-block bg-primary\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row justify-content-center\">\r\n                <div class=\"col-12 col-lg-8 justify-content-center\">\r\n\r\n                    <div class=\"\">\r\n\r\n\r\n                        <div class=\"form-block-container shadow-lg bg-body px-5 py-7 p-md-9\" data-theme=\"light\">\r\n\r\n                            \r\n\r\n                                <!-- MARKETING CLOUD Form Container -- Start -->\r\n                                <div class=\"marketing-cloud-form-container\">\r\n                                                                            <div class=\"form-content mb-3\">\r\n                                                                                            <h2 class=\"h5 mb-3\">\u00bfQuieres m\u00e1s informaci\u00f3n? Hablemos.<\/h2>\r\n                                                                                                                                <\/div>\r\n\r\n                                    \r\n\r\n                                    \r\n                                    <iframe\r\n                                        id=\"marketing-cloud-form\"\r\n                                        class=\"marketing-cloud-iframe\"\r\n                                        data-iframe-params=\"utm_source,utm_medium,utm_campaign,utm_term,utm_content,transid,gclid,intcmp,msclkid\"\r\n                                        src=\"https:\/\/cloud.m.sinch.com\/sinchform1_0?referrer=https%3A%2F%2Fsinch.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Findustries%2F174274&#038;lang=es&#038;theme=sinch.com\"\r\n                                        title=\"\u00bfQuieres m\u00e1s informaci\u00f3n? Hablemos.\"\r\n                                        style=\"width: 100%;\">\r\n                                    <\/iframe>\r\n                                <\/div>\r\n                                <!-- MARKETING CLOUD Container -- Start -->\r\n\r\n\r\n                                                    <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n\r\n    <section data-content-type=\"component\"  class=\"section section-py bg-light\" data-theme=\"light\">\r\n        <div class=\"position-relative overflow-hidden resources-cards-wrap\">\r\n            <div class=\"position-relative resources-cards\">\r\n                                    <div class=\"container\">\r\n                        <div class=\"d-flex flex-column flex-md-row align-items-start justify-content-between gap-6 gap-md-7 gap-lg-9\">\r\n                            <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                        <div>\r\n            \r\n                            <h2 class=\"mb-0 h3\">Contenido relacionado<\/h2>\r\n                    <\/div>\r\n\r\n                                                            <\/div>\r\n                                                            <div class=\"d-lg-none\">\r\n                                        <div class=\"d-flex gap-4\">\r\n        <button data-carousel-role=\"prev\" data-carousel-nav=\"block-cdbfe94e6ec688c986a1f22f1d83d30f\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Diapositiva anterior\">\r\n            <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-left.svg\"><\/svg>\r\n        <\/button>\r\n        <button data-carousel-role=\"next\" data-carousel-nav=\"block-cdbfe94e6ec688c986a1f22f1d83d30f\" class=\"btn btn-neutral btn-lg btn-icon\" aria-label=\"Siguiente diapositiva\">\r\n            <svg width=\"24\" height=\"24\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/layout\/chevron-right.svg\"><\/svg>\r\n        <\/button>\r\n    <\/div>\r\n                                    <\/div>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                                <div class=\"w-100 mt-6 mt-md-7 mt-lg-9\">\r\n                    <div class=\"carousel\" data-carousel=\"block-cdbfe94e6ec688c986a1f22f1d83d30f\" data-carousel-active-index=\"0\" data-carousel-dragable=\"false\">\r\n                        <div class=\"container\">\r\n                            <div class=\"carousel__track carouselTrack\" data-transition=\"true\">\r\n                                <div class=\"row position-relative flex-nowrap\">\r\n                                    \r\n                                            <article class=\"resoureces-cards__slide col-12 col-md-6 col-lg-4\" data-carousel-slide=\"0\">\r\n                                                                                                                    <a href=\"https:\/\/sinch.com\/es\/blog\/rcs-banca-servicios-financieros\/\" class=\"card-link text-decoration-none \" title=\"RCS en la banca: El siguiente paso en la experiencia digital del cliente\">\r\n                        <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"1400\" height=\"868\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/11\/SI-Blog-RCS-FinServ-Hero-3.png\" class=\"rounded-0\" alt=\"Imagen para RCS en la banca: El siguiente paso en la experiencia digital del cliente\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/11\/SI-Blog-RCS-FinServ-Hero-3.png 1400w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/11\/SI-Blog-RCS-FinServ-Hero-3-300x186.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/11\/SI-Blog-RCS-FinServ-Hero-3-1024x635.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/11\/SI-Blog-RCS-FinServ-Hero-3-768x476.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/11\/SI-Blog-RCS-FinServ-Hero-3-1208x748.png 1208w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/11\/SI-Blog-RCS-FinServ-Hero-3-784x486.png 784w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                            \r\n                                                            <div class=\"fs-xs d-flex gap-2 pb-2\">\r\n                                                                            <span class=\"d-flex gap-2\">\r\n                                                                                            <svg class=\"text-accent\" aria-hidden=\"true\" width=\"20\" height=\"20\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/document-image.svg\"><\/svg>\r\n                                                                                        <span class=\"card-category-text\"><span class=\"text-capitalize\">Consejos<\/span>, <span class=\"text-capitalize\">Productos<\/span><\/span>\r\n                                        <\/span>\r\n                                                                                                                                            <\/div>\r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h5\"\r\n                                data-title-clamp='true'                                >\r\n                                RCS en la banca: El siguiente paso en la experiencia digital del cliente                            <\/h3>\r\n                                                                                <\/div>\r\n                                                    <address class=\"text-start d-flex align-items-center gap-3 m-0\">\r\n                                                                    <img decoding=\"async\" class=\"img-cover rounded\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/03\/Megan-Libby.png\" width=\"40\" height=\"40\" alt=\"Foto de Megan Libby\">\r\n                                                                <span class=\"fs-xs\">Megan Libby<\/span>\r\n                            <\/address>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n                        <\/a>\r\n        \r\n                                                    <\/article>\r\n                                            \r\n                                            <article class=\"resoureces-cards__slide col-12 col-md-6 col-lg-4\" data-carousel-slide=\"1\">\r\n                                                                                                                    <a href=\"https:\/\/sinch.com\/es\/blog\/plugin-de-sinch-para-cursor-sms-voz-y-verificacion\/\" class=\"card-link text-decoration-none \" title=\"Crea funciones de SMS, voz y verificaci\u00f3n sin salir de Cursor\u00a0\">\r\n                        <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"1920\" height=\"1080\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/Sinch-plugin-for-Cursor-integration-preview.png\" class=\"rounded-0\" alt=\"Imagen para Crea funciones de SMS, voz y verificaci\u00f3n sin salir de Cursor\u00a0\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/Sinch-plugin-for-Cursor-integration-preview.png 1920w, https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/Sinch-plugin-for-Cursor-integration-preview-300x169.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/Sinch-plugin-for-Cursor-integration-preview-1024x576.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/Sinch-plugin-for-Cursor-integration-preview-768x432.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/Sinch-plugin-for-Cursor-integration-preview-1536x864.png 1536w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                            \r\n                                                            <div class=\"fs-xs d-flex gap-2 pb-2\">\r\n                                                                            <span class=\"d-flex gap-2\">\r\n                                                                                            <svg class=\"text-accent\" aria-hidden=\"true\" width=\"20\" height=\"20\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/document-image.svg\"><\/svg>\r\n                                                                                        <span class=\"card-category-text\"><span class=\"text-capitalize\">Desarrolladores<\/span><\/span>\r\n                                        <\/span>\r\n                                                                                                                                            <\/div>\r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h5\"\r\n                                data-title-clamp='true'                                >\r\n                                Crea funciones de SMS, voz y verificaci\u00f3n sin salir de Cursor\u00a0                            <\/h3>\r\n                                                                                <\/div>\r\n                                                    <address class=\"text-start d-flex align-items-center gap-3 m-0\">\r\n                                                                    <img decoding=\"async\" class=\"img-cover rounded\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2026\/03\/author-icon-sinch.png\" width=\"40\" height=\"40\" alt=\"Foto de The Sinch team\">\r\n                                                                <span class=\"fs-xs\">The Sinch team<\/span>\r\n                            <\/address>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n                        <\/a>\r\n        \r\n                                                    <\/article>\r\n                                            \r\n                                            <article class=\"resoureces-cards__slide col-12 col-md-6 col-lg-4\" data-carousel-slide=\"2\">\r\n                                                                                                                    <a href=\"https:\/\/sinch.com\/es\/blog\/capacidades-criticas-cpaas-gartner-2026\/\" class=\"card-link text-decoration-none \" title=\"El informe Critical Capabilities\u2122 de Gartner\u00ae de 2026 para CPaaS ya est\u00e1 disponible: lo que significa para los l\u00edderes empresariales\">\r\n                        <div class=\"card h-100 bg-transparent d-flex flex-column\">\r\n                                                            <div class=\"card-image-zoom ratio-16x9 rounded-lg\">\r\n\r\n                            \r\n                            \r\n                            <img width=\"1296\" height=\"800\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/SI_Gartner_2026_Blog-Post_Header-Image.png\" class=\"rounded-0\" alt=\"Imagen para El informe Critical Capabilities\u2122 de Gartner\u00ae de 2026 para CPaaS ya est\u00e1 disponible: lo que significa para los l\u00edderes empresariales\" decoding=\"async\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 400px, (min-resolution: 2dppx) and (min-width: 1200px) 400px, (min-width: 1200px) 800px, (min-width: 768px) 50vw, 100vw\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/SI_Gartner_2026_Blog-Post_Header-Image.png 1296w, https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/SI_Gartner_2026_Blog-Post_Header-Image-300x185.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/SI_Gartner_2026_Blog-Post_Header-Image-1024x632.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2026\/06\/SI_Gartner_2026_Blog-Post_Header-Image-768x474.png 768w\" \/>                        <\/div>\r\n                                                                            <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                            \r\n                                                            <div class=\"fs-xs d-flex gap-2 pb-2\">\r\n                                                                            <span class=\"d-flex gap-2\">\r\n                                                                                            <svg class=\"text-accent\" aria-hidden=\"true\" width=\"20\" height=\"20\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/document-image.svg\"><\/svg>\r\n                                                                                        <span class=\"card-category-text\"><span class=\"text-capitalize\">Empresa<\/span><\/span>\r\n                                        <\/span>\r\n                                                                                                                                            <\/div>\r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h5\"\r\n                                data-title-clamp='true'                                >\r\n                                El informe Critical Capabilities\u2122 de Gartner\u00ae de 2026 para CPaaS ya est\u00e1 disponible: lo que significa para los l\u00edderes empresariales                            <\/h3>\r\n                                                                                <\/div>\r\n                                                    <address class=\"text-start d-flex align-items-center gap-3 m-0\">\r\n                                                                    <img decoding=\"async\" class=\"img-cover rounded\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2026\/03\/Glafira-Bunja.jpg\" width=\"40\" height=\"40\" alt=\"Foto de Glafira Bunja\">\r\n                                                                <span class=\"fs-xs\">Glafira Bunja<\/span>\r\n                            <\/address>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n                        <\/a>\r\n        \r\n                                                    <\/article>\r\n                                            \r\n                                    \r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n    \r\n","protected":false},"author":1,"featured_media":191417,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-174274","industries","type-industries","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>servicios financieros<\/title>\n<meta name=\"description\" content=\"Crea experiencias del cliente fiables, escalables y en cumplimiento con la normativa en una plataforma dise\u00f1ada para los servicios financieros modernos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"servicios financieros\" \/>\n<meta property=\"og:description\" content=\"Crea experiencias del cliente fiables, escalables y en cumplimiento con la normativa en una plataforma dise\u00f1ada para los servicios financieros modernos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wearesinch\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T02:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-link-preview-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WeAreSinch\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/servicios-financieros\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/servicios-financieros\\\/\",\"name\":\"servicios financieros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/servicios-financieros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/servicios-financieros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SI-Financial-services-link-preview-image.png\",\"datePublished\":\"2025-12-12T21:43:23+00:00\",\"dateModified\":\"2026-07-08T02:43:56+00:00\",\"description\":\"Crea experiencias del cliente fiables, escalables y en cumplimiento con la normativa en una plataforma dise\u00f1ada para los servicios financieros modernos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/servicios-financieros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/servicios-financieros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/servicios-financieros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SI-Financial-services-link-preview-image.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SI-Financial-services-link-preview-image.png\",\"width\":2400,\"height\":1264},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/servicios-financieros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinch.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industries\",\"item\":\"https:\\\/\\\/sinch.com\\\/es\\\/sectores\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"servicios financieros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/\",\"name\":\"Sinch\",\"description\":\"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinch.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#organization\",\"name\":\"Sinch\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"width\":800,\"height\":496,\"caption\":\"Sinch\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wearesinch\\\/\",\"https:\\\/\\\/x.com\\\/WeAreSinch\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sinch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZZ2u_B2afTxA0v-xcgfsaw\",\"https:\\\/\\\/www.instagram.com\\\/wearesinch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"servicios financieros","description":"Crea experiencias del cliente fiables, escalables y en cumplimiento con la normativa en una plataforma dise\u00f1ada para los servicios financieros modernos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/","og_locale":"es_ES","og_type":"article","og_title":"servicios financieros","og_description":"Crea experiencias del cliente fiables, escalables y en cumplimiento con la normativa en una plataforma dise\u00f1ada para los servicios financieros modernos.","og_url":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/","og_site_name":"Sinch","article_publisher":"https:\/\/www.facebook.com\/wearesinch\/","article_modified_time":"2026-07-08T02:43:56+00:00","og_image":[{"width":2400,"height":1264,"url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-link-preview-image.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@WeAreSinch","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/","url":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/","name":"servicios financieros","isPartOf":{"@id":"https:\/\/sinch.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/#primaryimage"},"image":{"@id":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/#primaryimage"},"thumbnailUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-link-preview-image.png","datePublished":"2025-12-12T21:43:23+00:00","dateModified":"2026-07-08T02:43:56+00:00","description":"Crea experiencias del cliente fiables, escalables y en cumplimiento con la normativa en una plataforma dise\u00f1ada para los servicios financieros modernos.","breadcrumb":{"@id":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/#primaryimage","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-link-preview-image.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/07\/SI-Financial-services-link-preview-image.png","width":2400,"height":1264},{"@type":"BreadcrumbList","@id":"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinch.com\/es\/"},{"@type":"ListItem","position":2,"name":"Industries","item":"https:\/\/sinch.com\/es\/sectores\/"},{"@type":"ListItem","position":3,"name":"servicios financieros"}]},{"@type":"WebSite","@id":"https:\/\/sinch.com\/es\/#website","url":"https:\/\/sinch.com\/es\/","name":"Sinch","description":"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch","publisher":{"@id":"https:\/\/sinch.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinch.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sinch.com\/es\/#organization","name":"Sinch","url":"https:\/\/sinch.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sinch.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","width":800,"height":496,"caption":"Sinch"},"image":{"@id":"https:\/\/sinch.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wearesinch\/","https:\/\/x.com\/WeAreSinch","https:\/\/www.linkedin.com\/company\/sinch","https:\/\/www.youtube.com\/channel\/UCZZ2u_B2afTxA0v-xcgfsaw","https:\/\/www.instagram.com\/wearesinch\/"]}]}},"_links":{"self":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/industries\/174274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/industries"}],"about":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/types\/industries"}],"author":[{"embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/industries\/174274\/revisions"}],"predecessor-version":[{"id":193097,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/industries\/174274\/revisions\/193097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/media\/191417"}],"wp:attachment":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/media?parent=174274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}