{"id":163425,"date":"2025-06-30T07:46:00","date_gmt":"2025-06-30T07:46:00","guid":{"rendered":"https:\/\/sinch.com\/?post_type=blog&#038;p=163425"},"modified":"2026-06-30T12:28:05","modified_gmt":"2026-06-30T12:28:05","slug":"voz-bancos-servicios-financieros","status":"publish","type":"blog","link":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/","title":{"rendered":"Los clientes quieren un servicio seguro y personal y los bancos tienen dificultades para prestarlo: \u00bfPuede ayudar la voz?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si trabajas en el sector de los servicios financieros, la comunicaci\u00f3n con los clientes puede parecerte un poco un callej\u00f3n sin salida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como revela nuestro <a href=\"https:\/\/sinch.com\/es\/state-of-customer-communications\/\">Informe de 2025 <em>El estado de las comunicaciones con los clientes<\/em><\/a>, la mayor\u00eda de los consumidores esperan de sus instituciones financieras no solo una experiencia de usuario muy segura, sino tambi\u00e9n muy personalizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo, los l\u00edderes de empresas financieras nos dijeron que satisfacer las necesidades de personalizaci\u00f3n de los clientes y, al mismo tiempo, garantizar unas comunicaciones seguras y conformes con la normativa, son exactamente los dos mayores retos para su sector en estos momentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto parece un dilema irresoluble, pero no tiene por qu\u00e9 serlo. Como tambi\u00e9n muestran nuestros datos, aglutinar tus recursos tecnol\u00f3gicos en torno a una soluci\u00f3n de voz moderna puede resolver el problema. Exploremos los resultados de la encuesta y veamos c\u00f3mo.<\/p>\n\n\n\r\n    <nav data-content-type=\"longform\" class=\"toc-block longform-spacings px-5 py-6 px-md-6 px-lg-7 py-md-7 bg-light fs-sm rounded-lg\" aria-labelledby=\"toc-title-1398\"><p class=\"h5 m-0\" id=\"toc-title-1398\">\u00cdndice<\/p><div class=\"d-flex mt-3\"><div class=\"w-auto fw-bold text-accent d-flex me-2\">01<\/div><div class=\"d-flex flex-column\"><a class=\"fw-bold scrollme link-body-color text-accent\" href=\"#lo-que-los-clientes-esperan-realmente-de-las-instituciones-financieras-en-2025-y-por-que-a-los-bancos-les-cuesta-mantenerse-al-dia\">Lo que los clientes esperan realmente de las instituciones financieras en 2025 y por qu\u00e9 a los bancos les cuesta mantenerse al d\u00eda<\/a><\/div><\/div><div class=\"d-flex mt-3\"><div class=\"w-auto fw-bold text-accent d-flex me-2\">02<\/div><div class=\"d-flex flex-column\"><a class=\"fw-bold scrollme link-body-color text-accent\" href=\"#la-voz-el-video-y-las-aplicaciones-moviles-destacan-como-los-mejores-canales-para-la-seguridad-del-usuario-y-la-cx-en-la-banca\">La voz, el v\u00eddeo y las aplicaciones m\u00f3viles destacan como los mejores canales para la seguridad del usuario y la CX en la banca<\/a><\/div><\/div><div class=\"d-flex mt-3\"><div class=\"w-auto fw-bold text-accent d-flex me-2\">03<\/div><div class=\"d-flex flex-column\"><a class=\"fw-bold scrollme link-body-color text-accent\" href=\"#anchor_3-formas-de-utilizar-la-voz-en-los-servicios-bancarios\">3 formas de utilizar la voz en los servicios bancarios<\/a><a class=\"scrollme link-body-color\" href=\"#llamadas-personalizadas-para-mantener-informados-a-los-clientes\">Llamadas personalizadas para mantener informados a los clientes<\/a><a class=\"scrollme link-body-color\" href=\"#llamadas-y-chats-de-video-en-la-aplicacion-faciles-de-usar-para-el-cliente\">Llamadas y chats de v\u00eddeo en la aplicaci\u00f3n, f\u00e1ciles de usar para el cliente<\/a><a class=\"scrollme link-body-color\" href=\"#una-comunicacion-segura-en-la-que-tus-clientes-pueden-confiar\">Una comunicaci\u00f3n segura, en la que tus clientes pueden confiar<\/a><\/div><\/div><div class=\"d-flex mt-3\"><div class=\"w-auto fw-bold text-accent d-flex me-2\">04<\/div><div class=\"d-flex flex-column\"><a class=\"fw-bold scrollme link-body-color text-accent\" href=\"#a-futuro-la-voz-no-es-una-alternativa-en-banca-deberia-ser-parte-de-tus-cimientos\">A futuro: La voz no es una alternativa en banca, deber\u00eda ser parte de tus cimientos<\/a><\/div><\/div><\/nav>\n\n\n<h2 class=\"wp-block-heading\">Lo que los clientes esperan realmente de las instituciones financieras en 2025 y por qu\u00e9 a los bancos les cuesta mantenerse al d\u00eda<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que el primer banco de Espa\u00f1a abri\u00f3 sus puertas el 2 de junio de 1782 (el Banco Nacional de San Carlos), la banca en Europa ha experimentado algunos cambios importantes. Muchas operaciones tradicionales, como consultar el saldo de una cuenta, realizar una inversi\u00f3n o transferir dinero, han sido sustituidas por procesos basados en internet, como la banca m\u00f3vil, los monederos digitales y los pagos en l\u00ednea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cambio, otras cosas no han cambiado en absoluto. Despu\u00e9s de m\u00e1s de 200 a\u00f1os, los clientes siguen buscando y queriendo interacciones personales y seguras con sus bancos. Seg\u00fan nuestra encuesta sobre el estado de las comunicaciones con los clientes de 2025, realizada entre m\u00e1s de 2800 consumidores de todo el mundo, la seguridad y la personalizaci\u00f3n son las dos principales expectativas de los clientes.<\/p>\n\n\n\r\n    \r\n        <div class=\"row hub-data longform-spacings\">\r\n\r\n                            <div class=\"col-6 col-lg-6 my-2\">\r\n                    <div class=\"hub-data-item h-100 p-4 p-md-5 rounded-lg bg-primary\" data-theme=\"light\">\r\n                        <div class=\"h3 counter\">83%<\/div>\r\n                        <div class=\"content-body text-body-color\">\r\n                            <p>de los consumidores quieren una personalizaci\u00f3n basada en su situaci\u00f3n financiera<\/p>                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n\r\n                            <div class=\"col-6 col-lg-6 my-2\">\r\n                    <div class=\"hub-data-item h-100 p-4 p-md-5 rounded-lg bg-primary\" data-theme=\"light\">\r\n                        <div class=\"h3 counter\">76%<\/div>\r\n                        <div class=\"content-body text-body-color\">\r\n                            <p class=\"mb-0\">de los consumidores se sienten m\u00e1s seguros cuando las empresas toman medidas adicionales para proteger sus datos personales en l\u00ednea<\/p>                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n\r\n            \r\n        <\/div>\r\n\r\n\n\n\n<p class=\"wp-block-paragraph\">Parece que eso deber\u00eda ser bastante sencillo de cumplir, \u00bfverdad? Pues no del todo. Satisfacer las demandas de los consumidores de una experiencia personalizada en m\u00faltiples canales al tiempo que se garantiza el cumplimiento normativo, la protecci\u00f3n de datos y la seguridad en todos los \u00e1mbitos es, de hecho, un gran reto para el sector de los servicios financieros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando preguntamos a cientos de dirigentes de empresas financieras por sus principales preocupaciones en torno a la comunicaci\u00f3n con los clientes, el 55&nbsp;% de los encuestados dijeron que <strong>la seguridad y la privacidad eran sus principales retos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y cuando se trata de <a href=\"https:\/\/sinch.com\/es\/blog\/experiencia-cliente-personalizada\/\">una experiencia del cliente (CX) verdaderamente personalizada<\/a>, el 32&nbsp;% de los directivos de empresas de servicios financieros tambi\u00e9n admite que la falta de personalizaci\u00f3n es uno de sus principales retos de comunicaci\u00f3n con el cliente. Al mismo tiempo, las instituciones financieras tambi\u00e9n est\u00e1n preocupadas por el cumplimiento normativo y la seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed que, por un lado, las instituciones financieras necesitan recopilar y analizar toneladas de datos de clientes para poder ofrecerles la experiencia personalizada que esperan. Por otra parte, manejan informaci\u00f3n muy sensible que debe tratarse con sumo cuidado para mantener a salvo a sus clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo pueden hacerlo? \u00bfY cu\u00e1l es el mejor canal para ofrecer un intercambio seguro e individualizado? Los clientes tienen una preferencia clara, la interacci\u00f3n con una voz humana.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La voz, el v\u00eddeo y las aplicaciones m\u00f3viles destacan como los mejores canales para la seguridad del usuario y la CX en la banca<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Por muy digital que se haya vuelto la banca <em><a href=\"https:\/\/sinch.com\/es\/estado-comunicaciones-clientes\/capitulo\/informacion-estrategica-sectores\/?utm_content=&#038;utm_term=finserv_voice_article&#038;intcmp=GL-25-Brn_SCC_blog_content\">El estado de las comunicaciones con los clientes<\/a><\/em><a href=\"https:\/\/sinch.com\/es\/estado-comunicaciones-clientes\/capitulo\/informacion-estrategica-sectores\/?utm_content=blog&amp;intcmp=GL_25_SCC\" target=\"_blank\" rel=\"noreferrer noopener\"> de Sinch<\/a> revela que los consumidores siguen prefiriendo las interacciones cara a cara cuando hablan de finanzas personales. Los resultados no sorprenden. Al fin y al cabo, sentarse con un asesor de confianza es exactamente el tipo de experiencia personalizada y segura que buscan los clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfY cuando las reuniones en persona no son posibles? Entonces los consumidores prefieren canales de comunicaci\u00f3n que se acerquen lo m\u00e1s posible a una interacci\u00f3n cara a cara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como muestra nuestra encuesta, cuando se trata de discutir asuntos complejos o importantes y no es posible una conversaci\u00f3n en persona, la gran mayor\u00eda de los clientes (41&nbsp;%) quiere hablar por tel\u00e9fono o mediante videollamada.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"833\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/08\/SDCC-25-Chapter-5-Chart-8_v2-ES-1024x833.png\" alt=\"El gr\u00e1fico muestra que el 41\u00a0% de los consumidores prefieren la voz y el v\u00eddeo para las conversaciones financieras.\" class=\"wp-image-165516\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/08\/SDCC-25-Chapter-5-Chart-8_v2-ES-1024x833.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/08\/SDCC-25-Chapter-5-Chart-8_v2-ES-300x244.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/08\/SDCC-25-Chapter-5-Chart-8_v2-ES-768x625.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/08\/SDCC-25-Chapter-5-Chart-8_v2-ES-1536x1249.png 1536w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/08\/SDCC-25-Chapter-5-Chart-8_v2-ES-2048x1666.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Cuando se trata de discusiones financieras importantes, los clientes quieren hablar con un ser humano.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El mensaje es claro: Cuando se trata de hablar de datos sensibles, en lo que m\u00e1s conf\u00edan los consumidores en en otros humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los clientes tambi\u00e9n tienen preferencias muy claras y quieren saber m\u00e1s de sus bancos sobre amenazas a la seguridad o alertas de fraude. Seg\u00fan nuestra encuesta, el 46&nbsp;% de los consumidores quiere hacer un seguimiento telef\u00f3nico de las notificaciones de alerta de fraude.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"567\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SDCC-25-Chapter-4-Chart-7_v2-ES-1024x567.png\" alt=\"Gr\u00e1fico de anillos: el 46 % prefiere el tel\u00e9fono para alertas de fraude, 20 % texto, 16 % email, 16 % portal de clientes y 2 % otros\" class=\"wp-image-166414\" srcset=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SDCC-25-Chapter-4-Chart-7_v2-ES-1024x567.png 1024w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SDCC-25-Chapter-4-Chart-7_v2-ES-300x166.png 300w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SDCC-25-Chapter-4-Chart-7_v2-ES-768x425.png 768w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SDCC-25-Chapter-4-Chart-7_v2-ES-1536x850.png 1536w, https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SDCC-25-Chapter-4-Chart-7_v2-ES-2048x1133.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Para la mayor\u00eda de los consumidores, hablar por tel\u00e9fono es la forma m\u00e1s segura de hacer el seguimiento de una alerta de fraude.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En un escenario t\u00edpico un cliente recibe un aviso inicial sobre una actividad sospechosa en su cuenta (<a href=\"https:\/\/sinch.com\/customer-stories\/helping-prevent-fraud-with-two-way-sms-nets\/\">quiz\u00e1 por SMS<\/a>). Entonces tendr\u00e1n preguntas: \u00bfSe bloque\u00f3 el pago? \u00bfCu\u00e1les son los siguientes pasos para asegurar mi cuenta? Son estos detalles sensibles los que los clientes quieren discutir en un canal en el que se sienten m\u00e1s seguros: por tel\u00e9fono.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero incluso cuando se trata de preguntas de asistencia general, los chats en directo (22&nbsp;%) y las llamadas telef\u00f3nicas (19&nbsp;%) son los dos canales m\u00e1s populares para los clientes de los bancos, despu\u00e9s del email (31&nbsp;%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mirando m\u00e1s all\u00e1 de la asistencia, el 32&nbsp;% de las personas encuestadas tambi\u00e9n dijeron que los mensajes in-app mejorar\u00edan su experiencia de cliente con una entidad financiera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y todo esto se resume en esto: <strong>Los clientes de servicios financieros prefieren la interacci\u00f3n humana, ya que les proporciona esa experiencia cercana y segura que buscan<\/strong>. Tambi\u00e9n quieren tener la seguridad de que las comunicaciones que reciben de su banco proceden realmente del banco. Y buscan un intercambio interactivo y personalizado. Por lo tanto, incluso en la <a href=\"https:\/\/sinch.com\/es\/blog\/banca-omnicanal\/\">omnicanalidad<\/a>, la llamada a un agente humano debe estar siempre disponible para tus clientes. No basta con digitalizarse. Si quieres generar confianza, reducir el fraude y evitar que los clientes de alto valor se marchen, la voz no es solo algo que est\u00e1 bien tener, es tu piedra angular.<\/p>\n\n\n    <div data-content-type=\"longform\"  class=\"callout text-body-color px-5 py-6 px-md-6 px-lg-7 py-md-7 longform-spacings rounded-lg bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"content-body\"> <p>Cuando se trata de la comunicaci\u00f3n con el cliente en el sector de los servicios financieros, se trata de garantizar que la voz sea una opci\u00f3n de contacto f\u00e1cil y segura en m\u00faltiples puntos de contacto con el cliente.<\/p><\/div>\r\n    <\/div>\r\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n exploraremos tres formas de ponerlo en pr\u00e1ctica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3 formas de utilizar la voz en los servicios bancarios<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si quieres ganarte la confianza de tus clientes y mantenerlos enganchados, la voz es un canal esencial. Una <a href=\"https:\/\/sinch.com\/es\/?post_type=voice&amp;p=61978\">API de voz programable<\/a> te permite integrar servicios de voz en m\u00faltiples puntos de contacto con el cliente y satisfacer la demanda de tus clientes de una comunicaci\u00f3n personal y asistida por voz. Al mismo tiempo, te permitir\u00e1 utilizar seguridad y conformidad normativa a nivel empresarial, para que no tengas que preocuparte por cumplir las normas de seguridad m\u00e1s estrictas.<\/p>\n\n\n\r\n    <aside data-content-type=\"longform\"  class=\"banner-block longform-spacings rounded-lg shadow-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 bg-light\" data-theme=\"light\" aria-labelledby=\"banner-block-block_9243833eec6547d22bb83f736f8f51bb\">\r\n                    <p class=\"text-uppercase section-caption text-body-color\">\r\n                API de voz programable de Sinch            <\/p>\r\n                            <p class=\"h4 text-accent fw-bold\" id=\"banner-block-block_9243833eec6547d22bb83f736f8f51bb\">\r\n                Una comunicaci\u00f3n por voz segura y conforme a las normas            <\/p>\r\n                            <div class=\"mb-0 text-body-color\">\r\n                                    <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Con la API de voz programable de Sinch, una experiencia atractiva para el cliente y la seguridad ya no est\u00e1n re\u00f1idas, y adem\u00e1s obtienes una calidad de llamada superior y opciones de personalizaci\u00f3n.<\/p><\/div>\r\n                            <\/div>\r\n        \r\n        <div class=\"text-start mt-5\"><a href=\"https:\/\/sinch.com\/es\/voice\/voice-calling\/\"  class=\"btn btn-secondary\" >M\u00e1s informaci\u00f3n<\/a><\/div>\r\n    <\/aside>\r\n\r\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed tienes tres casos de uso de lo que ser\u00eda una API de voz en la pr\u00e1ctica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Llamadas personalizadas para mantener informados a los clientes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los clientes esperan que sus instituciones financieras se pongan en contacto con ellos con informaci\u00f3n relevante para ellos. Por ejemplo: Recibir una notificaci\u00f3n cuando vence la renovaci\u00f3n de su pr\u00e9stamo, recibir actualizaciones de pago o saber m\u00e1s sobre sus opciones de inversi\u00f3n actuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Integrando tu sistema CRM con una API de voz programable, es f\u00e1cil mantener a tus clientes al d\u00eda por tel\u00e9fono con la informaci\u00f3n que realmente les interesa. Estas notificaciones de llamadas pueden incluso automatizarse. Adem\u00e1s, tendr\u00e1s acceso a funciones como grabaciones de llamadas, transcripciones o tecnolog\u00eda de voz a texto, que te permitir\u00e1n recopilar datos de los clientes de forma segura para ofrecer un servicio a\u00fan mejor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y lo que es m\u00e1s, con un proveedor fiable de API de voz programable como Sinch, no tienes que preocuparte por la seguridad de las conexiones. La seguridad est\u00e1 integrada en cada parte de nuestra tecnolog\u00eda de voz, y nuestra plataforma protege las interacciones sensibles de los clientes mediante funciones avanzadas como el cifrado, la certificaci\u00f3n ISO 27001, <a href=\"https:\/\/sinch.com\/es\/voice\/stirshaken\/\" target=\"_blank\" rel=\"noreferrer noopener\">los protocolos STIR\/SHAKEN<\/a>, y cumple normas exhaustivas como el RGPD.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Llamadas y chats de v\u00eddeo en la aplicaci\u00f3n, f\u00e1ciles de usar para el cliente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 claro que los consumidores conf\u00edan mucho en las interacciones en directo y en los canales verificados, como la app de su banco. Con <a href=\"https:\/\/sinch.com\/es\/?post_type=voice&amp;p=61978\">la voz programable<\/a>, puedes integrar f\u00e1cilmente llamadas de voz y v\u00eddeo directamente en tu aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Supongamos que un cliente recibe una notificaci\u00f3n push en la aplicaci\u00f3n bancaria sobre una posible actividad fraudulenta. Lo ven enseguida y quieren hablar con tu equipo de asistencia para obtener m\u00e1s informaci\u00f3n. Ahora la funci\u00f3n de llamada dentro de la aplicaci\u00f3n les permite realizar una llamada telef\u00f3nica o una videollamada directamente desde la aplicaci\u00f3n. Tambi\u00e9n podr\u00edas integrarlo en tu p\u00e1gina web si es un punto de contacto popular entre tus clientes. En ambos casos, reduce cualquier fricci\u00f3n al pasar de una aplicaci\u00f3n o p\u00e1gina web a una llamada y, en una situaci\u00f3n cr\u00edtica, tambi\u00e9n ofreces una comunicaci\u00f3n r\u00e1pida y fiable en los canales en los que m\u00e1s conf\u00edan los clientes bancarios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una comunicaci\u00f3n segura, en la que tus clientes pueden confiar<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una API de voz programable tambi\u00e9n a\u00f1ade esa capa de seguridad que buscan tus clientes. Pi\u00e9nsalo as\u00ed: Puedes verificar la identidad de un usuario mediante SMS, llamada telef\u00f3nica o <a href=\"https:\/\/www.youtube.com\/watch?v=Pl6UuJ-kP1w\" target=\"_blank\" rel=\"noreferrer noopener\">llamada flash<\/a> antes de darle acceso a la informaci\u00f3n de su cuenta bancaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, los clientes podr\u00edan configurar su n\u00famero de m\u00f3vil o incluso de tel\u00e9fono fijo para recibir contrase\u00f1as de un solo uso. Entonces podr\u00edas utilizar el software de conversi\u00f3n de texto a voz de la API de voz para realizar una llamada telef\u00f3nica con un c\u00f3digo de voz, incluso en varios idiomas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/09\/SI-Blog-Voice-Financial-Services-Handset-ES-1024x749.png\" alt=\"Pantalla de smartphone que muestra una llamada entrante de San Francisco con una indicaci\u00f3n para verificar tu cuenta\" class=\"wp-image-162570\"\/><figcaption class=\"wp-element-caption\"><em>Utiliza la autenticaci\u00f3n por llamada telef\u00f3nica para una capa adicional de seguridad en la banca.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Esto facilita la detecci\u00f3n y prevenci\u00f3n del fraude por tu parte, al tiempo que aumenta la seguridad de tus clientes.<\/p>\n\n\n    <div data-content-type=\"longform\"  class=\"callout text-body-color px-5 py-6 px-md-6 px-lg-7 py-md-7 longform-spacings rounded-lg bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"content-body\"> <p class=\"mb-0\">Obt\u00e9n m\u00e1s informaci\u00f3n sobre el <a href=\"https:\/\/sinch.com\/es\/apis\/verificacion\/voz\/\">m\u00e9todo de verificaci\u00f3n por llamadas telef\u00f3nicas<\/a> de Sinch, que te permite verificar usuarios de todo el mundo.<\/p><\/div>\r\n    <\/div>\r\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n hay opciones para la comunicaci\u00f3n segura dentro de las aplicaciones. Por ejemplo, las llamadas de voz programables dentro de la aplicaci\u00f3n de Sinch ofrecen <a href=\"https:\/\/sinch.com\/blog\/call-masking-explained\/\">enmascaramiento de llamadas<\/a> para <a href=\"https:\/\/www.revolut.com\/news\/revolut_introduces_in_app_calls_to_help_customers_expose_phone_call_scams\/\" target=\"_blank\" rel=\"noreferrer noopener\">evitar que agentes malintencionados se hagan pasar por tu instituci\u00f3n<\/a>. Las llamadas dentro de la aplicaci\u00f3n tambi\u00e9n est\u00e1n encriptadas de extremo a extremo, lo que dificulta que personas no autorizadas intercepten las llamadas o accedan a datos confidenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, puedes integrar todo esto con los sistemas de autenticaci\u00f3n de tu propia aplicaci\u00f3n, como una autenticaci\u00f3n en dos fases (2FA). Esto garantiza que solo los usuarios autorizados puedan iniciar o recibir llamadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con las llamadas dentro de la aplicaci\u00f3n, los datos de comunicaci\u00f3n permanecen dentro de un entorno seguro, lo que reduce la exposici\u00f3n a vulnerabilidades de terceros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A futuro: La voz no es una alternativa en banca, deber\u00eda ser parte de tus cimientos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Estos son solo algunos ejemplos que muestran c\u00f3mo a\u00f1adir servicios de voz modernos garantiza una comunicaci\u00f3n con el cliente fluida, personalizada y segura en los canales que tus clientes realmente prefieren y en los que conf\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, en funci\u00f3n de tus necesidades, hay muchas posibilidades de combinar la API de voz programable de Sinch con chatbots, bots de voz, agentes de IA, un centro de contacto basado en la nube, servicios de email y SMS, as\u00ed como m\u00e9todos de verificaci\u00f3n, todo desde un proveedor con los mismos altos est\u00e1ndares de seguridad, acuerdos de nivel de servicio s\u00f3lidos y una red de operadores global. As\u00ed puedes expandirte a tu ritmo sin la complejidad de tener que utilizar varias plataformas.<\/p>\n\n\n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-sand\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <svg height=\"40\" class=\"quote-icon quote-icon-color\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/custom-icons\/quotes-right.svg\"><\/svg>\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-29d029c90565b33668f21e309a903849\">\r\n            \u00abElegimos a Sinch por su reputaci\u00f3n. Siempre conoc\u00ed a Sinch como un proveedor de servicios de voz y activos de numeraci\u00f3n respetado. Fue una elecci\u00f3n un poco obvia\u00bb.        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-29d029c90565b33668f21e309a903849\">\r\n                        Gareth Hamer                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">Director de Servicios para operadores en World Mobile<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n\n\n<p class=\"wp-block-paragraph\">Probablemente te est\u00e9s preguntando si una API de voz programable aumentar\u00e1 tus gastos generales o te supondr\u00e1 una inversi\u00f3n alta de tiempo. No te preocupes, no lo har\u00e1. Aunque la API de voz programable de Sinch es f\u00e1cil de usar para los desarrolladores, tambi\u00e9n proporcionamos orientaci\u00f3n pr\u00e1ctica en todo momento: desde la evaluaci\u00f3n t\u00e9cnica inicial hasta la documentaci\u00f3n detallada y los recursos de SDK, pasando por la asistencia t\u00e9cnica integral de nuestro equipo de expertos, siempre que la necesites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQuieres saber m\u00e1s sobre la oferta de voz de Sinch para servicios financieros? Consulta nuestra <a href=\"https:\/\/sinch.com\/es\/?post_type=voice&amp;p=61978\">API de voz programable<\/a>, o <a href=\"https:\/\/sinch.com\/es\/?post_type=voice&amp;p=61978#form\">ponte en contacto directamente con nuestros expertos en voz<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y para conocer mejor nuestras herramientas basadas en la nube para el sector bancario, explora m\u00e1s a fondo <a href=\"https:\/\/sinch.com\/es\/sectores\/servicios-financieros\/\">las soluciones para servicios financieros de Sinch<\/a>.<\/p>\n\n\n\r\n    <aside data-content-type=\"longform\"  class=\"banner-block longform-spacings rounded-lg shadow-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 bg-light\" data-theme=\"dark\" aria-labelledby=\"banner-block-block_2015e2e4005cce5948853e890f9857f5\">\r\n                    <p class=\"text-uppercase section-caption text-body-color\">\r\n                SINCH PARA SERVICIOS FINANCIEROS            <\/p>\r\n                            <p class=\"h4 text-accent fw-bold\" id=\"banner-block-block_2015e2e4005cce5948853e890f9857f5\">\r\n                Soluciones de comunicaci\u00f3n rentables            <\/p>\r\n                            <div class=\"mb-0 text-body-color\">\r\n                                    <div class=\"content-body mb-0 text-body-color\"><p class=\"mb-0\">Evita el fraude, cumple la normativa y ofrece una experiencia de cliente fluida con la plataforma de comunicaciones en la nube de Sinch: desde contrase\u00f1as de un solo uso y notificaciones hasta conversaciones que mantienen a los clientes enganchados, informados, seguros y contentos.<\/p><\/div>\r\n                            <\/div>\r\n        \r\n        <div class=\"text-start mt-5\"><a href=\"https:\/\/sinch.com\/es\/servicios-financieros\/\"  class=\"btn btn-secondary\" >M\u00e1s informaci\u00f3n<\/a><\/div>\r\n    <\/aside>\r\n\r\n","protected":false},"author":37,"featured_media":162562,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"blog_category":[328,330],"class_list":["post-163425","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog_category-insights-es","blog_category-productos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los clientes bancarios quieren seguridad y personalizaci\u00f3n - Sinch<\/title>\n<meta name=\"description\" content=\"Datos de consumidores en 2025 muestran c\u00f3mo las instituciones financieras no aciertan con sus comunicaciones. \u00bfQu\u00e9 les falta? Invertir en soluciones de voz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los clientes bancarios quieren seguridad y personalizaci\u00f3n - Sinch\" \/>\n<meta property=\"og:description\" content=\"Datos de consumidores en 2025 muestran c\u00f3mo las instituciones financieras no aciertan con sus comunicaciones. \u00bfQu\u00e9 les falta? Invertir en soluciones de voz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wearesinch\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T12:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/06\/SI-Blog-Voice-Financial-Services-Link-Preview-1024x536.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WeAreSinch\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/voz-bancos-servicios-financieros\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/voz-bancos-servicios-financieros\\\/\",\"name\":\"Los clientes bancarios quieren seguridad y personalizaci\u00f3n - Sinch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/voz-bancos-servicios-financieros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/voz-bancos-servicios-financieros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/SI-Blog-Voice-Financial-Services-Hero.png\",\"datePublished\":\"2025-06-30T07:46:00+00:00\",\"dateModified\":\"2026-06-30T12:28:05+00:00\",\"description\":\"Datos de consumidores en 2025 muestran c\u00f3mo las instituciones financieras no aciertan con sus comunicaciones. \u00bfQu\u00e9 les falta? Invertir en soluciones de voz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/voz-bancos-servicios-financieros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/voz-bancos-servicios-financieros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/voz-bancos-servicios-financieros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/SI-Blog-Voice-Financial-Services-Hero.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/SI-Blog-Voice-Financial-Services-Hero.png\",\"width\":1400,\"height\":830},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/voz-bancos-servicios-financieros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinch.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/sinch.com\\\/es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Los clientes quieren un servicio seguro y personal y los bancos tienen dificultades para prestarlo: \u00bfPuede ayudar la voz?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/\",\"name\":\"Sinch\",\"description\":\"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinch.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#organization\",\"name\":\"Sinch\",\"url\":\"https:\\\/\\\/sinch.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"width\":800,\"height\":496,\"caption\":\"Sinch\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wearesinch\\\/\",\"https:\\\/\\\/x.com\\\/WeAreSinch\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sinch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZZ2u_B2afTxA0v-xcgfsaw\",\"https:\\\/\\\/www.instagram.com\\\/wearesinch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los clientes bancarios quieren seguridad y personalizaci\u00f3n - Sinch","description":"Datos de consumidores en 2025 muestran c\u00f3mo las instituciones financieras no aciertan con sus comunicaciones. \u00bfQu\u00e9 les falta? Invertir en soluciones de voz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/","og_locale":"es_ES","og_type":"article","og_title":"Los clientes bancarios quieren seguridad y personalizaci\u00f3n - Sinch","og_description":"Datos de consumidores en 2025 muestran c\u00f3mo las instituciones financieras no aciertan con sus comunicaciones. \u00bfQu\u00e9 les falta? Invertir en soluciones de voz.","og_url":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/","og_site_name":"Sinch","article_publisher":"https:\/\/www.facebook.com\/wearesinch\/","article_modified_time":"2026-06-30T12:28:05+00:00","og_image":[{"url":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/06\/SI-Blog-Voice-Financial-Services-Link-Preview-1024x536.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@WeAreSinch","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/","url":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/","name":"Los clientes bancarios quieren seguridad y personalizaci\u00f3n - Sinch","isPartOf":{"@id":"https:\/\/sinch.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/#primaryimage"},"image":{"@id":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/#primaryimage"},"thumbnailUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/06\/SI-Blog-Voice-Financial-Services-Hero.png","datePublished":"2025-06-30T07:46:00+00:00","dateModified":"2026-06-30T12:28:05+00:00","description":"Datos de consumidores en 2025 muestran c\u00f3mo las instituciones financieras no aciertan con sus comunicaciones. \u00bfQu\u00e9 les falta? Invertir en soluciones de voz.","breadcrumb":{"@id":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/#primaryimage","url":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/06\/SI-Blog-Voice-Financial-Services-Hero.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/06\/SI-Blog-Voice-Financial-Services-Hero.png","width":1400,"height":830},{"@type":"BreadcrumbList","@id":"https:\/\/sinch.com\/es\/blog\/voz-bancos-servicios-financieros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinch.com\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/sinch.com\/es\/blog\/"},{"@type":"ListItem","position":3,"name":"Los clientes quieren un servicio seguro y personal y los bancos tienen dificultades para prestarlo: \u00bfPuede ayudar la voz?"}]},{"@type":"WebSite","@id":"https:\/\/sinch.com\/es\/#website","url":"https:\/\/sinch.com\/es\/","name":"Sinch","description":"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch","publisher":{"@id":"https:\/\/sinch.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinch.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sinch.com\/es\/#organization","name":"Sinch","url":"https:\/\/sinch.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sinch.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","width":800,"height":496,"caption":"Sinch"},"image":{"@id":"https:\/\/sinch.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wearesinch\/","https:\/\/x.com\/WeAreSinch","https:\/\/www.linkedin.com\/company\/sinch","https:\/\/www.youtube.com\/channel\/UCZZ2u_B2afTxA0v-xcgfsaw","https:\/\/www.instagram.com\/wearesinch\/"]}]}},"_links":{"self":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/blog\/163425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/users\/37"}],"version-history":[{"count":1,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/blog\/163425\/revisions"}],"predecessor-version":[{"id":195292,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/blog\/163425\/revisions\/195292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/media\/162562"}],"wp:attachment":[{"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/media?parent=163425"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/tags?post=163425"},{"taxonomy":"blog_category","embeddable":true,"href":"https:\/\/sinch.com\/es\/wp-json\/wp\/v2\/blog_category?post=163425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}