{"id":161400,"date":"2025-06-16T09:29:00","date_gmt":"2025-06-16T09:29:00","guid":{"rendered":"https:\/\/sinch.com\/?post_type=scc-chapter&#038;p=161400"},"modified":"2026-02-02T02:19:55","modified_gmt":"2026-02-02T02:19:55","slug":"informiert","status":"publish","type":"scc-chapter","link":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/","title":{"rendered":"Meister der informativen Kundenkommunikation"},"content":{"rendered":"    <section data-content-type=\"hub\"  class=\"section section-hub-py bg-body shadow-divider\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center justify-content-center\">\r\n                <div class=\"col-md-10 justify-content-center\">\r\n\r\n                                            <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                                            <div>\r\n                                    \r\n                                    <h2 class=\"h3 mb-0\">Was Kunden wissen m\u00fcssen, wann sie es wissen m\u00fcssen<\/h2>                                <\/div>\r\n                            \r\n                            <div class=\"content-body text-body-color\"><p class=\"mb-0\">Von Auftragsbest\u00e4tigungen und Versandaktualisierungen bis hin zu Terminerinnerungen und Onboarding-Ma\u00dfnahmen &#8211; Ihre Strategie zur Bereitstellung von Informationen wirkt sich direkt auf das Kundenerlebnis aus. Diese Transaktionsnachrichten halten die Menschen auf dem Laufenden und sorgen daf\u00fcr, dass Ihr Unternehmen reibungslos l\u00e4uft. Die Experten von Sinch erl\u00e4utern, warum Aktualisierungen f\u00fcr Kunden so wichtig sind.<\/p><\/div>                        <\/div>\r\n                    \r\n                                            <div class=\"mt-6 mt-md-7 mt-lg-9\">\r\n                                                            <div>\r\n                                    \n\t<div class=\"custom-video\">\r\n\t\t\t\t\t                    <div class=\"iframe-responsive-container lazy-video rounded-lg overflow-hidden \">\r\n                <a href=\"https:\/\/www.youtube.com\/watch?v=PKvWI9U1rj4\" class=\"lazy-video-link\" data-lazy-video=\"PKvWI9U1rj4\" target=\"_blank\" rel=\"nofollow\" role=\"button\" data-source=\"youtube\" data-language=\"de\" data-thumb=\"https:\/\/img.youtube.com\/vi\/PKvWI9U1rj4\/maxresdefault.jpg\" title=\"Sinch Video\">\r\n                    <div class=\"btn btn-light btn-light-social btn-play btn-play-circle\">\r\n                                                    <svg aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/play.svg\"><\/svg>\r\n                                            <\/div>\r\n                    <img decoding=\"async\"  src=\"https:\/\/img.youtube.com\/vi\/PKvWI9U1rj4\/maxresdefault.jpg\" alt=\"The state of customer communications - Pillar 2: Informed\">\r\n                <\/a>\r\n            <\/div>\r\n                        <script type=\"application\/ld+json\">\r\n            {\n    \"@context\": \"http:\/\/schema.org\",\n    \"@type\": \"VideoObject\",\n    \"@id\": \"https:\/\/www.youtube.com\/watch?v=PKvWI9U1rj4#VideoObject\",\n    \"thumbnailUrl\": \"https:\/\/img.youtube.com\/vi\/PKvWI9U1rj4\/maxresdefault.jpg\",\n    \"embedUrl\": \"https:\/\/www.youtube.com\/embed\/PKvWI9U1rj4\",\n    \"contentUrl\": \"https:\/\/www.youtube.com\/watch?v=PKvWI9U1rj4\",\n    \"name\": \"The state of customer communications - Pillar 2: Informed\",\n    \"description\": \"From order updates to fraud alerts, timely notifications ensure your customers stay updated with the information they need to know. In this video, we explore the second pillar of exceptional customer communication: keeping people informed.\\n\\nCustomer updates are much different than mass marketing messages. They\\u2019re almost always personal and anticipated. But customers can\\u2019t stay informed if messages never reach them. That\\u2019s why deliverability is so important. Listen in as we talk to a Sinch expert about reaching the inbox.\\nGet more in Chapter 3 of The state of customer communications:\\nhttps:\/\/s.sinch.com\/44NJN7w\\n\\n\\ud83c\\udfa5 This is the fourth video in our series covering highlights from the full report. Watch the entire series here: https:\/\/www.youtube.com\/watch?v=_Vjrgu-ybZI&list=PLDWxiKsSIVPJcUp6nNuz958h2qlGl32sP\",\n    \"uploadDate\": \"2025-07-21T22:12:54+00:00\",\n    \"duration\": \"PT3M13S\"\n}        <\/script>\r\n        \t\t\r\n\t\t\t<\/div>\r\n\r\n\t\r\n\n\r\n                                <\/div>\r\n                            \r\n                        <\/div>\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                                    <div class=\"col-md-6 col-lg-7 order-2 order-md-2 ps-md-7 ps-lg-10\">\r\n                        \n\r\n    \r\n    \r\n    \r\n                    <div class=\"position-relative\">\r\n                <div id=\"highcharts_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ\"><\/div>\r\n            <\/div>\r\n        \r\n        <script>\r\n            (function() {\r\n                \/\/ Init chart\r\n                function chartInit_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ() {\r\n                    const chartID = \"highcharts_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ\";\r\n                    const chartContainer = document.getElementById(chartID);\r\n\r\n                    if (!chartContainer) return;\r\n\r\n                    \/\/ Check if chart already existns. Do not init it again\r\n                    if (chartContainer.dataset.initialized === \"true\") {\r\n                        \/\/ console.log(\"Chart already initialized: \" + chartID);\r\n                        return;\r\n                    }\r\n\r\n                    chartContainer.dataset.initialized = \"true\"; \/\/ Mark chart as initialised\r\n\r\n\r\n                    Highcharts.chart(chartID, {\r\n                        credits: {\r\n                            enabled: false,\r\n                        },\r\n                        chart: {\r\n                            type: \"pie\",\r\n                            backgroundColor: \"transparent\"\r\n                            ,\r\n                            \/\/ height: '40%',\r\n                        },\r\n                        title: {\r\n                            text: \"Wie empf\u00e4ngt man am besten Informationsnachrichten von einem Unternehmen?\",\r\n                            align: \"left\",\r\n                            style: {\r\n                                fontWeight: 400,\r\n                                fontSize: \"1rem\",\r\n                                color: \"var(--sinch-accent, #000000)\",\r\n                            },\r\n                        },\r\n                        tooltip: {\r\n                            pointFormat: \"<b>{point.y}%<\/b>\",\r\n                        },\r\n                        accessibility: {\r\n                            enabled: false,\r\n                            point: {\r\n                                valueSuffix: \"%\",\r\n                            },\r\n                        }\r\n                        , colors: ['#1750C2','#1860F0','#2977FF','#5996FF','#85B6FF','#A3C8FF','#AEB7BD',],\r\n                        plotOptions: {\r\n                            pie: {\r\n                                    allowPointSelect: false,\r\n                                    borderWidth: 0,\r\n                                    cursor: 'pointer',\r\n                                    dataLabels: {\r\n                                        enabled: true,\r\n                                        format: `<span style='font-size:1.7em; font-weight:400'>{point.y}%<\/span><br><span style='font-weight:400' class='d-none d-lg-inline'>{point.name}<\/span>`,\r\n                                        distance: 30,\r\n                                        connectorColor: '#c9d1d6',\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                            textOutline: 'none',\r\n                                        },\r\n                                        padding: 10,\r\n                                    },\r\n                                },                        },\r\n                        series: [\r\n                             {\r\n                                animation: {\r\n                                    duration: 2000,\r\n                                }\r\n                                ,\r\n                                            colorByPoint: true,\r\n                                            name: 'Percentage'\r\n                                        ,\r\n\r\n                                data: [\r\n                                    \r\n                                                {\r\n                                                    name: `Nur eine E-Mail`,\r\n                                                    y: 50,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Eine E-Mail und eine Textnachricht`,\r\n                                                    y: 24,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Nur eine Textnachricht`,\r\n                                                    y: 12,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `E-Mail, Text- und Sprachnachricht`,\r\n                                                    y: 10,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Eine Text- und eine Sprachnachricht`,\r\n                                                    y: 2,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Nur eine automatische Sprachnachricht`,\r\n                                                    y: 1,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Sonstiges (bitte eintragen)`,\r\n                                                    y: 1,\r\n                                                },\r\n                                                                            ],\r\n                            }\r\n                                                                                ],\r\n                    });\r\n                }\r\n\r\n                document.addEventListener(\"DOMContentLoaded\", function() {\r\n                    const chartElement = document.getElementById(\"highcharts_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ\");\r\n\r\n                    \/\/ on frontend: Init chart only on scroll (if not initialised)\r\n                    function checkAndInitChart() {\r\n                        if (!chartElement || chartElement.dataset.initialized === \"true\") return;\r\n                        if (isScrolledIntoView(chartElement)) {\r\n                            chartInit_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ();\r\n                        }\r\n                    }\r\n\r\n                    window.addEventListener(\"scroll\", checkAndInitChart);\r\n                    window.addEventListener(\"resize\", chartInit_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ, true);\r\n\r\n                    \/\/ If is visible on load, init\r\n                    checkAndInitChart();\r\n                });\r\n\r\n                \/\/ If we are in Block Editor, reinit chart on each change\r\n                            })();\r\n\r\n            \/\/ window.addEventListener('DOMContentLoaded', function() {\r\n            \/\/     let chartInitialized_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ = false;\r\n            \/\/     const chartID_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ = \"highcharts_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ\";\r\n\r\n            \/\/     chartInit_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ(chartID_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ);\r\n\r\n            \/\/     const chartElement_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ = document.getElementById(chartID_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ);\r\n            \/\/     if (window.isScrolledIntoView(chartElement_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ, false)) {\r\n            \/\/         chartInitialized_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ = true;\r\n            \/\/     }\r\n\r\n            \/\/     addEventListener(\"scroll\", (event) => {\r\n            \/\/         if (!chartInitialized_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ) {\r\n            \/\/             const chartElement_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ = document.getElementById(chartID_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ);\r\n            \/\/             if (window.isScrolledIntoView(chartElement_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ, false)) {\r\n            \/\/                 chartInit_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ(chartID_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ);\r\n\r\n            \/\/                 chartInitialized_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ = true;\r\n            \/\/             }\r\n            \/\/         }\r\n            \/\/     });\r\n            \/\/ });\r\n\r\n            \/\/ window.addEventListener('resize', function(event) {\r\n            \/\/     const chartID_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ = \"highcharts_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ\";\r\n            \/\/     chartInit_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ(chartID_block_YmxvY2tfNmYwNjk3ZGY0ZjkzNDUwMzA4NmZkMjA0NTg1YmEyMGQ);\r\n            \/\/ }, true);\r\n\r\n            \/\/         <\/script>\r\n\r\n\n\r\n                    <\/div>\r\n                \r\n                \r\n                <div class=\"col-md-6 col-lg-5 altblo-content order-1 order-md-1 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <h3 class=\"h4 mb-0\">Wie wollen die Verbraucher Informationsnachrichten erhalten?<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>E-Mail, Telefon oder Textnachrichten? Gibt es einen &#8222;richtigen Weg&#8220;, um Verbrauchern transaktionsbezogene Mitteilungen zukommen zu lassen?<\/p><p>Auf die Frage, was ihrer Meinung nach der beste Kanal f\u00fcr den Erhalt von Informationsnachrichten von Marken ist, w\u00e4hlte die H\u00e4lfte der Verbraucher E-Mail.<\/p><p>W\u00e4hrend 12 % bei Informationsnachrichten &#8222;nur eine SMS&#8220; bevorzugen, m\u00f6chten doppelt so viele (24 %) sowohl eine E-Mail als auch eine Textnachrichten erhalten.  <b>Fast 1 von 10 Verbrauchern gibt an, dass sie eine Nachricht \u00fcber alle drei Kan\u00e4le erhalten m\u00f6chten: Via E-Mail, Textnachricht und Sprachdienste.<\/b><\/p><p class=\"mb-0\">Die Wahrheit ist, dass der richtige digitale Kommunikationskanal von den Vorlieben des Kunden sowie von der Situation und den Informationen abh\u00e4ngt, die Sie liefern m\u00fcssen.<\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                \r\n                                    <div class=\"col-md-6 col-lg-7 order-2 order-md-1 pe-md-7 pe-lg-10 text-center pb-4 pb-lg-0\">\r\n                        <img decoding=\"async\" width=\"600\" height=\"642\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/05\/SDCC-25-Chapter-3-Chart-2_v2-3.png\" class=\"img-fluid\" alt=\"Image for Bereitstellung von Informationen f\u00fcr die Generationen\" sizes=\"(-webkit-min-device-pixel-ratio: 2) and (min-width: 1200px) 648px, (min-resolution: 2dppx) and (min-width: 1200px) 648px, (min-width: 1200px) 1296px, (min-width: 768px) 50vw, 100vw\" \/>                    <\/div>\r\n                \r\n                <div class=\"col-md-6 col-lg-5 altblo-content order-1 order-md-2 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <h3 class=\"h4 mb-0\">Bereitstellung von Informationen f\u00fcr die Generationen<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>Es gibt einige Meinungsverschiedenheiten zwischen den Altersgruppen, wenn es um den Empfang von Informationsnachrichten geht.<\/p><p>W\u00e4hrend die Baby-Boomer am ehesten nur eine E-Mail w\u00fcnschen (54 %), w\u00fcnschten sich die Verbraucher der Generation Z am ehesten das Dreiergespann aus Informationsmitteilungen per E-Mail, SMS und Telefon (13 %).<\/p><p>Wie nicht anders zu erwarten, w\u00fcnschten sich die Verbraucher der Generation Z und der Millennials etwas h\u00e4ufiger als der Durchschnitt, dass ihnen Kundeninformationen ausschlie\u00dflich per SMS zugestellt werden. Allerdings w\u00e4hlten die Boomer eher als die j\u00fcngeren Generationen die Option von E-Mail und SMS.<\/p><p>All dies deutet darauf hin, dass unabh\u00e4ngig vom Alter Ihrer Zielgruppe eine digitale Mehrkanal-Kommunikationsstrategie, die die Verbraucher auf dem Laufenden h\u00e4lt, von gro\u00dfem Nutzen ist.<\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                                    <div class=\"col-md-6 col-lg-7 order-2 order-md-2 ps-md-7 ps-lg-10\">\r\n                        \n\r\n    \r\n    \r\n    \r\n                    <div class=\"position-relative\">\r\n                <div id=\"highcharts_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU\"><\/div>\r\n            <\/div>\r\n        \r\n        <script>\r\n            (function() {\r\n                \/\/ Init chart\r\n                function chartInit_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU() {\r\n                    const chartID = \"highcharts_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU\";\r\n                    const chartContainer = document.getElementById(chartID);\r\n\r\n                    if (!chartContainer) return;\r\n\r\n                    \/\/ Check if chart already existns. Do not init it again\r\n                    if (chartContainer.dataset.initialized === \"true\") {\r\n                        \/\/ console.log(\"Chart already initialized: \" + chartID);\r\n                        return;\r\n                    }\r\n\r\n                    chartContainer.dataset.initialized = \"true\"; \/\/ Mark chart as initialised\r\n\r\n\r\n                    Highcharts.chart(chartID, {\r\n                        credits: {\r\n                            enabled: false,\r\n                        },\r\n                        chart: {\r\n                            type: \"bar\",\r\n                            backgroundColor: \"transparent\"\r\n                            , spacing: [0, 20, 0, 20],\r\n                            \/\/ height: '40%',\r\n                        },\r\n                        title: {\r\n                            text: \"Was frustriert Sie an den Informationsnachrichten, die Sie von Unternehmen erhalten?<br>(Die Befragten haben bis zu drei Optionen ausgew\u00e4hlt.)\",\r\n                            align: \"left\",\r\n                            style: {\r\n                                fontWeight: 400,\r\n                                fontSize: \"1rem\",\r\n                                color: \"var(--sinch-accent, #000000)\",\r\n                            },\r\n                        },\r\n                        tooltip: {\r\n                            pointFormat: \"<b>{point.y}%<\/b>\",\r\n                        },\r\n                        accessibility: {\r\n                            enabled: false,\r\n                            point: {\r\n                                valueSuffix: \"%\",\r\n                            },\r\n                        }\r\n                        , legend: { enabled: false },\r\n                                xAxis: {\r\n                                    type: 'category',\r\n                                    \/\/ height: '50%',\r\n                                    labels: {\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                        },\r\n                                    },\r\n                                },\r\n                                yAxis: {\r\n                                    min: 0,\r\n                                    max: 60,\r\n                                    title: {\r\n                                        text: null,\r\n                                    },\r\n                                    gridLineColor: 'transparent',\r\n                                    opposite: true,\r\n                                    labels: {\r\n                                        formatter: function () {\r\n                                            return this.value + '%';\r\n                                        },\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                        },\r\n                                    },\r\n                                },\r\n                        plotOptions: {\r\n                            \r\n                            bar: {\r\n                                        borderWidth: 0,\r\n                                        borderRadius: '20%',\r\n                                        grouping: false,\r\n                                        events: {\r\n                                            legendItemClick: function () {\r\n                                                return false; \r\n                                            }\r\n                                        },\r\n                                        pointPadding: 0,\r\n                                        \/\/ pointWidth: 20,\r\n                                        groupPadding: 0.1,\r\n                                    },                        },\r\n                        series: [\r\n                             {\r\n                                animation: {\r\n                                    duration: 2000,\r\n                                }\r\n                                ,\r\n                                            color: '#5996FF',\r\n                                            name: 'SDCC-25-Chapter-3-Chart-3',\r\n                                            dataLabels: {\r\n                                                enabled: true,\r\n                                                formatter: function () {\r\n                                                    let returnVal = this.y + '%';\r\n                                                    return returnVal;\r\n                                                },\r\n                                                style:{\r\n                                                    fontWeight: '400',\r\n                                                    color: 'var(--sinch-body-color, #000000)',\r\n                                                    textOutline: 'var(--sinch-subtle-border-color, none)',\r\n                                                    fontSize: 'clamp(0.75rem, calc(0.75rem + 0.4vw), 1.2rem)'\r\n                                                }\r\n                                            }\r\n                                        ,\r\n\r\n                                data: [\r\n                                    \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Meldungen sind zu h\u00e4ufig\/\u00fcberm\u00e4\u00dfig h\u00e4ufig<\/span>`,\r\n                                                    y: 48,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Meldungen sind redundant<\/span>`,\r\n                                                    y: 31,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Keine M\u00f6glichkeit, Fragen zu stellen\/Unterst\u00fctzung zu erhalten<\/span>`,\r\n                                                    y: 28,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">In den Nachrichten fehlen Echtzeitinformationen<\/span>`,\r\n                                                    y: 20,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Nachrichten kommen nicht rechtzeitig an<\/span>`,\r\n                                                    y: 20,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Nachrichten kommen zu einem ung\u00fcnstigen Zeitpunkt<\/span>`,\r\n                                                    y: 19,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Nachrichten sind nicht personalisiert<\/span>`,\r\n                                                    y: 17,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Ich kann meinen bevorzugten Kanal nicht ausw\u00e4hlen<\/span>`,\r\n                                                    y: 9,\r\n                                                },\r\n                                                                            ],\r\n                            }\r\n                                                                                ],\r\n                    });\r\n                }\r\n\r\n                document.addEventListener(\"DOMContentLoaded\", function() {\r\n                    const chartElement = document.getElementById(\"highcharts_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU\");\r\n\r\n                    \/\/ on frontend: Init chart only on scroll (if not initialised)\r\n                    function checkAndInitChart() {\r\n                        if (!chartElement || chartElement.dataset.initialized === \"true\") return;\r\n                        if (isScrolledIntoView(chartElement)) {\r\n                            chartInit_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU();\r\n                        }\r\n                    }\r\n\r\n                    window.addEventListener(\"scroll\", checkAndInitChart);\r\n                    window.addEventListener(\"resize\", chartInit_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU, true);\r\n\r\n                    \/\/ If is visible on load, init\r\n                    checkAndInitChart();\r\n                });\r\n\r\n                \/\/ If we are in Block Editor, reinit chart on each change\r\n                            })();\r\n\r\n            \/\/ window.addEventListener('DOMContentLoaded', function() {\r\n            \/\/     let chartInitialized_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU = false;\r\n            \/\/     const chartID_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU = \"highcharts_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU\";\r\n\r\n            \/\/     chartInit_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU(chartID_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU);\r\n\r\n            \/\/     const chartElement_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU = document.getElementById(chartID_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU);\r\n            \/\/     if (window.isScrolledIntoView(chartElement_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU, false)) {\r\n            \/\/         chartInitialized_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU = true;\r\n            \/\/     }\r\n\r\n            \/\/     addEventListener(\"scroll\", (event) => {\r\n            \/\/         if (!chartInitialized_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU) {\r\n            \/\/             const chartElement_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU = document.getElementById(chartID_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU);\r\n            \/\/             if (window.isScrolledIntoView(chartElement_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU, false)) {\r\n            \/\/                 chartInit_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU(chartID_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU);\r\n\r\n            \/\/                 chartInitialized_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU = true;\r\n            \/\/             }\r\n            \/\/         }\r\n            \/\/     });\r\n            \/\/ });\r\n\r\n            \/\/ window.addEventListener('resize', function(event) {\r\n            \/\/     const chartID_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU = \"highcharts_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU\";\r\n            \/\/     chartInit_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU(chartID_block_YmxvY2tfOTFiYmY4ZGY4NjM0NWE5ZmM1ZjYyODE4NGUwNTMzNTU);\r\n            \/\/ }, true);\r\n\r\n            \/\/         <\/script>\r\n\r\n\n\r\n                    <\/div>\r\n                \r\n                \r\n                <div class=\"col-md-6 col-lg-5 altblo-content order-1 order-md-1 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <h3 class=\"h4 mb-0\">Informationsflut: Problempunkte der Verbraucher<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>Wie bei den Beschwerden \u00fcber Werbebotschaften geben die Verbraucher an, dass sie am meisten \u00fcber zu h\u00e4ufige oder \u00fcberm\u00e4\u00dfige Informationsmitteilungen frustriert sind (48 %).<\/p><p>Ebenso finden mehr als 30 % \u00fcberfl\u00fcssige Informationsmeldungen frustrierend. Beide Ergebnisse legen nahe, dass <b>es so etwas wie eine \u00dcberinformation der Kunden gibt.<\/b><\/p><p>Nicht weit hinter den beiden Spitzenreitern sind fast 28 % der Kunden ver\u00e4rgert, wenn sie als Reaktion auf eine Transaktionsnachricht keine Fragen stellen k\u00f6nnen. Diese zweiseitige Konversation mit dem Support <a href=\"https:\/\/sinch.com\/fr\/blog\/qu-est-ce-que-l-ia-conversationnelle-et-comment-cela-fonctionne\/\" target=\"_blank\" rel=\"noopener noreferrer\">oder einem KI-Chatbot<\/a> ist etwas, das SMS und andere Messaging-Kan\u00e4le erm\u00f6glichen k\u00f6nnen.<\/p><p class=\"mb-0\"><b>Die Aktualit\u00e4t der Informationen ist ebenfalls ein Schl\u00fcsselfaktor<\/b>. Mehr als 19 % sind frustriert, wenn diese Mitteilungen nicht p\u00fcnktlich oder zu einem ung\u00fcnstigen Zeitpunkt eintreffen. Mehr als 20 % finden es ebenfalls nicht gut, wenn diese Nachrichten keine Echtzeitinformationen enthalten.<\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                \r\n                \r\n                <div class=\"col-md-9 altblo-content order-1 order-md-1 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <h3 class=\"h4 mb-0\">Welche Arten von Kundenaktualisierungen sind am wichtigsten?<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>Niemand w\u00fcrde die Bedeutung von Auftragsbest\u00e4tigungen, Versandaktualisierungen und Lieferbenachrichtigungen au\u00dfer Acht lassen. Diese Kommunikation im elektronischen Handel geh\u00f6rt zum Alltag der Verbraucher. Aber wie sieht es mit Kundenaktualisierungen jenseits von Aktivit\u00e4ten wie Online-Shopping, Lebensmittellieferungen und Mitfahrgelegenheiten aus?<\/p><p>Wir baten die Verbraucher, die Wichtigkeit von Informationsbotschaften aus anderen Branchen, einschlie\u00dflich Gesundheitswesen und Finanzdienstleistungen, zu bewerten. Wenn eine Nachricht zeitkritische oder dringende Informationen enth\u00e4lt, wird sie von den Verbrauchern eindeutig als sehr wichtig angesehen. Die Wichtigkeit und Unmittelbarkeit dieser Nachrichten macht Messaging (SMS, MMS, RCS) oft zu einem idealen Kommunikationskanal.<\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n                            <div class=\"mt-6 mt-md-7 mt-lg-9\">\r\n                    \n\r\n    \r\n        <div class=\"row cards gy-6 gy-md-7 gy-lg-9 gx-lg-5 \">\r\n            \r\n                <div class=\"col-12 col-md-6 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/bell-badge.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    57 % der Verbraucher halten <b>Terminbest\u00e4tigungen<\/b> f\u00fcr sehr wichtig.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-6 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/heart-pulse.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    59 % der Verbraucher stufen die <b>Benachrichtigung \u00fcber Testergebnisse<\/b> durch Gesundheitsunternehmen als sehr wichtig ein.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-6 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/privacy.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    74 % der Verbraucher sagen, dass <b>Betrugswarnungen<\/b> eine sehr wichtige Art von Informationsmitteilung sind.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-6 col-lg-3\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/piggy-bank.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    46 % der Verbraucher betrachten <b>Zahlungserinnerungen<\/b> als sehr wichtige Informationsnachrichten.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                    <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                    <\/div>\r\n\n\r\n                <\/div>\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py bg-primary-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center justify-content-center\">\r\n                <div class=\"col-md-10 justify-content-center\">\r\n\r\n                                            <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                                            <div>\r\n                                    \r\n                                    <h3 class=\"h4 mb-0\">Haben Sie die Zustellbarkeit von E-Mails zur Priorit\u00e4t erkl\u00e4rt?<\/h3>                                <\/div>\r\n                            \r\n                            <div class=\"content-body text-body-color\"><p>Mehr als 50 % der Verbraucher wollen Informationsnachrichten per E-Mail erhalten. Das hei\u00dft, Sie m\u00fcssen im Posteingang landen und Spam vermeiden.<\/p><p><a href=\"https:\/\/www.mailgun.com\/resources\/research\/email-customer-experience\/\" target=\"_blank\" rel=\"noopener noreferrer\">Untersuchungen von Sinch Mailgun<\/a> haben ergeben, dass 71 % ihren Spam-Ordner durchsuchen w\u00fcrden, um eine fehlende Transaktions-E-Mail zu finden. Weitere 16 % w\u00fcrden dies tun, wenn die Information wichtig w\u00e4re. Das ist ein Beweis f\u00fcr die Bedeutung der Informationskommunikation und keine Entschuldigung daf\u00fcr, dass man sich nicht um die Zustellbarkeit k\u00fcmmert.<\/p><p>Die Untersuchungen von Mailgun haben auch ergeben, dass <b>die Verbraucher eher negativ auf Nachrichten reagieren, die im Spam landen.<\/b> 33 % gaben an, dass sie es \u00e4rgerlich oder frustrierend finden, wenn dies geschieht, 10 % verlieren das Vertrauen in die Marke, und weitere 10 % w\u00fcrden sich abmelden.  <\/p><p class=\"\">Eine effektive Methode zur Verbesserung Ihrer Chancen, den Posteingang zu erreichen, ist die Trennung von Transaktions- und Werbe-E-Mail-Verkehr auf verschiedenen Subdomains oder Sende-IP-Adressen. <a href=\"https:\/\/www.mailgun.com\/resources\/research\/email-sender-reputation\/\" target=\"_blank\" rel=\"noopener noreferrer\">Der Bericht von Mailgun zum Stand der E-Mail-Zustellbarkeit<\/a> ergab jedoch, dass 50 % der Absender diese Taktik nicht anwenden. Weitere 13 % sind sich nicht sicher, ob sie den E-Mail-Verkehr nach Zustellbarkeit trennen.<\/p><p class=\"\"><\/p><small><\/small><p class=\"\">* E-Mail und das Kundenerlebnis<br>** Stand der Zustellbarkeit von E-Mails 2025<\/p><p class=\"mb-0\"><\/p><\/div>                        <\/div>\r\n                    \r\n                                            <div class=\"mt-6 mt-md-7 mt-lg-9\">\r\n                                                            <div>\r\n                                    \n\r\n    \r\n        <div class=\"row hub-data longform-spacings\">\r\n\r\n                            <div class=\"col-6 col-lg-6 my-2\">\r\n                    <div class=\"hub-data-item h-100 p-4 p-md-5 rounded-lg bg-primary\" data-theme=\"light\">\r\n                        <div class=\"h3 counter\">87%<\/div>\r\n                        <div class=\"content-body text-body-color\">\r\n                            <p class=\"mb-0\">der Verbraucher w\u00fcrden in ihrem Spam-Ordner nach einer fehlenden Transaktions-E-Mail suchen. * <\/p>                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n\r\n                            <div class=\"col-6 col-lg-6 my-2\">\r\n                    <div class=\"hub-data-item h-100 p-4 p-md-5 rounded-lg bg-primary\" data-theme=\"light\">\r\n                        <div class=\"h3 counter\">33%<\/div>\r\n                        <div class=\"content-body text-body-color\">\r\n                            <p class=\"mb-0\">der Verbraucher finden es \u00e4rgerlich oder frustrierend, wenn E-Mails, die sie erwarten, im Spam landen. * <\/p>                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n\r\n                            <div class=\"col-6 col-lg-6 my-2\">\r\n                    <div class=\"hub-data-item h-100 p-4 p-md-5 rounded-lg bg-primary\" data-theme=\"light\">\r\n                        <div class=\"h3 counter\">10%<\/div>\r\n                        <div class=\"content-body text-body-color\">\r\n                            <p class=\"mb-0\">der Verbraucher w\u00fcrden das Vertrauen in die Marke verlieren oder sich abmelden, wenn die Nachrichten weiterhin als Spam verschickt werden. * <\/p>                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n\r\n                            <div class=\"col-6 col-lg-6 my-2\">\r\n                    <div class=\"hub-data-item h-100 p-4 p-md-5 rounded-lg bg-primary\" data-theme=\"light\">\r\n                        <div class=\"h3 counter\">63%<\/div>\r\n                        <div class=\"content-body text-body-color\">\r\n                            <p class=\"mb-0\">der Absender trennen nicht zwischen Transaktions- und Werbe-E-Mail-Verkehr (oder sind sich nicht sicher). ** <\/p>                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n\r\n            \r\n        <\/div>\r\n\r\n\n\r\n                                <\/div>\r\n                            \r\n                        <\/div>\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center justify-content-center\">\r\n                <div class=\"col-md-10 justify-content-center\">\r\n\r\n                    \r\n                                            <div class=\"\">\r\n                                                            <div>\r\n                                    \n    <div data-content-type=\"longform\" class=\"quote hub-quote longform-spacings d-flex flex-column rounded-lg px-5 py-6 px-md-6 py-md-7 p-lg-7 shadow-sm bg-primary\" data-theme=\"light\">\r\n\r\n        <div class=\"quote-logo mb-3\">\r\n                            <svg height=\"40\" class=\"quote-icon quote-icon-color\" aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/custom-icons\/quotes-right.svg\"><\/svg>\r\n                    <\/div>\r\n\r\n        <blockquote class=\"quote-content content-body m-0 text-body-color\" id=\"quote-block-151f299f88401a9951713fbb6936077a\">\r\n            \u201eE-Mail ist ein Kanal, der oft f\u00fcr seinen hohen Return on Investment gefeiert wird. Dieser ROI sinkt jedoch, wenn die Probleme mit der Zustellbarkeit von E-Mails zunehmen. Wenn Sie sich nicht an bew\u00e4hrte Verfahren f\u00fcr die Zustellbarkeit von E-Mails halten, wird Sie das irgendwann einholen. Sobald Sie in die richtige Infrastruktur, Authentifizierung und Marketingtechnologie investiert haben, konzentrieren Sie sich darauf, eine gute Listenhygiene aufrechtzuerhalten und gleichzeitig hochwertige, relevante Inhalte an interaktive Abonnenten zu liefern.\u201c        <\/blockquote>\r\n\r\n                    <div class=\"d-flex gap-3 mt-5\">\r\n                                    <div>\r\n                        <img decoding=\"async\" width=\"72\" height=\"72\" class=\"rounded-lg quote-author\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/05\/SI-Portrait-Kate-Nowrouzi.png\" alt=\"Foto von Kate Nowrouzi\">\r\n                    <\/div>\r\n                                <div class=\"d-flex flex-column align-self-center fs-sm\">\r\n                    <cite class=\"mb-0 fw-bold text-accent fst-normal\" aria-describedby=\"quote-block-151f299f88401a9951713fbb6936077a\">\r\n                        Kate Nowrouzi                    <\/cite>\r\n                                            <span class=\"mb-0 text-body-color\">VP f\u00fcr Zustellbarkeit und Produktstrategie, Sinch<\/span>\r\n                                    <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\n\r\n                                <\/div>\r\n                            \r\n                        <\/div>\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py bg-body shadow-divider\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center justify-content-center\">\r\n                <div class=\"col-md-10 justify-content-center\">\r\n\r\n                                            <div class=\"d-flex flex-column gap-3 gap-lg-4\">\r\n\r\n                                                            <div>\r\n                                                                            <p class=\"text-uppercase section-caption\">Informiert<\/p>\r\n                                    \r\n                                    <h2 class=\"h3 mb-0\">Praxisbeispiele f\u00fcr Mobile Messaging<\/h2>                                <\/div>\r\n                            \r\n                            <div class=\"content-body text-body-color\"><p>Der systemeigene Nachrichteneingang auf Smartphones ist zu einem vertrauten Ort f\u00fcr den Empfang von Informationsnachrichten wie Terminerinnerungen geworden. Wir baten die Umfrageteilnehmer, die Art des Textes auszuw\u00e4hlen, den sie f\u00fcr eine Erinnerung an einen Arzttermin bevorzugten:<\/p><p>1. Eine einfache SMS-Erinnerung<br>2. Eine MMS-Erinnerung mit einem Bild des Standortes<br>3. Eine gebrandete RCS-Nachricht mit Schaltfl\u00e4chen zur Best\u00e4tigung oder Verschiebung des Termins<\/p><p class=\"mb-0\">Die Konkurrenz war stark. W\u00e4hrend <b>41 % der Teilnehmer die RCS-Nachricht w\u00e4hlten<\/b>, bevorzugten 40 % die MMS-Nachricht mit einem Bild. Vielleicht hat das Bild dazu beigetragen, dass ich mich f\u00fcr den Termin entschieden habe. Beachten Sie, dass eine RCS-Nachricht auch Bilder und andere Medien zusammen mit Branding, Aktionsvorschl\u00e4gen und vielem mehr enthalten kann.&nbsp;<\/p><\/div>                        <\/div>\r\n                    \r\n                                            <div class=\"mt-6 mt-md-7 mt-lg-9\">\r\n                                                            <div class=\"text-center\">\r\n                                    <img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/05\/SI-Handsets-SMS-MMS-RCS-2.png\" alt=\"Image for Praxisbeispiele f\u00fcr Mobile Messaging\">\r\n                                <\/div>\r\n                            \r\n                        <\/div>\r\n\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                                    <div class=\"col-md-6 col-lg-7 order-2 order-md-2 ps-md-7 ps-lg-10\">\r\n                        \n\r\n    \r\n    \r\n    \r\n                    <div class=\"position-relative\">\r\n                <div id=\"highcharts_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE\"><\/div>\r\n            <\/div>\r\n        \r\n        <script>\r\n            (function() {\r\n                \/\/ Init chart\r\n                function chartInit_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE() {\r\n                    const chartID = \"highcharts_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE\";\r\n                    const chartContainer = document.getElementById(chartID);\r\n\r\n                    if (!chartContainer) return;\r\n\r\n                    \/\/ Check if chart already existns. Do not init it again\r\n                    if (chartContainer.dataset.initialized === \"true\") {\r\n                        \/\/ console.log(\"Chart already initialized: \" + chartID);\r\n                        return;\r\n                    }\r\n\r\n                    chartContainer.dataset.initialized = \"true\"; \/\/ Mark chart as initialised\r\n\r\n\r\n                    Highcharts.chart(chartID, {\r\n                        credits: {\r\n                            enabled: false,\r\n                        },\r\n                        chart: {\r\n                            type: \"bar\",\r\n                            backgroundColor: \"transparent\"\r\n                            , spacing: [0, 20, 0, 20],\r\n                            \/\/ height: '40%',\r\n                        },\r\n                        title: {\r\n                            text: \"Welche Kan\u00e4le nutzen Einzelh\u00e4ndler f\u00fcr Conversational Commerce?\",\r\n                            align: \"left\",\r\n                            style: {\r\n                                fontWeight: 400,\r\n                                fontSize: \"1rem\",\r\n                                color: \"var(--sinch-accent, #000000)\",\r\n                            },\r\n                        },\r\n                        tooltip: {\r\n                            pointFormat: \"<b>{point.y}%<\/b>\",\r\n                        },\r\n                        accessibility: {\r\n                            enabled: false,\r\n                            point: {\r\n                                valueSuffix: \"%\",\r\n                            },\r\n                        }\r\n                        , legend: { enabled: false },\r\n                                xAxis: {\r\n                                    type: 'category',\r\n                                    \/\/ height: '50%',\r\n                                    labels: {\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                        },\r\n                                    },\r\n                                },\r\n                                yAxis: {\r\n                                    min: 0,\r\n                                    max: 80,\r\n                                    title: {\r\n                                        text: null,\r\n                                    },\r\n                                    gridLineColor: 'transparent',\r\n                                    opposite: true,\r\n                                    labels: {\r\n                                        formatter: function () {\r\n                                            return this.value + '%';\r\n                                        },\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                        },\r\n                                    },\r\n                                },\r\n                        plotOptions: {\r\n                            \r\n                            bar: {\r\n                                        borderWidth: 0,\r\n                                        borderRadius: '20%',\r\n                                        grouping: false,\r\n                                        events: {\r\n                                            legendItemClick: function () {\r\n                                                return false; \r\n                                            }\r\n                                        },\r\n                                        pointPadding: 0,\r\n                                        \/\/ pointWidth: 20,\r\n                                        groupPadding: 0.1,\r\n                                    },                        },\r\n                        series: [\r\n                             {\r\n                                animation: {\r\n                                    duration: 2000,\r\n                                }\r\n                                ,\r\n                                            color: '#FADA5A',\r\n                                            name: 'SDCC-25-Chapter-3-Chart-4',\r\n                                            dataLabels: {\r\n                                                enabled: true,\r\n                                                formatter: function () {\r\n                                                    let returnVal = this.y + '%';\r\n                                                    return returnVal;\r\n                                                },\r\n                                                style:{\r\n                                                    fontWeight: '400',\r\n                                                    color: 'var(--sinch-body-color, #000000)',\r\n                                                    textOutline: 'var(--sinch-subtle-border-color, none)',\r\n                                                    fontSize: 'clamp(0.75rem, calc(0.75rem + 0.4vw), 1.2rem)'\r\n                                                }\r\n                                            }\r\n                                        ,\r\n\r\n                                data: [\r\n                                    \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Textnachrichten-Chatbots<\/span>`,\r\n                                                    y: 59,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Chatbots auf Website oder App<\/span>`,\r\n                                                    y: 56,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Direktnachrichten in sozialen Medien (z. B. Instagram, Tik Tok)<\/span>`,\r\n                                                    y: 45,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Sprachassistenten (z. B. Alexa, Google Assistant)<\/span>`,\r\n                                                    y: 44,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Andere Messaging-Apps (WhatsApp, Messenger, usw.)<\/span>`,\r\n                                                    y: 43,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Keine Nutzung von Conversational Commerce<\/span>`,\r\n                                                    y: 4,\r\n                                                },\r\n                                                                            ],\r\n                            }\r\n                                                                                ],\r\n                    });\r\n                }\r\n\r\n                document.addEventListener(\"DOMContentLoaded\", function() {\r\n                    const chartElement = document.getElementById(\"highcharts_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE\");\r\n\r\n                    \/\/ on frontend: Init chart only on scroll (if not initialised)\r\n                    function checkAndInitChart() {\r\n                        if (!chartElement || chartElement.dataset.initialized === \"true\") return;\r\n                        if (isScrolledIntoView(chartElement)) {\r\n                            chartInit_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE();\r\n                        }\r\n                    }\r\n\r\n                    window.addEventListener(\"scroll\", checkAndInitChart);\r\n                    window.addEventListener(\"resize\", chartInit_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE, true);\r\n\r\n                    \/\/ If is visible on load, init\r\n                    checkAndInitChart();\r\n                });\r\n\r\n                \/\/ If we are in Block Editor, reinit chart on each change\r\n                            })();\r\n\r\n            \/\/ window.addEventListener('DOMContentLoaded', function() {\r\n            \/\/     let chartInitialized_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE = false;\r\n            \/\/     const chartID_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE = \"highcharts_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE\";\r\n\r\n            \/\/     chartInit_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE(chartID_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE);\r\n\r\n            \/\/     const chartElement_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE = document.getElementById(chartID_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE);\r\n            \/\/     if (window.isScrolledIntoView(chartElement_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE, false)) {\r\n            \/\/         chartInitialized_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE = true;\r\n            \/\/     }\r\n\r\n            \/\/     addEventListener(\"scroll\", (event) => {\r\n            \/\/         if (!chartInitialized_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE) {\r\n            \/\/             const chartElement_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE = document.getElementById(chartID_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE);\r\n            \/\/             if (window.isScrolledIntoView(chartElement_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE, false)) {\r\n            \/\/                 chartInit_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE(chartID_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE);\r\n\r\n            \/\/                 chartInitialized_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE = true;\r\n            \/\/             }\r\n            \/\/         }\r\n            \/\/     });\r\n            \/\/ });\r\n\r\n            \/\/ window.addEventListener('resize', function(event) {\r\n            \/\/     const chartID_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE = \"highcharts_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE\";\r\n            \/\/     chartInit_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE(chartID_block_YmxvY2tfM2U4YmFiOTM1NjA3MWNjNWFkYTk0NzY2NjU4MjMxZmE);\r\n            \/\/ }, true);\r\n\r\n            \/\/         <\/script>\r\n\r\n\n\r\n                    <\/div>\r\n                \r\n                \r\n                <div class=\"col-md-6 col-lg-5 altblo-content order-1 order-md-1 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <p class=\"text-uppercase section-caption\">Informiert im Bereich Einzelhandel<\/p><h3 class=\"h4 mb-0\">Conversational Commerce<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>Unsere Untersuchung ergab, dass 28 % der Verbraucher frustriert sind, wenn sie keine Fragen stellen k\u00f6nnen, um weitere Informationen zu erhalten. Die gute Nachricht ist, dass <b>96 % der befragten Einzelh\u00e4ndler in unserer Branchenumfrage angaben, dass sie <\/b><a href=\"https:\/\/sinch.com\/blog\/conversational-commerce\/\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"\">Conversational Commerce<\/a> f\u00fcr die zweiseitige Kundenkommunikation nutzen .<\/p><p>Weit \u00fcber die H\u00e4lfte setzt Chatbots \u00fcber Textnachrichten und\/oder auf ihren Websites ein. Dar\u00fcber hinaus geben mehr als 40 % an, dass sie Social Media Direct Messaging (DMs), OTT-Kan\u00e4le wie WhatsApp oder digitale Sprachassistenten nutzen.<\/p><p class=\"mb-0\">W\u00e4hrend das Ziel von Conversational Commerce darin besteht, Kunden zu binden und den Umsatz zu steigern, kann die Unterst\u00fctzung dieses Erlebnisses durch hilfreiche Informationen die Konversionsrate erh\u00f6hen.<\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                                    <div class=\"col-md-6 col-lg-7 order-2 order-md-1 pe-md-7 pe-lg-10\">\r\n                        \n\r\n    \r\n    \r\n    \r\n                    <div class=\"position-relative\">\r\n                <div id=\"highcharts_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk\"><\/div>\r\n            <\/div>\r\n        \r\n        <script>\r\n            (function() {\r\n                \/\/ Init chart\r\n                function chartInit_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk() {\r\n                    const chartID = \"highcharts_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk\";\r\n                    const chartContainer = document.getElementById(chartID);\r\n\r\n                    if (!chartContainer) return;\r\n\r\n                    \/\/ Check if chart already existns. Do not init it again\r\n                    if (chartContainer.dataset.initialized === \"true\") {\r\n                        \/\/ console.log(\"Chart already initialized: \" + chartID);\r\n                        return;\r\n                    }\r\n\r\n                    chartContainer.dataset.initialized = \"true\"; \/\/ Mark chart as initialised\r\n\r\n\r\n                    Highcharts.chart(chartID, {\r\n                        credits: {\r\n                            enabled: false,\r\n                        },\r\n                        chart: {\r\n                            type: \"pie\",\r\n                            backgroundColor: \"transparent\"\r\n                            ,\r\n                            \/\/ height: '40%',\r\n                        },\r\n                        title: {\r\n                            text: \"W\u00fcrden Sie einem KI-Chatbot zutrauen, Ihnen genaue Antworten zur Sendungsverfolgung oder zu den Lieferzeiten zu geben?\",\r\n                            align: \"left\",\r\n                            style: {\r\n                                fontWeight: 400,\r\n                                fontSize: \"1rem\",\r\n                                color: \"var(--sinch-accent, #000000)\",\r\n                            },\r\n                        },\r\n                        tooltip: {\r\n                            pointFormat: \"<b>{point.y}%<\/b>\",\r\n                        },\r\n                        accessibility: {\r\n                            enabled: false,\r\n                            point: {\r\n                                valueSuffix: \"%\",\r\n                            },\r\n                        }\r\n                        , colors: ['#fada5a','#D3D9DE','#AEB7BD',],\r\n                        plotOptions: {\r\n                            pie: {\r\n                                    allowPointSelect: false,\r\n                                    borderWidth: 0,\r\n                                    cursor: 'pointer',\r\n                                    dataLabels: {\r\n                                        enabled: true,\r\n                                        format: `<span style='font-size:1.7em; font-weight:400'>{point.y}%<\/span><br><span style='font-weight:400' class='d-none d-lg-inline'>{point.name}<\/span>`,\r\n                                        distance: 30,\r\n                                        connectorColor: '#c9d1d6',\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                            textOutline: 'none',\r\n                                        },\r\n                                        padding: 10,\r\n                                    },\r\n                                },                        },\r\n                        series: [\r\n                             {\r\n                                animation: {\r\n                                    duration: 2000,\r\n                                }\r\n                                ,\r\n                                            colorByPoint: true,\r\n                                            name: 'Percentage'\r\n                                        ,\r\n\r\n                                data: [\r\n                                    \r\n                                                {\r\n                                                    name: `Ja`,\r\n                                                    y: 52,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Nein`,\r\n                                                    y: 26,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Unsicher`,\r\n                                                    y: 22,\r\n                                                },\r\n                                                                            ],\r\n                            }\r\n                                                                                ],\r\n                    });\r\n                }\r\n\r\n                document.addEventListener(\"DOMContentLoaded\", function() {\r\n                    const chartElement = document.getElementById(\"highcharts_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk\");\r\n\r\n                    \/\/ on frontend: Init chart only on scroll (if not initialised)\r\n                    function checkAndInitChart() {\r\n                        if (!chartElement || chartElement.dataset.initialized === \"true\") return;\r\n                        if (isScrolledIntoView(chartElement)) {\r\n                            chartInit_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk();\r\n                        }\r\n                    }\r\n\r\n                    window.addEventListener(\"scroll\", checkAndInitChart);\r\n                    window.addEventListener(\"resize\", chartInit_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk, true);\r\n\r\n                    \/\/ If is visible on load, init\r\n                    checkAndInitChart();\r\n                });\r\n\r\n                \/\/ If we are in Block Editor, reinit chart on each change\r\n                            })();\r\n\r\n            \/\/ window.addEventListener('DOMContentLoaded', function() {\r\n            \/\/     let chartInitialized_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk = false;\r\n            \/\/     const chartID_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk = \"highcharts_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk\";\r\n\r\n            \/\/     chartInit_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk(chartID_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk);\r\n\r\n            \/\/     const chartElement_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk = document.getElementById(chartID_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk);\r\n            \/\/     if (window.isScrolledIntoView(chartElement_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk, false)) {\r\n            \/\/         chartInitialized_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk = true;\r\n            \/\/     }\r\n\r\n            \/\/     addEventListener(\"scroll\", (event) => {\r\n            \/\/         if (!chartInitialized_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk) {\r\n            \/\/             const chartElement_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk = document.getElementById(chartID_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk);\r\n            \/\/             if (window.isScrolledIntoView(chartElement_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk, false)) {\r\n            \/\/                 chartInit_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk(chartID_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk);\r\n\r\n            \/\/                 chartInitialized_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk = true;\r\n            \/\/             }\r\n            \/\/         }\r\n            \/\/     });\r\n            \/\/ });\r\n\r\n            \/\/ window.addEventListener('resize', function(event) {\r\n            \/\/     const chartID_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk = \"highcharts_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk\";\r\n            \/\/     chartInit_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk(chartID_block_YmxvY2tfMGU0YjQ1ZmQwYzgzZGU4Y2NkYWU0MjlhZjJlNTcwNzk);\r\n            \/\/ }, true);\r\n\r\n            \/\/         <\/script>\r\n\r\n\n\r\n                    <\/div>\r\n                \r\n                \r\n                <div class=\"col-md-6 col-lg-5 altblo-content order-1 order-md-2 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <p class=\"text-uppercase section-caption\">INFORMIERT IM BEREICH EINZELHANDEL<\/p><h3 class=\"h4 mb-0\">F\u00fchlen sich die Kunden wohl, wenn sie Informationen von k\u00fcnstlicher Intelligenz erhalten?<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>Eine der vielen M\u00f6glichkeiten, wie Einzelh\u00e4ndler von KI profitieren k\u00f6nnen, besteht darin, den Verbrauchern Antworten auf grundlegende Logistikfragen zu geben. Sie fragen sich, wann Sie ein Paket erwarten k\u00f6nnen? Warum nicht einen KI-Chatbot nach einem Update fragen?<\/p><p>Unsere Umfrage ergab, dass <b>mehr als die H\u00e4lfte der Verbraucher (52,3 %) KI f\u00fcr grundlegende Informationen zur Auftragsverfolgung und zum Versand vertrauen w\u00fcrden<\/b>. Etwa ein Viertel w\u00fcrde sich nicht wohl f\u00fchlen, und 22 % sind sich nicht sicher, ob sie der KI vertrauen w\u00fcrden.<\/p><p class=\"\">Eine Aufschl\u00fcsselung nach Generationen zeigt, dass j\u00fcngere Verbraucher eher &#8222;Ja&#8220; dazu sagen, KI f\u00fcr Einzelhandelsinformationen zu vertrauen.<br><\/p><p>\u2022 <b>Generation Z: 67 %<\/b><br>\u2022 <b>Millennials: 63 %<\/b><br>\u2022 Generation X: 54 %<br>\u2022 Babyboomer: 38 %<\/p><p class=\"mb-0\"><br><\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                                    <div class=\"col-md-6 col-lg-7 order-2 order-md-1 pe-md-7 pe-lg-10\">\r\n                        \n\r\n    \r\n    \r\n    \r\n                    <div class=\"position-relative\">\r\n                <div id=\"highcharts_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk\"><\/div>\r\n            <\/div>\r\n        \r\n        <script>\r\n            (function() {\r\n                \/\/ Init chart\r\n                function chartInit_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk() {\r\n                    const chartID = \"highcharts_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk\";\r\n                    const chartContainer = document.getElementById(chartID);\r\n\r\n                    if (!chartContainer) return;\r\n\r\n                    \/\/ Check if chart already existns. Do not init it again\r\n                    if (chartContainer.dataset.initialized === \"true\") {\r\n                        \/\/ console.log(\"Chart already initialized: \" + chartID);\r\n                        return;\r\n                    }\r\n\r\n                    chartContainer.dataset.initialized = \"true\"; \/\/ Mark chart as initialised\r\n\r\n\r\n                    Highcharts.chart(chartID, {\r\n                        credits: {\r\n                            enabled: false,\r\n                        },\r\n                        chart: {\r\n                            type: \"pie\",\r\n                            backgroundColor: \"transparent\"\r\n                            ,\r\n                            \/\/ height: '40%',\r\n                        },\r\n                        title: {\r\n                            text: \"Wie wahrscheinlich ist es, dass Sie einen Arzttermin vergessen oder vers\u00e4umen, wenn Sie nie eine Erinnerungsnachricht erhalten?\",\r\n                            align: \"left\",\r\n                            style: {\r\n                                fontWeight: 400,\r\n                                fontSize: \"1rem\",\r\n                                color: \"var(--sinch-accent, #000000)\",\r\n                            },\r\n                        },\r\n                        tooltip: {\r\n                            pointFormat: \"<b>{point.y}%<\/b>\",\r\n                        },\r\n                        accessibility: {\r\n                            enabled: false,\r\n                            point: {\r\n                                valueSuffix: \"%\",\r\n                            },\r\n                        }\r\n                        , colors: ['#1860F0','#2977FF','#5996FF','#A3C8FF','#C4DCFF',],\r\n                        plotOptions: {\r\n                            pie: {\r\n                                    allowPointSelect: false,\r\n                                    borderWidth: 0,\r\n                                    cursor: 'pointer',\r\n                                    dataLabels: {\r\n                                        enabled: true,\r\n                                        format: `<span style='font-size:1.7em; font-weight:400'>{point.y}%<\/span><br><span style='font-weight:400' class='d-none d-lg-inline'>{point.name}<\/span>`,\r\n                                        distance: 30,\r\n                                        connectorColor: '#c9d1d6',\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                            textOutline: 'none',\r\n                                        },\r\n                                        padding: 10,\r\n                                    },\r\n                                },                        },\r\n                        series: [\r\n                             {\r\n                                animation: {\r\n                                    duration: 2000,\r\n                                }\r\n                                ,\r\n                                            colorByPoint: true,\r\n                                            name: 'Percentage'\r\n                                        ,\r\n\r\n                                data: [\r\n                                    \r\n                                                {\r\n                                                    name: `Sehr hoch`,\r\n                                                    y: 7,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Eher wahrscheinlich`,\r\n                                                    y: 25,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Neutral`,\r\n                                                    y: 21,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Unwahrscheinlich`,\r\n                                                    y: 29,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Sehr unwahrscheinlich`,\r\n                                                    y: 18,\r\n                                                },\r\n                                                                            ],\r\n                            }\r\n                                                                                ],\r\n                    });\r\n                }\r\n\r\n                document.addEventListener(\"DOMContentLoaded\", function() {\r\n                    const chartElement = document.getElementById(\"highcharts_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk\");\r\n\r\n                    \/\/ on frontend: Init chart only on scroll (if not initialised)\r\n                    function checkAndInitChart() {\r\n                        if (!chartElement || chartElement.dataset.initialized === \"true\") return;\r\n                        if (isScrolledIntoView(chartElement)) {\r\n                            chartInit_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk();\r\n                        }\r\n                    }\r\n\r\n                    window.addEventListener(\"scroll\", checkAndInitChart);\r\n                    window.addEventListener(\"resize\", chartInit_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk, true);\r\n\r\n                    \/\/ If is visible on load, init\r\n                    checkAndInitChart();\r\n                });\r\n\r\n                \/\/ If we are in Block Editor, reinit chart on each change\r\n                            })();\r\n\r\n            \/\/ window.addEventListener('DOMContentLoaded', function() {\r\n            \/\/     let chartInitialized_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk = false;\r\n            \/\/     const chartID_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk = \"highcharts_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk\";\r\n\r\n            \/\/     chartInit_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk(chartID_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk);\r\n\r\n            \/\/     const chartElement_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk = document.getElementById(chartID_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk);\r\n            \/\/     if (window.isScrolledIntoView(chartElement_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk, false)) {\r\n            \/\/         chartInitialized_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk = true;\r\n            \/\/     }\r\n\r\n            \/\/     addEventListener(\"scroll\", (event) => {\r\n            \/\/         if (!chartInitialized_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk) {\r\n            \/\/             const chartElement_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk = document.getElementById(chartID_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk);\r\n            \/\/             if (window.isScrolledIntoView(chartElement_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk, false)) {\r\n            \/\/                 chartInit_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk(chartID_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk);\r\n\r\n            \/\/                 chartInitialized_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk = true;\r\n            \/\/             }\r\n            \/\/         }\r\n            \/\/     });\r\n            \/\/ });\r\n\r\n            \/\/ window.addEventListener('resize', function(event) {\r\n            \/\/     const chartID_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk = \"highcharts_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk\";\r\n            \/\/     chartInit_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk(chartID_block_YmxvY2tfZTUzZGUzOTA4MTU4NzQ4NDUzODU3Mjg5NmMzMmYyYjk);\r\n            \/\/ }, true);\r\n\r\n            \/\/         <\/script>\r\n\r\n\n\r\n                    <\/div>\r\n                \r\n                \r\n                <div class=\"col-md-6 col-lg-5 altblo-content order-1 order-md-2 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <p class=\"text-uppercase section-caption\">Information im Bereich Gesundheitsf\u00fcrsorge<\/p><h3 class=\"h4 mb-0\">Der Nutzen von freundlichen Erinnerungen<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>Wie wichtig sind die Terminerinnerungen der Gesundheitsdienstleister?  <\/p><p>Rund 25 % der Verbraucher gaben an, dass sie einen Termin ohne Erinnerungsnachricht mit einer gewissen Wahrscheinlichkeit vers\u00e4umen w\u00fcrden. Weitere 7 % gaben zu, dass sie den Termin mit gro\u00dfer Wahrscheinlichkeit vers\u00e4umen w\u00fcrden. Das sind insgesamt 32 %.<\/p><p><b>Stellen Sie sich vor, fast einer von drei Patienten w\u00fcrde seinen Termin verpassen<\/b>. Das k\u00f6nnte zu einem operativen Albtraum mit Umplanungen und Umstrukturierungen f\u00fchren.  <\/p><p class=\"mb-0\">Diese Informationsmitteilungen, die h\u00e4ufig per SMS \u00fcbermittelt werden, kommen sowohl dem Unternehmen als auch dem Empf\u00e4nger zugute. &#8222;Nichterscheinen&#8220; im Gesundheitswesen kann zu Einnahmeverlusten, Zeit-\/Ressourcenverschwendung, l\u00e4ngeren Wartezeiten und sogar zu negativen Auswirkungen auf die Gesundheit der Patienten f\u00fchren.<\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                                    <div class=\"col-md-6 col-lg-7 order-2 order-md-2 ps-md-7 ps-lg-10\">\r\n                        \n\r\n    \r\n    \r\n    \r\n                    <div class=\"position-relative\">\r\n                <div id=\"highcharts_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc\"><\/div>\r\n            <\/div>\r\n        \r\n        <script>\r\n            (function() {\r\n                \/\/ Init chart\r\n                function chartInit_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc() {\r\n                    const chartID = \"highcharts_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc\";\r\n                    const chartContainer = document.getElementById(chartID);\r\n\r\n                    if (!chartContainer) return;\r\n\r\n                    \/\/ Check if chart already existns. Do not init it again\r\n                    if (chartContainer.dataset.initialized === \"true\") {\r\n                        \/\/ console.log(\"Chart already initialized: \" + chartID);\r\n                        return;\r\n                    }\r\n\r\n                    chartContainer.dataset.initialized = \"true\"; \/\/ Mark chart as initialised\r\n\r\n\r\n                    Highcharts.chart(chartID, {\r\n                        credits: {\r\n                            enabled: false,\r\n                        },\r\n                        chart: {\r\n                            type: \"pie\",\r\n                            backgroundColor: \"transparent\"\r\n                            ,\r\n                            \/\/ height: '40%',\r\n                        },\r\n                        title: {\r\n                            text: \"M\u00f6chten oder erwarten Sie, dass Unternehmen des Gesundheitswesens neben Terminerinnerungen auch andere rechtzeitige Nachrichten \u00fcbermitteln?\",\r\n                            align: \"left\",\r\n                            style: {\r\n                                fontWeight: 400,\r\n                                fontSize: \"1rem\",\r\n                                color: \"var(--sinch-accent, #000000)\",\r\n                            },\r\n                        },\r\n                        tooltip: {\r\n                            pointFormat: \"<b>{point.y}%<\/b>\",\r\n                        },\r\n                        accessibility: {\r\n                            enabled: false,\r\n                            point: {\r\n                                valueSuffix: \"%\",\r\n                            },\r\n                        }\r\n                        , colors: ['#2977FF','#85B6FF','#AEB7BD','',],\r\n                        plotOptions: {\r\n                            pie: {\r\n                                    allowPointSelect: false,\r\n                                    borderWidth: 0,\r\n                                    cursor: 'pointer',\r\n                                    dataLabels: {\r\n                                        enabled: true,\r\n                                        format: `<span style='font-size:1.7em; font-weight:400'>{point.y}%<\/span><br><span style='font-weight:400' class='d-none d-lg-inline'>{point.name}<\/span>`,\r\n                                        distance: 30,\r\n                                        connectorColor: '#c9d1d6',\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                            textOutline: 'none',\r\n                                        },\r\n                                        padding: 10,\r\n                                    },\r\n                                },                        },\r\n                        series: [\r\n                             {\r\n                                animation: {\r\n                                    duration: 2000,\r\n                                }\r\n                                ,\r\n                                            colorByPoint: true,\r\n                                            name: 'Percentage'\r\n                                        ,\r\n\r\n                                data: [\r\n                                    \r\n                                                {\r\n                                                    name: `Ja. Es ist hilfreich`,\r\n                                                    y: 55,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Ich m\u00f6chte die Mahnungen ausw\u00e4hlen`,\r\n                                                    y: 30,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Nein. Es ist aufdringlich`,\r\n                                                    y: 9,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `Nein. Ich kann damit umgehen`,\r\n                                                    y: 6,\r\n                                                },\r\n                                                                            ],\r\n                            }\r\n                                                                                ],\r\n                    });\r\n                }\r\n\r\n                document.addEventListener(\"DOMContentLoaded\", function() {\r\n                    const chartElement = document.getElementById(\"highcharts_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc\");\r\n\r\n                    \/\/ on frontend: Init chart only on scroll (if not initialised)\r\n                    function checkAndInitChart() {\r\n                        if (!chartElement || chartElement.dataset.initialized === \"true\") return;\r\n                        if (isScrolledIntoView(chartElement)) {\r\n                            chartInit_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc();\r\n                        }\r\n                    }\r\n\r\n                    window.addEventListener(\"scroll\", checkAndInitChart);\r\n                    window.addEventListener(\"resize\", chartInit_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc, true);\r\n\r\n                    \/\/ If is visible on load, init\r\n                    checkAndInitChart();\r\n                });\r\n\r\n                \/\/ If we are in Block Editor, reinit chart on each change\r\n                            })();\r\n\r\n            \/\/ window.addEventListener('DOMContentLoaded', function() {\r\n            \/\/     let chartInitialized_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc = false;\r\n            \/\/     const chartID_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc = \"highcharts_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc\";\r\n\r\n            \/\/     chartInit_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc(chartID_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc);\r\n\r\n            \/\/     const chartElement_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc = document.getElementById(chartID_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc);\r\n            \/\/     if (window.isScrolledIntoView(chartElement_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc, false)) {\r\n            \/\/         chartInitialized_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc = true;\r\n            \/\/     }\r\n\r\n            \/\/     addEventListener(\"scroll\", (event) => {\r\n            \/\/         if (!chartInitialized_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc) {\r\n            \/\/             const chartElement_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc = document.getElementById(chartID_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc);\r\n            \/\/             if (window.isScrolledIntoView(chartElement_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc, false)) {\r\n            \/\/                 chartInit_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc(chartID_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc);\r\n\r\n            \/\/                 chartInitialized_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc = true;\r\n            \/\/             }\r\n            \/\/         }\r\n            \/\/     });\r\n            \/\/ });\r\n\r\n            \/\/ window.addEventListener('resize', function(event) {\r\n            \/\/     const chartID_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc = \"highcharts_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc\";\r\n            \/\/     chartInit_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc(chartID_block_YmxvY2tfYmQ0YzFiMTE3N2IxOGQ2NjBhNDk3MzRmZGQwYjg0YTc);\r\n            \/\/ }, true);\r\n\r\n            \/\/         <\/script>\r\n\r\n\n\r\n                    <\/div>\r\n                \r\n                \r\n                <div class=\"col-md-6 col-lg-5 altblo-content order-1 order-md-1 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <p class=\"text-uppercase section-caption\">INFORMATION IM BEREICH GESUNDHEIT<\/p><h3 class=\"h4 mb-0\">Erwartungen f\u00fcr andere rechtzeitige Mahnungen<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>Es gibt noch viele andere Informationsbotschaften, die die Patientenerfahrung im Gesundheitswesen unterst\u00fctzen. Das reicht von Nachuntersuchungen nach dem Arztbesuch \u00fcber die Aktualisierung der Medikamenteneinnahme bis hin zu Erinnerungen an Vorsorgetermine.<\/p><p><b>Fast 55 % der Verbraucher w\u00fcnschen diese Erinnerungen und halten sie f\u00fcr hilfreich<\/b>. Dar\u00fcber hinaus w\u00fcnschen sich fast 30 % die M\u00f6glichkeit, die Art der Informationen zu w\u00e4hlen, die sie erhalten.<\/p><p class=\"mb-0\">Denken Sie daran, dass etwa 15 % der Patienten es vorziehen w\u00fcrden, diese Mitteilungen nicht zu erhalten. Stellen Sie also sicher, dass die Leute sich ein- und austragen k\u00f6nnen.<\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-light-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                                    <div class=\"col-md-6 col-lg-7 order-2 order-md-2 ps-md-7 ps-lg-10\">\r\n                        \n\r\n    \r\n    \r\n    \r\n                    <div class=\"position-relative\">\r\n                <div id=\"highcharts_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU\"><\/div>\r\n            <\/div>\r\n        \r\n        <script>\r\n            (function() {\r\n                \/\/ Init chart\r\n                function chartInit_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU() {\r\n                    const chartID = \"highcharts_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU\";\r\n                    const chartContainer = document.getElementById(chartID);\r\n\r\n                    if (!chartContainer) return;\r\n\r\n                    \/\/ Check if chart already existns. Do not init it again\r\n                    if (chartContainer.dataset.initialized === \"true\") {\r\n                        \/\/ console.log(\"Chart already initialized: \" + chartID);\r\n                        return;\r\n                    }\r\n\r\n                    chartContainer.dataset.initialized = \"true\"; \/\/ Mark chart as initialised\r\n\r\n\r\n                    Highcharts.chart(chartID, {\r\n                        credits: {\r\n                            enabled: false,\r\n                        },\r\n                        chart: {\r\n                            type: \"bar\",\r\n                            backgroundColor: \"transparent\"\r\n                            , spacing: [0, 20, 0, 20],\r\n                            \/\/ height: '40%',\r\n                        },\r\n                        title: {\r\n                            text: \"Wie oft erwarten Sie, dass Sie von Ihrem Finanzinstitut \u00fcber den Stand Ihrer Konten informiert werden?\",\r\n                            align: \"left\",\r\n                            style: {\r\n                                fontWeight: 400,\r\n                                fontSize: \"1rem\",\r\n                                color: \"var(--sinch-accent, #000000)\",\r\n                            },\r\n                        },\r\n                        tooltip: {\r\n                            pointFormat: \"<b>{point.y}%<\/b>\",\r\n                        },\r\n                        accessibility: {\r\n                            enabled: false,\r\n                            point: {\r\n                                valueSuffix: \"%\",\r\n                            },\r\n                        }\r\n                        , legend: { enabled: false },\r\n                                xAxis: {\r\n                                    type: 'category',\r\n                                    \/\/ height: '50%',\r\n                                    labels: {\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                        },\r\n                                    },\r\n                                },\r\n                                yAxis: {\r\n                                    min: 0,\r\n                                    max: 40,\r\n                                    title: {\r\n                                        text: null,\r\n                                    },\r\n                                    gridLineColor: 'transparent',\r\n                                    opposite: true,\r\n                                    labels: {\r\n                                        formatter: function () {\r\n                                            return this.value + '%';\r\n                                        },\r\n                                        style: {\r\n                                            color: 'var(--sinch-body-color, #000000)',\r\n                                        },\r\n                                    },\r\n                                },\r\n                        plotOptions: {\r\n                            \r\n                            bar: {\r\n                                        borderWidth: 0,\r\n                                        borderRadius: '20%',\r\n                                        grouping: false,\r\n                                        events: {\r\n                                            legendItemClick: function () {\r\n                                                return false; \r\n                                            }\r\n                                        },\r\n                                        pointPadding: 0,\r\n                                        \/\/ pointWidth: 20,\r\n                                        groupPadding: 0.1,\r\n                                    },                        },\r\n                        series: [\r\n                             {\r\n                                animation: {\r\n                                    duration: 2000,\r\n                                }\r\n                                ,\r\n                                            color: '#5ba891',\r\n                                            name: '',\r\n                                            dataLabels: {\r\n                                                enabled: true,\r\n                                                formatter: function () {\r\n                                                    let returnVal = this.y + '%';\r\n                                                    return returnVal;\r\n                                                },\r\n                                                style:{\r\n                                                    fontWeight: '400',\r\n                                                    color: 'var(--sinch-body-color, #000000)',\r\n                                                    textOutline: 'var(--sinch-subtle-border-color, none)',\r\n                                                    fontSize: 'clamp(0.75rem, calc(0.75rem + 0.4vw), 1.2rem)'\r\n                                                }\r\n                                            }\r\n                                        ,\r\n\r\n                                data: [\r\n                                    \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">T\u00e4glich<\/span>`,\r\n                                                    y: 9,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">W\u00f6chentlich<\/span>`,\r\n                                                    y: 26,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Monatlich<\/span>`,\r\n                                                    y: 29,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Viertelj\u00e4hrlich<\/span>`,\r\n                                                    y: 7,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Wann immer es eine signifikante Kontobewegung gibt<\/span>`,\r\n                                                    y: 19,\r\n                                                },\r\n                                            \r\n                                                {\r\n                                                    name: `<span class=\"chart-columns-categories-fs\">Nur wenn eine dringende Situation vorliegt<\/span>`,\r\n                                                    y: 10,\r\n                                                },\r\n                                                                            ],\r\n                            }\r\n                                                                                ],\r\n                    });\r\n                }\r\n\r\n                document.addEventListener(\"DOMContentLoaded\", function() {\r\n                    const chartElement = document.getElementById(\"highcharts_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU\");\r\n\r\n                    \/\/ on frontend: Init chart only on scroll (if not initialised)\r\n                    function checkAndInitChart() {\r\n                        if (!chartElement || chartElement.dataset.initialized === \"true\") return;\r\n                        if (isScrolledIntoView(chartElement)) {\r\n                            chartInit_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU();\r\n                        }\r\n                    }\r\n\r\n                    window.addEventListener(\"scroll\", checkAndInitChart);\r\n                    window.addEventListener(\"resize\", chartInit_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU, true);\r\n\r\n                    \/\/ If is visible on load, init\r\n                    checkAndInitChart();\r\n                });\r\n\r\n                \/\/ If we are in Block Editor, reinit chart on each change\r\n                            })();\r\n\r\n            \/\/ window.addEventListener('DOMContentLoaded', function() {\r\n            \/\/     let chartInitialized_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU = false;\r\n            \/\/     const chartID_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU = \"highcharts_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU\";\r\n\r\n            \/\/     chartInit_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU(chartID_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU);\r\n\r\n            \/\/     const chartElement_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU = document.getElementById(chartID_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU);\r\n            \/\/     if (window.isScrolledIntoView(chartElement_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU, false)) {\r\n            \/\/         chartInitialized_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU = true;\r\n            \/\/     }\r\n\r\n            \/\/     addEventListener(\"scroll\", (event) => {\r\n            \/\/         if (!chartInitialized_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU) {\r\n            \/\/             const chartElement_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU = document.getElementById(chartID_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU);\r\n            \/\/             if (window.isScrolledIntoView(chartElement_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU, false)) {\r\n            \/\/                 chartInit_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU(chartID_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU);\r\n\r\n            \/\/                 chartInitialized_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU = true;\r\n            \/\/             }\r\n            \/\/         }\r\n            \/\/     });\r\n            \/\/ });\r\n\r\n            \/\/ window.addEventListener('resize', function(event) {\r\n            \/\/     const chartID_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU = \"highcharts_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU\";\r\n            \/\/     chartInit_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU(chartID_block_YmxvY2tfNGEwNzg5MzkzZWY1ZDQyMTk0YzJkM2EwYzBlYzkzZWU);\r\n            \/\/ }, true);\r\n\r\n            \/\/         <\/script>\r\n\r\n\n\r\n                    <\/div>\r\n                \r\n                \r\n                <div class=\"col-md-6 col-lg-5 altblo-content order-1 order-md-1 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <p class=\"text-uppercase section-caption\">fundierte Finanzdienstleistungen<\/p><h3 class=\"h4 mb-0\">H\u00e4ufigkeit der Kontoaktualisierung<\/h3><div class=\"content-body mb-0 mt-3 mt-lg-4\"><p>Sinch-Untersuchungen haben ergeben, dass 43 % der Verbraucher Aktualisierungen des Kontostands zumindest f\u00fcr einigerma\u00dfen wichtig halten, und 37 % sagen dasselbe \u00fcber Benachrichtigungen \u00fcber ihre Sparziele.<\/p><p>Wir haben auch erfahren, dass es eine h\u00e4ufige Frustration ist, zu h\u00e4ufig Informationsmeldungen zu erhalten. Wie oft wollen diese Kunden also \u00fcber ihre pers\u00f6nlichen Finanzen informiert werden?<\/p><p class=\"mb-0\">Die Ergebnisse deuten darauf hin, dass <b>der optimale Zeitpunkt f\u00fcr diese Informationen zwischen w\u00f6chentlichen und monatlichen Aktualisierungen liegt.<\/b> Mehr als 50 % der Personen w\u00e4hlten eine dieser Kadenzen. Es ist jedoch wahrscheinlich am besten, wenn die Kunden und Auftraggeber die H\u00e4ufigkeit selbst bestimmen k\u00f6nnen.<\/p><\/div>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py bg-body\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"hub-banner px-5 py-7 p-md-9 justify-content-lg-center rounded-lg bg- bg-light-subtle\">\r\n\r\n                <div class=\"row align-items-center justify-content-center py-lg-3 gx-lg-7 gx-md-6 \">\r\n\r\n                                            <div class=\"col-md-6 mt-5 mt-md-0 order-2 order-md-2\">\r\n                            \n\t<div class=\"custom-video\">\r\n\t\t\t\t\t                    <div class=\"iframe-responsive-container lazy-video rounded-lg overflow-hidden \">\r\n                <a href=\"https:\/\/www.youtube.com\/watch?v=GH5JJQJcShI\" class=\"lazy-video-link\" data-lazy-video=\"GH5JJQJcShI\" target=\"_blank\" rel=\"nofollow\" role=\"button\" data-source=\"youtube\" data-language=\"de\" data-thumb=\"https:\/\/img.youtube.com\/vi\/GH5JJQJcShI\/maxresdefault.jpg\" title=\"Sinch Video\">\r\n                    <div class=\"btn btn-light btn-light-social btn-play btn-play-circle\">\r\n                                                    <svg aria-hidden=\"true\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/play.svg\"><\/svg>\r\n                                            <\/div>\r\n                    <img decoding=\"async\"  src=\"https:\/\/img.youtube.com\/vi\/GH5JJQJcShI\/maxresdefault.jpg\" alt=\"How EasyPark Group keeps users informed with RCS\">\r\n                <\/a>\r\n            <\/div>\r\n                        <script type=\"application\/ld+json\">\r\n            {\n    \"@context\": \"http:\/\/schema.org\",\n    \"@type\": \"VideoObject\",\n    \"@id\": \"https:\/\/www.youtube.com\/watch?v=GH5JJQJcShI#VideoObject\",\n    \"thumbnailUrl\": \"https:\/\/img.youtube.com\/vi\/GH5JJQJcShI\/maxresdefault.jpg\",\n    \"embedUrl\": \"https:\/\/www.youtube.com\/embed\/GH5JJQJcShI\",\n    \"contentUrl\": \"https:\/\/www.youtube.com\/watch?v=GH5JJQJcShI\",\n    \"name\": \"How EasyPark Group keeps users informed with RCS\",\n    \"description\": \"Discover how EasyPark Group, a leader in digital parking solutions, leverages Sinch's SMS and RCS (Rich Communication Services) technologies to improve customer experience for millions of monthly users across 20+ countries. \\n\\nIn this video, Alex Keynes, Head of Product for the driver's experience at EasyPark, shares the impact of switching to a single communications partner.\\n\\nBy switching to Sinch for all markets, EasyPark Group simplified their messaging infrastructure without sacrificing a high-quality driver experience.  \\n\\n\\u201cSinch is reliable, their delivery rates are high, and they\\u2019re not taking any shortcuts,\\u201d Alex explained. \\u201cFor us, this is something that we can rely on and that we don't need to spend a lot of time on.\\u201d \\n\\nRead the full case study here: https:\/\/www.sinch.com\/insights\/customer-stories\/how-easypark-group-keeps-20m-monthly-users-informed-sms-and-rcs\/\\n\\n\\n\\n#rcs #customerexperience #verifiedsender\",\n    \"uploadDate\": \"2024-06-13T14:42:30+00:00\",\n    \"duration\": \"PT3M53S\"\n}        <\/script>\r\n        \t\t\r\n\t\t\t<\/div>\r\n\r\n\t\r\n\n\r\n                        <\/div>\r\n                    \r\n                    \r\n                    <div class=\"col-md-6 order-1 order-md-1\">\r\n                                                    <p class=\"text-uppercase section-caption\">Kundenbericht<\/p>\r\n                        \r\n                        <h3 class=\"h4 mb-3 mb-lg-4\">Mehr Wert f\u00fcr den Kunden durch informative Mitteilungen<\/h3>\r\n\r\n                        <p>Die EasyPark-App f\u00fcr Mobiltelefone hilft Menschen auf der ganzen Welt, das Problem der Parkplatzsuche und -bezahlung zu l\u00f6sen.<\/p><p class=\"mb-0\">Sehen Sie sich diesen Kundenbericht von Sinch an, um zu erfahren, wie Informationstexte das gesamte Kundenerlebnis verbessern und wie EasyPark sowohl SMS als auch RCS nutzt, um seinen Nutzern wichtige Kundeninformationen zukommen zu lassen.<\/p>                        \r\n                    <\/div>\r\n                <\/div>\r\n\r\n            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n\r\n\n\n    <section data-content-type=\"hub\"  class=\"section section-hub-py hub-altblock bg-primary-subtle\" data-theme=\"light\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\">\r\n\r\n                \r\n                \r\n                <div class=\"col-md-9 altblo-content order-1 order-md-1 pb-4 pb-lg-0\">\r\n\r\n\r\n                    <h3 class=\"h4 mb-0\">Sind Sie bereit, die Herausforderungen der Kommunikation zu meistern und die Chancen zu nutzen?<\/h3>\r\n\r\n                <\/div>\r\n            <\/div>\r\n\r\n                            <div class=\"mt-6 mt-md-7 mt-lg-9\">\r\n                    \n\r\n    \r\n        <div class=\"row cards gy-6 gy-md-7 gy-lg-9 gx-lg-5 \">\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/api.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Conversation API                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Halten Sie Ihre Kunden informiert, indem Sie ihre Fragen beantworten und ihre Bed\u00fcrfnisse durch zweiseitige, mobile Gespr\u00e4che erf\u00fcllen.<br><br \/>\r\nNutzen Sie eine einfache API, um mit Kunden \u00fcber mehrere Nachrichtenkan\u00e4le in Verbindung zu treten.<br><br \/>\r\nF\u00fcgen Sie einfach neue Kan\u00e4le hinzu, wenn Sie bereit sind.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                            <div class=\"text-start\">\r\n                                                                    <a href=\"https:\/\/sinch.com\/apis\/messaging\/conversation-api\/\" class=\"btn-arrow fs-sm \" title=\"Conversation API\" target=\"_blank\">Jetzt loslegen<\/a>\r\n                                                            <\/div>\r\n                                            <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/email.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                E-Mail einbinden                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Senden Sie rechtzeitig transaktionsbezogene E-Mail-Nachrichten an den Posteingang.<br><br \/>\r\nWir haben Sinch Mailgun f\u00fcr Entwickler entwickelt und bieten branchenf\u00fchrende E-Mail-APIs, die die E-Mail-Integration f\u00fcr Versender jeder Gr\u00f6\u00dfenordnung vereinfachen.<br><br \/>\r\nEntdecken Sie au\u00dferdem eine komplette E-Mail-Zustellbarkeits-Suite mit <a href=\"https:\/\/www.mailgun.com\/products\/optimize\/\" target=\"_blank\">Mailgun Optimize<\/a>.                                 <\/div>\r\n                                                                                <\/div>\r\n                                                                            <div class=\"text-start\">\r\n                                                                    <a href=\"https:\/\/www.mailgun.com\/\" class=\"btn-arrow fs-sm \" title=\"E-Mail einbinden\" target=\"_blank\">Jetzt loslegen<\/a>\r\n                                                            <\/div>\r\n                                            <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n            \r\n                <div class=\"col-12 col-md-4 col-lg-4\">\r\n                                        <div class=\"card h-100 bg-transparent d-flex flex-column card-no-paddings\">\r\n                                                    <div class=\"card-body d-flex flex-column gap-3 gap-md-4 \">\r\n                        <div>\r\n                                                            <div class=\"card-icon mb-4 text-accent\">\r\n                                    <svg aria-hidden=\"true\" width=\"48\" height=\"48\" data-url=\"https:\/\/sinch.com\/wp-content\/plugins\/sinch-core\/assets\/icons\/sinch\/plugs.svg\"><\/svg>\r\n                                <\/div>\r\n                            \r\n                                                        <h3 class=\"card-title text-accent mb-0 fw-bold h6\"\r\n                                                                >\r\n                                Technik und Kommunikation verbinden                            <\/h3>\r\n                                                            <div class=\"card-text fs-sm text-body-color mb-0 mt-2\"\r\n                                                                        >\r\n                                    Sinch l\u00e4sst sich sehr gut mit den besten Marketingtechnologien kombinieren.<br><br \/>\r\nIntegrieren Sie die Kundenkommunikation in Ihre bestehende Software, um dialogorientierte und automatisierte Nachrichten zu versenden.<br><br \/>\r\nVerbinden Sie sich sofort mit Ihrem CRM, ERP oder MarTech mit nativen Integrationen in HubSpot, Salesforce, NetSuite, Zoho, Shopify und mehr.                                <\/div>\r\n                                                                                <\/div>\r\n                                                                            <div class=\"text-start\">\r\n                                                                    <a href=\"https:\/\/sinch.com\/integrations\/\" class=\"btn-arrow fs-sm \" title=\"Technik und Kommunikation verbinden\" target=\"_blank\">Jetzt loslegen<\/a>\r\n                                                            <\/div>\r\n                                            <\/div>\r\n                                <\/div>\r\n\r\n            \r\n                        <\/div>\r\n                    <\/div>\r\n\n\r\n                <\/div>\r\n            \r\n        <\/div>\r\n    <\/section>\r\n\r\n","protected":false},"featured_media":159674,"template":"","meta":{"_acf_changed":true},"class_list":["post-161400","scc-chapter","type-scc-chapter","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informieren Sie Kunden regelm\u00e4\u00dfig mit Transaktionsnachrichten - Sinch<\/title>\n<meta name=\"description\" content=\"Ein wichtiger Teil des Puzzles der digitalen Kommunikation ist es, die Verbraucher zu informieren. Erfahren Sie mehr dar\u00fcber, wie diese Botschaften die Customer Journey beeinflussen.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informieren Sie Kunden regelm\u00e4\u00dfig mit Transaktionsnachrichten - Sinch\" \/>\n<meta property=\"og:description\" content=\"Ein wichtiger Teil des Puzzles der digitalen Kommunikation ist es, die Verbraucher zu informieren. Erfahren Sie mehr dar\u00fcber, wie diese Botschaften die Customer Journey beeinflussen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wearesinch\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T02:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinch.com\/wp-content\/uploads\/2025\/05\/SI-SCC-Hub-Link-Preview-1200x628-1-1024x536.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WeAreSinch\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/der-stand-der-kundenkommunikation\\\/kapitel\\\/informiert\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/de\\\/der-stand-der-kundenkommunikation\\\/kapitel\\\/informiert\\\/\",\"name\":\"Informieren Sie Kunden regelm\u00e4\u00dfig mit Transaktionsnachrichten - Sinch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/der-stand-der-kundenkommunikation\\\/kapitel\\\/informiert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/der-stand-der-kundenkommunikation\\\/kapitel\\\/informiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/SI-SDCC-Chapter-3-Hero-Informed.png\",\"datePublished\":\"2025-06-16T09:29:00+00:00\",\"dateModified\":\"2026-02-02T02:19:55+00:00\",\"description\":\"Ein wichtiger Teil des Puzzles der digitalen Kommunikation ist es, die Verbraucher zu informieren. Erfahren Sie mehr dar\u00fcber, wie diese Botschaften die Customer Journey beeinflussen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/der-stand-der-kundenkommunikation\\\/kapitel\\\/informiert\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinch.com\\\/de\\\/der-stand-der-kundenkommunikation\\\/kapitel\\\/informiert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/der-stand-der-kundenkommunikation\\\/kapitel\\\/informiert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/SI-SDCC-Chapter-3-Hero-Informed.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/SI-SDCC-Chapter-3-Hero-Informed.png\",\"width\":1296,\"height\":1296},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/der-stand-der-kundenkommunikation\\\/kapitel\\\/informiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinch.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meister der informativen Kundenkommunikation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/sinch.com\\\/de\\\/\",\"name\":\"Sinch\",\"description\":\"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinch.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/#organization\",\"name\":\"Sinch\",\"url\":\"https:\\\/\\\/sinch.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"contentUrl\":\"https:\\\/\\\/sinch.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Thumbnail-Logo-Honey.png\",\"width\":800,\"height\":496,\"caption\":\"Sinch\"},\"image\":{\"@id\":\"https:\\\/\\\/sinch.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wearesinch\\\/\",\"https:\\\/\\\/x.com\\\/WeAreSinch\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sinch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZZ2u_B2afTxA0v-xcgfsaw\",\"https:\\\/\\\/www.instagram.com\\\/wearesinch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informieren Sie Kunden regelm\u00e4\u00dfig mit Transaktionsnachrichten - Sinch","description":"Ein wichtiger Teil des Puzzles der digitalen Kommunikation ist es, die Verbraucher zu informieren. Erfahren Sie mehr dar\u00fcber, wie diese Botschaften die Customer Journey beeinflussen.","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Informieren Sie Kunden regelm\u00e4\u00dfig mit Transaktionsnachrichten - Sinch","og_description":"Ein wichtiger Teil des Puzzles der digitalen Kommunikation ist es, die Verbraucher zu informieren. Erfahren Sie mehr dar\u00fcber, wie diese Botschaften die Customer Journey beeinflussen.","og_url":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/","og_site_name":"Sinch","article_publisher":"https:\/\/www.facebook.com\/wearesinch\/","article_modified_time":"2026-02-02T02:19:55+00:00","og_image":[{"url":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/05\/SI-SCC-Hub-Link-Preview-1200x628-1-1024x536.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@WeAreSinch","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/","url":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/","name":"Informieren Sie Kunden regelm\u00e4\u00dfig mit Transaktionsnachrichten - Sinch","isPartOf":{"@id":"https:\/\/sinch.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/#primaryimage"},"image":{"@id":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/#primaryimage"},"thumbnailUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/05\/SI-SDCC-Chapter-3-Hero-Informed.png","datePublished":"2025-06-16T09:29:00+00:00","dateModified":"2026-02-02T02:19:55+00:00","description":"Ein wichtiger Teil des Puzzles der digitalen Kommunikation ist es, die Verbraucher zu informieren. Erfahren Sie mehr dar\u00fcber, wie diese Botschaften die Customer Journey beeinflussen.","breadcrumb":{"@id":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/#primaryimage","url":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/05\/SI-SDCC-Chapter-3-Hero-Informed.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2025\/05\/SI-SDCC-Chapter-3-Hero-Informed.png","width":1296,"height":1296},{"@type":"BreadcrumbList","@id":"https:\/\/sinch.com\/de\/der-stand-der-kundenkommunikation\/kapitel\/informiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinch.com\/de\/"},{"@type":"ListItem","position":2,"name":"Meister der informativen Kundenkommunikation"}]},{"@type":"WebSite","@id":"https:\/\/sinch.com\/de\/#website","url":"https:\/\/sinch.com\/de\/","name":"Sinch","description":"SMS Messaging, Voice, Email, Video &amp; Verification APIs | Sinch","publisher":{"@id":"https:\/\/sinch.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinch.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/sinch.com\/de\/#organization","name":"Sinch","url":"https:\/\/sinch.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/sinch.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","contentUrl":"https:\/\/sinch.com\/wp-content\/uploads\/2024\/09\/Thumbnail-Logo-Honey.png","width":800,"height":496,"caption":"Sinch"},"image":{"@id":"https:\/\/sinch.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wearesinch\/","https:\/\/x.com\/WeAreSinch","https:\/\/www.linkedin.com\/company\/sinch","https:\/\/www.youtube.com\/channel\/UCZZ2u_B2afTxA0v-xcgfsaw","https:\/\/www.instagram.com\/wearesinch\/"]}]}},"_links":{"self":[{"href":"https:\/\/sinch.com\/de\/wp-json\/wp\/v2\/scc-chapter\/161400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinch.com\/de\/wp-json\/wp\/v2\/scc-chapter"}],"about":[{"href":"https:\/\/sinch.com\/de\/wp-json\/wp\/v2\/types\/scc-chapter"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinch.com\/de\/wp-json\/wp\/v2\/media\/159674"}],"wp:attachment":[{"href":"https:\/\/sinch.com\/de\/wp-json\/wp\/v2\/media?parent=161400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}